{"id":8220,"date":"2025-08-22T11:35:16","date_gmt":"2025-08-22T09:35:16","guid":{"rendered":"http:\/\/www.delphin-66.de\/wordpress\/?p=8220"},"modified":"2025-09-02T11:34:55","modified_gmt":"2025-09-02T09:34:55","slug":"sommerurlaub-2025-kopenhagen","status":"publish","type":"post","link":"http:\/\/www.delphin-66.de\/wordpress\/sommerurlaub-2025-kopenhagen\/","title":{"rendered":"Sommerurlaub 2025 &#8211; Kopenhagen!"},"content":{"rendered":"<div id=\"pl-8220\"  class=\"panel-layout\" ><div id=\"pg-8220-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-8220-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-8220-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p style=\"text-align: justify;\"><strong>09.08.2025, Drag\u00f8r - K\u00f8benhavn<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Die vergangenen Tage waren ereignisreich und ich habe mich schwer getan, einen neuen Blog-Beitrag abzuschlie\u00dfen. Aber heute (zur Zeit in S\u00f8nderborg, 22.08.2025, zum Abwettern) finde ich die Zeit.<\/em><\/p>\n<p style=\"text-align: justify;\">Nun sind wir, mehr unverhofft als geplant, unserem Ziel \"K\u00f8benhavn\" sehr nahe gekommen, uns fehlen lediglich 25 Seemeilen!<\/p>\n<p style=\"text-align: justify;\">Um 8 Uhr legen wir in Drag\u00f8r ab und fahren noch schnell in den n\u00f6rdlich gelegenen Teil des Hafens (alter Hafen), um Diesel zu tanken. Dann geht es auch schon weiter Richtung Norden.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_100707.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-8227 size-medium\" src=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_100707-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_100707-300x225.jpg 300w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_100707-800x600.jpg 800w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_100707-400x300.jpg 400w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_100707.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Die Ansteuerung des Stadthafens von Kopenhagen hat sich im Vergleich zu unserem letzten Besuch wesentlich ge\u00e4ndert: Das \"Trekroner Fort\" l\u00e4sst man heute auf der Backbordseite liegen. Vor das \"Trekroner Fort\" wurde ein Steinwall gesch\u00fcttet. Somit liegt die Hafeneinfahrt ca. 1,2 SM n\u00f6rdlicher als zuvor. Als wir diesen Steinwall querab haben, k\u00f6nnen wir sehen, dass die Arbeiten immer noch nicht abgeschlossen sind. Immer noch werden Steine mit Baggern auf dem mittlerweile sichtbaren Wall aufgesch\u00fcttet.<\/p>\n<p style=\"text-align: justify;\">Wenn man dann von S\u00fcden kommend in den Hafen Richtung Norden einschwenkt, liegen zur rechten Seite riesige Kreuzfahrtschiffe an der Pier. Im weiteren Verlauf kommen wir auch an der \"Danebrog\" vorbei, die gegen\u00fcber der \"Kongelige Pavilioner\" <a href=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_104407.jpg\"><img loading=\"lazy\" class=\"alignright wp-image-8228 size-medium\" src=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_104407-300x224.jpg\" alt=\"\" width=\"300\" height=\"224\" srcset=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_104407-300x224.jpg 300w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_104407-800x598.jpg 800w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_104407-402x300.jpg 402w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_104407.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>festgemacht hat. Gegen\u00fcber des \"Kongelige Teater\" biegen wir links dann ab und machen im Wartebereich f\u00fcr die Klappbr\u00fccke zum \"Christianshavn\" l\u00e4ngsseits fest. Gegen viertel nach 11 Uhr fahren wir schlie\u00dflich durch die ge\u00f6ffnete Br\u00fccke in den\u00a0 \"Chrisitanshavn\". Die Br\u00fccke ist eine Fu\u00dfg\u00e4nger- und Radfahrerbr\u00fccke, die extrem frequentiert wird. In den wenigen Minuten, in denen die Br\u00fccke ge\u00f6ffnet wird, sammeln sich Massen an Menschen und potentiellen Zuschauern. Vor gro\u00dfem Publikum laufen wir in den Kanal. Zu beiden Seiten sind, dicht an dicht, Wohnschiffe aber auch Freizeitboote festgemacht. Zum Teil sind die Wohnschiffe sehr sch\u00f6n her- und eingerichtet. Wir machen dann in einer der ganz<a href=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_111539.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-8229 size-medium\" src=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_111539-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_111539-300x225.jpg 300w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_111539-800x600.jpg 800w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_111539-400x300.jpg 400w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_111539.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> wenigen freien Boxen fest. Sie ist, so, wie alle anderen offensichtlich auch, auf rot gestellt. Somit war es vorhersehbar, dass wir hier nicht liegen bleiben k\u00f6nnen. Es kommen dann auch gleich zwei junge deutschsprachige Segler z\u00fcgig auf uns zu, um uns mitzuteilen, dass sie gerade im Begriff w\u00e4ren, ihr Schiff auf eben diesen Platz zu verholen. Ich bitte die Beiden um ein wenig Geduld und frage nach dem Hafenmeister, den die Beiden als Mittdrei\u00dfiger mit blonden, gelockten Haaren beschreiben. Nach meiner ergebnislosen Suche findet Nicole ihn schlie\u00dflich gut versteckt, vor dem von der Promenade zur\u00fcckliegenden Hafenmeisterb\u00fcro, hinter einer Hecke, auf einer Bank. Dort ist er sehr besch\u00e4ftigt (mit seinem Smartphone). Wir gehen zusammen in sein B\u00fcro, um nach einem freien Platz zu suchen. Nach einem intensiven Blick auf seine gro\u00dfe Tafel mit zahlreichen Post-its wird schnell klar, dass es heute keinen Platz f\u00fcr uns gibt, erst ab morgen. Diesen reservieren (Platz Nr. 64) wir ab morgen bis Dienstag.<\/p>\n<p style=\"text-align: justify;\">Somit binden wir unser Schiff wieder los und machen den Platz frei f\u00fcr die anderen beiden Segler. Wir werden indes auf der gegen\u00fcberliegenden Seite f\u00fcndig, wo wir uns l\u00e4ngsseits an die Kaimauer legen. Der Platz ist aber nur bis morgen 17 Uhr frei. Sp\u00e4ter, als der Hafenmeister kommt, bietet er uns an, dass wir auch bis Dienstag bleiben k\u00f6nnen. Das machen wir und bezahlen kontaktlos 1.000 DKK statt 1.050. Vielleicht ein Bonus, weil ich auf D\u00e4nisch verhandelt habe. Wir informieren auch den Hafenmeister von gegen\u00fcber, dass wir den Platz nicht mehr brauchen, aber gerne wieder kommen.<\/p>\n<p style=\"text-align: justify;\">Wenn wir nun schon in Kopenhagen sind, m\u00fcssen wir auch die Zeit nutzen. Daher\u00a0 leihen wir uns E-Bikes \u00fcber den Anbieter \"Lime\" und fahren ins 6 Kilometer entfernt gelegene Einkaufszentrum \"Fields\". Es liegt in einer Planstadt namens \"\u00d8restad\", dass sich seit den 90er Jahren in der Planung bzw. im Bau befindet.<\/p>\n<p style=\"text-align: justify;\">Abends besucht uns unsere mittlere Tochter, die hier am Christianshavn in einer Studenteneinrichtung wohnt und in Kopenhagen studiert. Wir freuen uns riesig, sie zu <a href=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250810_184003.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-8231 size-medium\" src=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250810_184003-300x223.jpg\" alt=\"\" width=\"300\" height=\"223\" srcset=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250810_184003-300x223.jpg 300w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250810_184003-800x595.jpg 800w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250810_184003-403x300.jpg 403w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250810_184003.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>sehen. Von ihr bekommen wir dann auch einen wertvollen Tipp: Genau gegen\u00fcber von uns, ist an einem gro\u00dfen Motorboot eine Legofigur in Form eines Piraten aufgestellt, die mit einer Wasserspritzeinrichtung, in Form einer Pistole, ausgestattet ist. Wie wir von Sophia erfahren, ist diese \u00fcber eine Web-Anwendung ausl\u00f6sbar. Daf\u00fcr muss man einfach nur den QR-Code, der \u00fcber der Figur aufgeh\u00e4ngt ist, scannen. Der<a href=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250811_074718.jpg\"><img loading=\"lazy\" class=\"alignright wp-image-8233 size-medium\" src=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250811_074718-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250811_074718-225x300.jpg 225w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250811_074718-600x800.jpg 600w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250811_074718.jpg 1024w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a> QR-Code ist nat\u00fcrlich auch aus Lego. Das Scannen geht sogar von unserer Plicht aus. Und tats\u00e4chlich, es funktioniert! Was f\u00fcr ein Riesenspa\u00df! Denn durch den Kanal fahren t\u00e4glich \"zig\" Ausflugsschiffe und Leihboote, mit unz\u00e4hligen Touristen. Unsere Trefferquote steigt von Mal zu Mal!<\/p>\n<p style=\"text-align: justify;\">Abends essen wir dann zusammen D\u00f6ner, auf Empfehlung unserer Tochter, bei einem ihrer Lieblingslokale direkt, um die Ecke ihrer Studentenbude. Im Anschluss schauen wir uns die kleine Studentenbude von Sophia und ihrem Freund an, die nur wenige Gehminuten von unserem Liegeplatz im \"Christianshavn\" gelegen ist. Danach gehen wir alle runter in den Aktivit\u00e4tsraum der Einrichtung und spielen Billard.<\/p>\n<p style=\"text-align: justify;\"><strong>10. bis 11.08.2025, K\u00f8benhavn (Hafentage)<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" class=\"size-medium wp-image-8230 alignleft\" src=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_175944-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_175944-300x225.jpg 300w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_175944-800x600.jpg 800w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_175944-400x300.jpg 400w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250809_175944.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Wir erleben eine wirklich unfassbar sch\u00f6ne Zeit in Kopenhagen. Unsere \u00e4lteste Tochter kommt dann sogar noch extra aus Hamburg mit einem Netflixbus angereist, um uns ein paar Tage an Bord zu begleiten. Kopenhagen ist eine wundersch\u00f6ne Stadt, mit Kan\u00e4len, moderner Architektur und bemerkenswerter Infrastruktur f\u00fcr Fahrradfahrer und Fu\u00dfg\u00e4nger. In der Innenstadt dominiert eindeutig der Fahrradverkehr.<\/p>\n<p style=\"text-align: justify;\">Am Montag, sp\u00e4ter Nachmittag, gehen Piet und ich zusammen mit dem Freund von unserer Mittleren ins Gym des Studentenwohnheims, und absolvieren dort ein anst\u00e4ndiges Workout; ein riesigerer Spa\u00df! Zum Abend hin gehen wir alle zusammen zum \"Food Marked\"\u00a0 (\"Broens Street Food\") mit toller Lage an der \"Butterfly 3-Way Bridge\".<\/p>\n<p style=\"text-align: justify;\">Heute m\u00fcssen wir uns dann von unserer Mittleren verabschieden. Wir m\u00fcssen morgen weiter und unsere Mittlere fliegt mit ihrem Freund am Donnerstag nach Florida.<\/p>\n<p style=\"text-align: justify;\"><strong>12.08.2025, K\u00f8benhavn - Gilleleje<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250812_202629.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-8234 size-medium\" src=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250812_202629-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250812_202629-300x225.jpg 300w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250812_202629-800x600.jpg 800w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250812_202629-400x300.jpg 400w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250812_202629.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Heute hei\u00dft es fr\u00fch aufstehen. Unsere \u00c4lteste und unser J\u00fcngster, Piet, d\u00fcrfen weiterschlafen. M\u00f6glichst leise legen wir um viertel nach sieben ab und verholen uns vor die Br\u00fccke, die um 07:25 (!) f\u00fcr 5 Minuten \u00f6ffnet. Mit uns warten noch zwei weitere Segler. Mit etwas Wehmut verlassen wir diesen sch\u00f6nen Ort und motoren aus dem Hafen, vorbei an der Meerjungfrau und der \"Danebrog\". Weiter geht es Richtung Norden. Wir lassen schlie\u00dflich das \"Kronborg Slot\" in Helsing\u00f8r an unserer Backbordseite liegen. Bei wirklich guten Bedingungen erreichen wir nach ca. 6 Stunden Gilleleje, wo wir im \u00f6stlichen Hafen l\u00e4ngsseits fest machen. Gilleleje ist auch wirklich sch\u00f6n. Der Hafen hat sch\u00f6ne Gastronomie und einen \"Rema\". Abends grillen wir zusammen an einem der Sitzgarnituren, direkt an unserem Liegeplatz. Zu dieser Zeit kommt noch ein Paar aus Bremerhaven, die bei uns l\u00e4ngsseits gehen. Dieses Detail ist nicht unwichtig, wie sich sp\u00e4ter zeigt.<\/p>\n<p style=\"text-align: justify;\"><strong>13.08.2025, Gilleleje - Ankern vor R\u00f8rvig<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250813_211933.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-8242 size-medium\" src=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250813_211933-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250813_211933-225x300.jpg 225w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250813_211933-600x800.jpg 600w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250813_211933.jpg 1024w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a>Gegen halb 9 legen wir dann ab und nehmen Kurs auf R\u00f8rvig, wo wir uns vor Anker legen wollen. Unsere Liegeplatznachbarn machen uns beil\u00e4ufig darauf aufmerksam, dass es bei der Weiterfahrt Richtung Westen, was f\u00fcr uns f\u00fcr \u00fcbermorgen vorgesehen ist, milit\u00e4rische Sperrgebiete zu beachten gibt. Das wussten wir tats\u00e4chlich nicht! Sie empfehlen uns au\u00dferdem die App \"SejlSikkert\", wo diese Sperrgebiete dargestellt sind und auch Informationen zur Verf\u00fcgung gestellt werden, wann diese Sperrgebiete aktiv sind. Wir sind sehr dankbar f\u00fcr diese Information. Erst sp\u00e4ter, wenn wir unsere gro\u00dfe Tour von R\u00f8rvig nach Ballen auf Sams\u00f8 machen, werden wir dankbar f\u00fcr diese Information sein. Ich werde beim n\u00e4chsten Beitrag davon berichten!<\/p>\n<p style=\"text-align: justify;\">Nach 23 SM erreichen wir schlie\u00dflich die kleine Ankerbucht bei R\u00f8rvig. Heute ist Badetag, den ganzen Tag Sonne und angenehme Temperaturen, wirklich traumhafte Bedingungen. Abends setzen wir dann zu dritt im Schlauchboot zum knapp 1 SM entfernt gelegenen Hafen \u00fcber. Unser J\u00fcngster mit dem SUP, da unser Schlauchboot zu klein f\u00fcr vier Personen ist. Hier setzen wir uns in den Au\u00dfenbereich des \"Lodsoldermandsg\u00e5rden\" und bestellen Pizza., sehr lecker! Im Anschluss gibt es nat\u00fcrlich noch ein Eis im \"Vaffel Huset\" gegen\u00fcber. Dort stellen wir uns sogar eine halbe Stunde lang an, so gut soll das Eis sein! Ob sich der Einsatz lohnt, ist Ansichtssache!<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250813_211042.jpg\"><img loading=\"lazy\" class=\"alignright wp-image-8241 size-medium\" src=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250813_211042-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250813_211042-300x225.jpg 300w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250813_211042-800x600.jpg 800w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250813_211042-400x300.jpg 400w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/20250813_211042.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Dann geht es zur\u00fcck zum Schiff. In der D\u00e4mmerung kommen wir u.a. auch an der gro\u00dfen Luxusyacht mit dem Namen \"Familybilt\" unter englischer Flagge vorbei. Da wir recht nahe am Heck des beeindruckend gro\u00dfen Schiffes vorbei fahren, kommen zwei Crew-Mitglieder auf die Heckplattform, und schauen etwas grimmig zu uns r\u00fcber. Wir gr\u00fc\u00dfen freundlich, was von den Beiden verhalten erwidert wird.<\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-8220-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-8220-0-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>&nbsp;<\/p>\n<p>\r\n\t\t<div id=\"wpgpxmaps_8220_553634\" class=\"wpgpxmaps\">\r\n\t\t\t<div id=\"map_8220_553634_cont\" style=\"width:100%; height:450px;position:relative\" >\r\n\t\t\t\t<div id=\"map_8220_553634\" style=\"width:100%; height:450px\"><\/div>\r\n\t\t\t\t<div id=\"wpgpxmaps_8220_553634_osm_footer\" class=\"wpgpxmaps_osm_footer\" style=\"display:none;\"><span> &copy; <a href=\"http:\/\/www.openstreetmap.org\/copyright\">OpenStreetMap<\/a> contributors<\/span><\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<canvas id=\"myChart_8220_553634\" class=\"plot\" style=\"width:100%; height:200px\"><\/canvas>\r\n\t\t\t<div id=\"ngimages_8220_553634\" class=\"ngimages\" style=\"display:none\"><\/div>\r\n\t\t\t<div id=\"report_8220_553634\" class=\"report\"><\/div>\r\n\t\t<\/div>\r\n\t\t\r\n\t\t<script type=\"text\/javascript\">\r\n\r\n\t\t\tjQuery(document).ready(function() {\r\n\r\n\t\t\t\tjQuery( \"#wpgpxmaps_8220_553634\" ).wpgpxmaps( {\r\n\t\t\t\t\ttargetId           : \"8220_553634\",\r\n\t\t\t\t\tmapType            : \"HYBRID\",\r\n\t\t\t\t\tmapData            : [[55.5911270,12.6797600],[55.5911270,12.6797490],[55.5911270,12.6797510],[55.5911270,12.6797510],[55.5911270,12.6797500],[55.5911270,12.6797490],[55.5911270,12.6797480],[55.5911270,12.6797480],[55.5911270,12.6797480],[55.5911270,12.6797480],[55.5911270,12.6797470],[55.5911270,12.6797470],[55.5911270,12.6797450],[55.5911270,12.6797450],[55.5911270,12.6797450],[55.5911270,12.6797450],[55.5911270,12.6797450],[55.5911270,12.6797450],[55.5911270,12.6797450],[55.5911270,12.6797440],[55.5911270,12.6797450],[55.5911270,12.6797450],[55.5911270,12.6797450],[55.5911270,12.6797450],[55.5911270,12.6797440],[55.5911240,12.6797440],[55.5911240,12.6797440],[55.5911240,12.6797440],[55.5911240,12.6797440],[55.5911220,12.6797440],[55.5911220,12.6797450],[55.5911350,12.6797680],[55.5911600,12.6797940],[55.5911600,12.6797950],[55.5911630,12.6797970],[55.5911680,12.6798040],[55.5912340,12.6798500],[55.5912490,12.6798510],[55.5912540,12.6798480],[55.5912540,12.6798400],[55.5912570,12.6798420],[55.5912620,12.6798430],[55.5912670,12.6798450],[55.5912720,12.6798430],[55.5912750,12.6798410],[55.5912770,12.6798390],[55.5912820,12.6798350],[55.5912950,12.6798240],[55.5912970,12.6798240],[55.5913000,12.6798230],[55.5912970,12.6798320],[55.5912950,12.6798460],[55.5912900,12.6798670],[55.5912720,12.6798950],[55.5912520,12.6799300],[55.5912160,12.6799920],[55.5911750,12.6800730],[55.5911300,12.6801660],[55.5911020,12.6802360],[55.5910760,12.6802890],[55.5910480,12.6803370],[55.5910070,12.6803990],[55.5909240,12.6804700],[55.5908350,12.6804530],[55.5907940,12.6804100],[55.5907380,12.6803410],[55.5906670,12.6802470],[55.5905880,12.6801460],[55.5905090,12.6800430],[55.5904280,12.6799390],[55.5903390,12.6798590],[55.5902570,12.6798250],[55.5901550,12.6798170],[55.5900740,12.6798390],[55.5899950,12.6798800],[55.5899190,12.6799390],[55.5898350,12.6800460],[55.5897590,12.6801840],[55.5897280,12.6802810],[55.5897030,12.6804600],[55.5897000,12.6806450],[55.5897130,12.6807920],[55.5897410,12.6809310],[55.5897840,12.6810580],[55.5898430,12.6812100],[55.5898860,12.6813380],[55.5899060,12.6814030],[55.5899260,12.6814690],[55.5899700,12.6816010],[55.5900130,12.6817340],[55.5900740,12.6818930],[55.5901020,12.6819550],[55.5901730,12.6821000],[55.5902520,12.6822260],[55.5903110,12.6823340],[55.5903210,12.6823650],[55.5903410,12.6824300],[55.5903610,12.6824980],[55.5904020,12.6826320],[55.5904220,12.6826990],[55.5904560,12.6827980],[55.5904860,12.6828990],[55.5905090,12.6829660],[55.5905420,12.6830670],[55.5905850,12.6832000],[55.5906310,12.6833330],[55.5906640,12.6834320],[55.5906970,12.6835320],[55.5907430,12.6836660],[55.5907790,12.6837660],[55.5908190,12.6838610],[55.5908320,12.6838920],[55.5908900,12.6840190],[55.5909490,12.6841440],[55.5909950,12.6842400],[55.5910410,12.6843410],[55.5910890,12.6844420],[55.5911220,12.6845120],[55.5911730,12.6846140],[55.5912210,12.6847080],[55.5912970,12.6848210],[55.5913560,12.6849050],[55.5914250,12.6849820],[55.5914650,12.6850320],[55.5915090,12.6850850],[55.5915470,12.6851460],[55.5916100,12.6852870],[55.5916610,12.6853880],[55.5917400,12.6855070],[55.5918010,12.6855910],[55.5918650,12.6856700],[55.5919540,12.6857580],[55.5920220,12.6858140],[55.5920940,12.6858730],[55.5921650,12.6859310],[55.5922560,12.6860150],[55.5923250,12.6860770],[55.5924220,12.6861410],[55.5924930,12.6861890],[55.5925670,12.6862270],[55.5926430,12.6862650],[55.5927400,12.6862980],[55.5928130,12.6863220],[55.5929130,12.6863480],[55.5930090,12.6863740],[55.5931080,12.6863920],[55.5931850,12.6864020],[55.5932330,12.6864080],[55.5932810,12.6864170],[55.5933580,12.6864340],[55.5934060,12.6864430],[55.5934570,12.6864510],[55.5935310,12.6864600],[55.5936070,12.6864680],[55.5937090,12.6864740],[55.5937820,12.6864770],[55.5938590,12.6864760],[55.5939350,12.6864720],[55.5940090,12.6864680],[55.5940600,12.6864660],[55.5941610,12.6864630],[55.5942350,12.6864570],[55.5942610,12.6864530],[55.5943340,12.6864420],[55.5943600,12.6864350],[55.5944110,12.6864210],[55.5944840,12.6863970],[55.5945560,12.6863650],[55.5946220,12.6863070],[55.5947010,12.6862030],[55.5947690,12.6860870],[55.5948120,12.6859870],[55.5948480,12.6858770],[55.5948740,12.6857610],[55.5948940,12.6855970],[55.5949020,12.6854730],[55.5948990,12.6853060],[55.5948810,12.6851450],[55.5948610,12.6850250],[55.5948380,12.6849080],[55.5948230,12.6848320],[55.5948020,12.6847580],[55.5947720,12.6846480],[55.5947540,12.6845710],[55.5947310,12.6844960],[55.5946880,12.6843410],[55.5946450,12.6841820],[55.5946220,12.6841030],[55.5945760,12.6839450],[55.5945300,12.6837840],[55.5944820,12.6836250],[55.5944490,12.6835040],[55.5944000,12.6833420],[55.5943620,12.6832220],[55.5943240,12.6831040],[55.5942710,12.6829510],[55.5942400,12.6828750],[55.5941970,12.6827670],[55.5941360,12.6826270],[55.5940850,12.6824770],[55.5940670,12.6823040],[55.5940650,12.6821270],[55.5940670,12.6819560],[55.5940670,12.6818370],[55.5940650,12.6816910],[55.5940600,12.6815540],[55.5940490,12.6814590],[55.5940320,12.6813110],[55.5940220,12.6812250],[55.5940090,12.6811420],[55.5939960,12.6810610],[55.5939810,12.6809560],[55.5939680,12.6808770],[55.5939580,12.6808260],[55.5939500,12.6807760],[55.5939350,12.6807040],[55.5939200,12.6806400],[55.5938990,12.6805580],[55.5938740,12.6804700],[55.5938540,12.6803820],[55.5938360,12.6803120],[55.5938230,12.6802750],[55.5938100,12.6802280],[55.5938030,12.6802010],[55.5937930,12.6801750],[55.5937880,12.6801600],[55.5937820,12.6801430],[55.5937800,12.6801350],[55.5937750,12.6801110],[55.5937620,12.6800790],[55.5937600,12.6800760],[55.5937540,12.6800650],[55.5937540,12.6800620],[55.5937540,12.6800610],[55.5937520,12.6800580],[55.5937390,12.6800350],[55.5937370,12.6800290],[55.5936810,12.6799310],[55.5936760,12.6799190],[55.5936370,12.6798390],[55.5936350,12.6798290],[55.5936170,12.6797860],[55.5935970,12.6797290],[55.5935970,12.6797230],[55.5935970,12.6797220],[55.5935970,12.6797210],[55.5935970,12.6797160],[55.5935970,12.6797150],[55.5935970,12.6797140],[55.5935970,12.6797140],[55.5935970,12.6797140],[55.5935970,12.6797140],[55.5935970,12.6797140],[55.5935970,12.6797140],[55.5935970,12.6797140],[55.5935970,12.6797140],[55.5935970,12.6797140],[55.5935990,12.6797140],[55.5935990,12.6797140],[55.5935990,12.6797140],[55.5935990,12.6797140],[55.5935990,12.6797150],[55.5935990,12.6797150],[55.5935970,12.6797140],[55.5935940,12.6797070],[55.5935940,12.6797040],[55.5935940,12.6797040],[55.5935970,12.6797000],[55.5935970,12.6796990],[55.5935990,12.6797000],[55.5935990,12.6797000],[55.5936020,12.6797060],[55.5936040,12.6797070],[55.5936040,12.6797080],[55.5936040,12.6797080],[55.5936070,12.6797060],[55.5936070,12.6797050],[55.5936070,12.6797050],[55.5936070,12.6797050],[55.5936070,12.6797040],[55.5936070,12.6797040],[55.5936070,12.6797040],[55.5936070,12.6797040],[55.5936070,12.6797040],[55.5936070,12.6797030],[55.5936040,12.6797030],[55.5936040,12.6797030],[55.5936040,12.6797020],[55.5936040,12.6797020],[55.5936040,12.6797020],[55.5936040,12.6797020],[55.5936040,12.6797000],[55.5936040,12.6797000],[55.5936070,12.6797090],[55.5936070,12.6797090],[55.5936070,12.6797110],[55.5936070,12.6797120],[55.5936070,12.6797110],[55.5936040,12.6797110],[55.5936040,12.6797110],[55.5936040,12.6797080],[55.5936020,12.6797070],[55.5936020,12.6797060],[55.5936020,12.6797050],[55.5935940,12.6796970],[55.5935940,12.6796990],[55.5935920,12.6797000],[55.5935920,12.6796990],[55.5935920,12.6796980],[55.5935920,12.6796970],[55.5935920,12.6796960],[55.5935920,12.6796960],[55.5935920,12.6796950],[55.5935920,12.6796950],[55.5935920,12.6796950],[55.5935920,12.6796950],[55.5935920,12.6796950],[55.5935920,12.6796950],[55.5935920,12.6796950],[55.5935920,12.6796950],[55.5935920,12.6796950],[55.5935940,12.6796950],[55.5935940,12.6796950],[55.5935940,12.6796950],[55.5935940,12.6796950],[55.5935940,12.6796950],[55.5935940,12.6796940],[55.5935940,12.6796950],[55.5935940,12.6796950],[55.5935920,12.6796950],[55.5935920,12.6796950],[55.5935920,12.6796950],[55.5935920,12.6796950],[55.5935920,12.6796940],[55.5935920,12.6796930],[55.5935920,12.6796930],[55.5935920,12.6796930],[55.5935920,12.6796940],[55.5935920,12.6796940],[55.5935920,12.6796940],[55.5935920,12.6796930],[55.5935920,12.6796930],[55.5935920,12.6796940],[55.5935920,12.6796950],[55.5935920,12.6796950],[55.5935920,12.6796950],[55.5935940,12.6796950],[55.5935940,12.6796940],[55.5935940,12.6796940],[55.5935940,12.6796930],[55.5935940,12.6796930],[55.5935940,12.6796920],[55.5935940,12.6796920],[55.5935940,12.6796920],[55.5935940,12.6796930],[55.5935940,12.6796940],[55.5935940,12.6796940],[55.5935940,12.6796940],[55.5935940,12.6796940],[55.5935940,12.6796930],[55.5935940,12.6796930],[55.5935940,12.6796930],[55.5935940,12.6796930],[55.5935940,12.6796920],[55.5935940,12.6796920],[55.5935940,12.6796920],[55.5935940,12.6796920],[55.5935940,12.6796920],[55.5935940,12.6796920],[55.5935940,12.6796920],[55.5935940,12.6796920],[55.5935940,12.6796920],[55.5935940,12.6796920],[55.5935940,12.6796900],[55.5935940,12.6796900],[55.5935940,12.6796900],[55.5935940,12.6796900],[55.5935940,12.6796900],[55.5935940,12.6796900],[55.5935940,12.6796900],[55.5935940,12.6796900],[55.5935940,12.6796900],[55.5935940,12.6796900],[55.5935940,12.6796900],[55.5935940,12.6796900],[55.5935940,12.6796900],[55.5935940,12.6796900],[55.5936070,12.6796830],[55.5936020,12.6796720],[55.5936090,12.6796630],[55.5936150,12.6796630],[55.5936150,12.6796630],[55.5936120,12.6796500],[55.5936070,12.6796430],[55.5936070,12.6796440],[55.5936070,12.6796440],[55.5936090,12.6796510],[55.5936120,12.6796540],[55.5936120,12.6796540],[55.5936070,12.6796690],[55.5935940,12.6797220],[55.5935870,12.6797070],[55.5935870,12.6797050],[55.5935870,12.6797030],[55.5935870,12.6797030],[55.5935870,12.6797030],[55.5935870,12.6797030],[55.5935870,12.6797030],[55.5935870,12.6797030],[55.5935870,12.6797030],[55.5935870,12.6797030],[55.5935870,12.6797030],[55.5935870,12.6797030],[55.5935870,12.6797030],[55.5935870,12.6797030],[55.5935870,12.6797030],[55.5935870,12.6797030],[55.5935870,12.6797030],[55.5935870,12.6797020],[55.5935870,12.6797030],[55.5935890,12.6797020],[55.5935890,12.6796990],[55.5935920,12.6797060],[55.5935970,12.6797120],[55.5936040,12.6797330],[55.5936090,12.6797430],[55.5936120,12.6797530],[55.5936150,12.6797530],[55.5936150,12.6797600],[55.5936150,12.6797620],[55.5936170,12.6797630],[55.5936170,12.6797630],[55.5936170,12.6797650],[55.5936150,12.6797690],[55.5936020,12.6797810],[55.5935870,12.6798000],[55.5935510,12.6798390],[55.5935330,12.6799360],[55.5935430,12.6799910],[55.5935480,12.6800050],[55.5935560,12.6800170],[55.5935940,12.6800620],[55.5936120,12.6800800],[55.5936550,12.6801290],[55.5937010,12.6801740],[55.5937470,12.6802270],[55.5937720,12.6802720],[55.5937900,12.6803480],[55.5938150,12.6804740],[55.5938360,12.6805820],[55.5938430,12.6806320],[55.5938510,12.6806960],[55.5938640,12.6807900],[55.5938770,12.6808580],[55.5938920,12.6809810],[55.5938990,12.6810330],[55.5939170,12.6811580],[55.5939270,12.6812250],[55.5939530,12.6813690],[55.5939810,12.6814770],[55.5940090,12.6815850],[55.5940440,12.6817230],[55.5940570,12.6817620],[55.5940880,12.6818800],[55.5941210,12.6819910],[55.5941440,12.6820660],[55.5941640,12.6821340],[55.5941890,12.6822070],[55.5942220,12.6823160],[55.5942730,12.6824660],[55.5943140,12.6825710],[55.5943600,12.6826660],[55.5943930,12.6827380],[55.5944230,12.6828100],[55.5944840,12.6829470],[55.5945510,12.6830790],[55.5946140,12.6832200],[55.5946620,12.6833220],[55.5947310,12.6834500],[55.5947790,12.6835510],[55.5948430,12.6836850],[55.5948580,12.6837200],[55.5948760,12.6837540],[55.5949070,12.6838170],[55.5949700,12.6839470],[55.5950240,12.6840470],[55.5950950,12.6841740],[55.5951510,12.6842770],[55.5952090,12.6843770],[55.5952880,12.6845120],[55.5953720,12.6846310],[55.5954310,12.6847200],[55.5955140,12.6848330],[55.5956030,12.6849410],[55.5956670,12.6850220],[55.5957330,12.6851040],[55.5957990,12.6851870],[55.5958650,12.6852680],[55.5959600,12.6853790],[55.5960310,12.6854530],[55.5960560,12.6854810],[55.5961020,12.6855370],[55.5961930,12.6856390],[55.5962620,12.6857080],[55.5963330,12.6857680],[55.5964330,12.6858490],[55.5965060,12.6859080],[55.5966050,12.6859830],[55.5967000,12.6860590],[55.5967710,12.6861250],[55.5968420,12.6861930],[55.5969410,12.6862800],[55.5970120,12.6863420],[55.5971060,12.6864240],[55.5971830,12.6864810],[55.5972570,12.6865440],[55.5973280,12.6866160],[55.5973990,12.6866780],[55.5974730,12.6867360],[55.5975670,12.6868190],[55.5976350,12.6868770],[55.5977300,12.6869430],[55.5977780,12.6869810],[55.5978490,12.6870370],[55.5979480,12.6871200],[55.5980420,12.6871990],[55.5981190,12.6872600],[55.5982150,12.6873330],[55.5983120,12.6874140],[55.5983830,12.6874670],[55.5984800,12.6875330],[55.5985310,12.6875710],[55.5986300,12.6876400],[55.5987040,12.6876880],[55.5987770,12.6877370],[55.5988740,12.6877960],[55.5989480,12.6878390],[55.5990470,12.6878920],[55.5991460,12.6879500],[55.5991940,12.6879760],[55.5992660,12.6880070],[55.5993190,12.6880220],[55.5993950,12.6880460],[55.5994970,12.6880860],[55.5995990,12.6881490],[55.5997000,12.6882230],[55.5997260,12.6882350],[55.5998280,12.6882570],[55.5998760,12.6882680],[55.5999500,12.6882990],[55.6000260,12.6883310],[55.6001050,12.6883500],[55.6001840,12.6883710],[55.6002850,12.6883950],[55.6003640,12.6884010],[55.6004660,12.6884160],[55.6004910,12.6884210],[55.6005650,12.6884260],[55.6006460,12.6884250],[55.6007000,12.6884260],[55.6008070,12.6884240],[55.6008630,12.6884260],[55.6009160,12.6884300],[55.6010200,12.6884410],[55.6011170,12.6884430],[55.6011930,12.6884490],[55.6012720,12.6884530],[55.6013510,12.6884520],[55.6014070,12.6884520],[55.6014860,12.6884500],[55.6015670,12.6884500],[55.6016740,12.6884320],[55.6017480,12.6884280],[55.6018210,12.6884390],[55.6018700,12.6884460],[55.6018980,12.6884470],[55.6020020,12.6884630],[55.6021060,12.6884730],[55.6021850,12.6884770],[55.6022660,12.6884810],[55.6023220,12.6884810],[55.6023730,12.6884830],[55.6024750,12.6884780],[55.6025790,12.6884640],[55.6026880,12.6884520],[55.6027930,12.6884540],[55.6028690,12.6884610],[55.6029480,12.6884630],[55.6030520,12.6884700],[55.6031050,12.6884710],[55.6031840,12.6884740],[55.6032350,12.6884790],[55.6033140,12.6884850],[55.6033900,12.6884880],[55.6034720,12.6884990],[55.6035530,12.6885050],[55.6036320,12.6885110],[55.6037110,12.6885240],[55.6038170,12.6885350],[55.6038990,12.6885430],[55.6039780,12.6885530],[55.6040280,12.6885610],[55.6041070,12.6885760],[55.6041860,12.6885860],[55.6042930,12.6885950],[55.6043690,12.6886040],[55.6044730,12.6886140],[55.6045520,12.6886240],[55.6046560,12.6886190],[55.6047350,12.6886230],[55.6047890,12.6886250],[55.6048930,12.6886240],[55.6049720,12.6886250],[55.6050810,12.6886320],[55.6051850,12.6886360],[55.6052920,12.6886410],[55.6053710,12.6886420],[55.6054780,12.6886350],[55.6055590,12.6886320],[55.6056630,12.6886290],[55.6057450,12.6886290],[55.6058540,12.6886170],[55.6059610,12.6886160],[55.6060400,12.6886180],[55.6061410,12.6886200],[55.6062230,12.6886230],[55.6063290,12.6886250],[55.6064390,12.6886310],[55.6065200,12.6886290],[55.6066240,12.6886370],[55.6067190,12.6886190],[55.6068050,12.6886000],[55.6068890,12.6885970],[55.6069420,12.6885960],[55.6070160,12.6885990],[55.6070640,12.6885950],[55.6070920,12.6885970],[55.6071230,12.6885970],[55.6071530,12.6886000],[55.6071790,12.6886050],[55.6072040,12.6886070],[55.6072320,12.6886100],[55.6072550,12.6886090],[55.6073590,12.6886250],[55.6074660,12.6886590],[55.6075730,12.6886700],[55.6076820,12.6886770],[55.6077610,12.6886820],[55.6078650,12.6886880],[55.6079720,12.6886930],[55.6080810,12.6886970],[55.6081580,12.6887000],[55.6082110,12.6887040],[55.6082390,12.6887070],[55.6082670,12.6887090],[55.6082950,12.6887100],[55.6083230,12.6887110],[55.6083510,12.6887150],[55.6083790,12.6887180],[55.6084040,12.6887200],[55.6084580,12.6887270],[55.6084860,12.6887320],[55.6085110,12.6887360],[55.6085640,12.6887440],[55.6086180,12.6887510],[55.6086710,12.6887560],[55.6086990,12.6887590],[55.6087550,12.6887640],[55.6088060,12.6887750],[55.6088870,12.6887870],[55.6089380,12.6887970],[55.6090170,12.6888150],[55.6090930,12.6888280],[55.6091720,12.6888420],[55.6092480,12.6888550],[55.6093320,12.6888720],[55.6094080,12.6888750],[55.6094870,12.6888790],[55.6095380,12.6888890],[55.6096170,12.6888940],[55.6097190,12.6889100],[55.6098150,12.6889170],[55.6098910,12.6889180],[55.6099960,12.6889180],[55.6100770,12.6889120],[55.6101530,12.6889060],[55.6102550,12.6889040],[55.6103310,12.6888970],[55.6104330,12.6888940],[55.6105140,12.6888990],[55.6105680,12.6889120],[55.6106690,12.6889380],[55.6107740,12.6889640],[55.6108750,12.6889840],[55.6109800,12.6890020],[55.6110810,12.6890200],[55.6111830,12.6890380],[55.6112360,12.6890490],[55.6113410,12.6890670],[55.6114420,12.6890860],[55.6115190,12.6891010],[55.6115920,12.6891110],[55.6116960,12.6891280],[55.6118010,12.6891390],[55.6118770,12.6891550],[55.6119790,12.6891800],[55.6120800,12.6892070],[55.6121820,12.6892300],[55.6122560,12.6892440],[55.6123320,12.6892560],[55.6124080,12.6892670],[55.6124820,12.6892780],[55.6125810,12.6893010],[55.6126830,12.6893230],[55.6127870,12.6893540],[55.6128890,12.6893900],[55.6129650,12.6894220],[55.6130390,12.6894430],[55.6131180,12.6894640],[55.6131960,12.6894820],[55.6133010,12.6895000],[55.6134050,12.6895200],[55.6135040,12.6895310],[55.6136030,12.6895360],[55.6136790,12.6895450],[55.6137560,12.6895540],[55.6138040,12.6895510],[55.6138800,12.6895520],[55.6139820,12.6895550],[55.6140810,12.6895490],[55.6141800,12.6895380],[55.6142820,12.6895240],[55.6143560,12.6895140],[55.6144320,12.6895050],[55.6145030,12.6894980],[55.6146020,12.6894900],[55.6146530,12.6894900],[55.6147010,12.6894810],[55.6147750,12.6894680],[55.6148280,12.6894680],[55.6149300,12.6894630],[55.6149780,12.6894610],[55.6150800,12.6894560],[55.6151770,12.6894580],[55.6152300,12.6894600],[55.6152530,12.6894610],[55.6153040,12.6894580],[55.6153550,12.6894590],[55.6153800,12.6894590],[55.6154330,12.6894610],[55.6154790,12.6894690],[55.6155300,12.6894610],[55.6156270,12.6894490],[55.6156770,12.6894420],[55.6157460,12.6894330],[55.6158020,12.6894230],[55.6158530,12.6894110],[55.6159290,12.6893910],[55.6160260,12.6893840],[55.6161020,12.6893830],[55.6161550,12.6893820],[55.6162570,12.6893780],[55.6163590,12.6893690],[55.6164600,12.6893630],[55.6165370,12.6893610],[55.6166410,12.6893510],[55.6166890,12.6893450],[55.6167400,12.6893370],[55.6168420,12.6893330],[55.6168670,12.6893360],[55.6169150,12.6893400],[55.6169610,12.6893480],[55.6170400,12.6893660],[55.6171440,12.6893900],[55.6172250,12.6894020],[55.6173020,12.6894100],[55.6173500,12.6894110],[55.6174030,12.6894120],[55.6174290,12.6894130],[55.6175330,12.6894170],[55.6176120,12.6894210],[55.6177110,12.6894290],[55.6178130,12.6894330],[55.6178610,12.6894340],[55.6179400,12.6894360],[55.6179930,12.6894370],[55.6180690,12.6894380],[55.6181430,12.6894330],[55.6182470,12.6894340],[55.6183240,12.6894400],[55.6184230,12.6894490],[55.6184990,12.6894570],[55.6185500,12.6894630],[55.6186010,12.6894670],[55.6186770,12.6894670],[55.6187050,12.6894680],[55.6187330,12.6894700],[55.6188120,12.6894770],[55.6188600,12.6894770],[55.6189610,12.6894610],[55.6190480,12.6894430],[55.6191240,12.6894340],[55.6192000,12.6894230],[55.6192540,12.6894140],[55.6193350,12.6894030],[55.6194090,12.6893940],[55.6194600,12.6893860],[55.6194850,12.6893810],[55.6195380,12.6893740],[55.6195610,12.6893720],[55.6195870,12.6893680],[55.6196100,12.6893660],[55.6196350,12.6893640],[55.6196600,12.6893590],[55.6197110,12.6893490],[55.6197620,12.6893410],[55.6198130,12.6893360],[55.6198610,12.6893310],[55.6199100,12.6893230],[55.6199810,12.6893100],[55.6200770,12.6892910],[55.6201510,12.6892920],[55.6202300,12.6893000],[55.6202550,12.6893020],[55.6203540,12.6893190],[55.6204260,12.6893310],[55.6205200,12.6893450],[55.6205700,12.6893510],[55.6206440,12.6893630],[55.6206950,12.6893680],[55.6207430,12.6893730],[55.6207920,12.6893790],[55.6208680,12.6893850],[55.6209390,12.6893860],[55.6209920,12.6893900],[55.6210180,12.6893910],[55.6210860,12.6893940],[55.6211350,12.6893910],[55.6212130,12.6893840],[55.6212870,12.6893810],[55.6213130,12.6893790],[55.6213840,12.6893840],[55.6214600,12.6893810],[55.6215340,12.6893750],[55.6215570,12.6893700],[55.6216070,12.6893640],[55.6216840,12.6893490],[55.6217060,12.6893400],[55.6218010,12.6893110],[55.6218260,12.6892990],[55.6219200,12.6892420],[55.6219430,12.6892300],[55.6219660,12.6892220],[55.6219890,12.6892140],[55.6220110,12.6892100],[55.6221080,12.6891930],[55.6221360,12.6891860],[55.6221590,12.6891770],[55.6222530,12.6891390],[55.6222780,12.6891290],[55.6223770,12.6890800],[55.6224210,12.6890630],[55.6224660,12.6890540],[55.6224890,12.6890460],[55.6225400,12.6890340],[55.6226390,12.6890240],[55.6227330,12.6890080],[55.6228270,12.6889890],[55.6229010,12.6889660],[55.6229980,12.6889460],[55.6231020,12.6889350],[55.6231750,12.6889340],[55.6232750,12.6889300],[55.6233510,12.6889280],[55.6234250,12.6889300],[55.6234500,12.6889310],[55.6234730,12.6889330],[55.6235470,12.6889370],[55.6235720,12.6889370],[55.6236510,12.6889420],[55.6236990,12.6889470],[55.6237220,12.6889510],[55.6237930,12.6889620],[55.6238410,12.6889730],[55.6239180,12.6889920],[55.6239910,12.6890190],[55.6240190,12.6890280],[55.6240680,12.6890380],[55.6241620,12.6890680],[55.6242350,12.6890840],[55.6242610,12.6890890],[55.6243090,12.6890970],[55.6243570,12.6891090],[55.6244510,12.6891380],[55.6245000,12.6891460],[55.6245960,12.6891670],[55.6246500,12.6891680],[55.6247460,12.6891710],[55.6248450,12.6891780],[55.6249190,12.6891750],[55.6249900,12.6891760],[55.6250870,12.6891800],[55.6251550,12.6891670],[55.6252620,12.6891680],[55.6252870,12.6891670],[55.6253360,12.6891560],[55.6254320,12.6891320],[55.6255030,12.6891170],[55.6255290,12.6891110],[55.6256230,12.6890750],[55.6256460,12.6890660],[55.6257190,12.6890380],[55.6257680,12.6890150],[55.6258360,12.6889860],[55.6259330,12.6889580],[55.6260270,12.6889160],[55.6261160,12.6888630],[55.6262070,12.6888020],[55.6263010,12.6887420],[55.6263240,12.6887240],[55.6263900,12.6886750],[55.6264130,12.6886650],[55.6264640,12.6886510],[55.6265400,12.6886290],[55.6265860,12.6886170],[55.6266570,12.6885960],[55.6267510,12.6885780],[55.6267970,12.6885770],[55.6268220,12.6885780],[55.6269190,12.6885830],[55.6269950,12.6885880],[55.6270460,12.6885920],[55.6270920,12.6885970],[55.6271880,12.6886060],[55.6272870,12.6886180],[55.6273130,12.6886220],[55.6273860,12.6886260],[55.6274830,12.6886280],[55.6275080,12.6886270],[55.6275310,12.6886270],[55.6275570,12.6886270],[55.6276530,12.6886290],[55.6277040,12.6886290],[55.6277270,12.6886310],[55.6277730,12.6886270],[55.6278720,12.6886240],[55.6279150,12.6886270],[55.6279910,12.6886230],[55.6280140,12.6886220],[55.6281160,12.6886160],[55.6281670,12.6886150],[55.6281920,12.6886140],[55.6282430,12.6886190],[55.6282910,12.6886240],[55.6283900,12.6886420],[55.6284160,12.6886450],[55.6285100,12.6886500],[55.6285330,12.6886520],[55.6285580,12.6886550],[55.6286060,12.6886710],[55.6286550,12.6886860],[55.6286800,12.6886950],[55.6287260,12.6887180],[55.6287760,12.6887390],[55.6288710,12.6887900],[55.6289490,12.6888300],[55.6290410,12.6888830],[55.6291120,12.6889120],[55.6291350,12.6889190],[55.6292260,12.6889310],[55.6293230,12.6889270],[55.6293940,12.6889180],[55.6294630,12.6889070],[55.6295360,12.6888890],[55.6296100,12.6888740],[55.6297120,12.6888730],[55.6297620,12.6888750],[55.6298590,12.6888870],[55.6299580,12.6888910],[55.6300600,12.6889010],[55.6301590,12.6889060],[55.6302600,12.6889100],[55.6303650,12.6889200],[55.6304610,12.6889170],[55.6305120,12.6889030],[55.6306090,12.6888760],[55.6306800,12.6888720],[55.6307530,12.6888710],[55.6308550,12.6888560],[55.6309540,12.6888470],[55.6310560,12.6888440],[55.6311320,12.6888420],[55.6312110,12.6888460],[55.6313150,12.6888480],[55.6313890,12.6888510],[55.6314620,12.6888550],[55.6315640,12.6888690],[55.6316610,12.6888870],[55.6317620,12.6888940],[55.6318610,12.6889030],[55.6319630,12.6889130],[55.6320590,12.6889180],[55.6321380,12.6889120],[55.6322420,12.6889060],[55.6323440,12.6888940],[55.6324230,12.6888900],[55.6325240,12.6888820],[55.6326260,12.6888810],[55.6326790,12.6888820],[55.6327580,12.6888880],[55.6328600,12.6888820],[55.6329540,12.6888700],[55.6330580,12.6888640],[55.6331600,12.6888620],[55.6332640,12.6888650],[55.6333600,12.6888900],[55.6334340,12.6889160],[55.6335330,12.6889490],[55.6336270,12.6889800],[55.6337190,12.6889980],[55.6338300,12.6890190],[55.6339270,12.6890330],[55.6340180,12.6890620],[55.6341120,12.6890920],[55.6342090,12.6891180],[55.6343030,12.6891400],[55.6344000,12.6891690],[55.6344940,12.6891900],[55.6345850,12.6892080],[55.6346820,12.6892310],[55.6347710,12.6892540],[55.6348620,12.6892620],[55.6349560,12.6892560],[55.6350530,12.6892450],[55.6351520,12.6892380],[55.6352430,12.6892310],[55.6353370,12.6892100],[55.6354260,12.6891690],[55.6355150,12.6891280],[55.6356140,12.6890900],[55.6356850,12.6890720],[55.6357030,12.6890680],[55.6357230,12.6890560],[55.6357840,12.6890310],[55.6358050,12.6890280],[55.6358480,12.6890150],[55.6358710,12.6890060],[55.6358930,12.6889980],[55.6359190,12.6889890],[55.6359420,12.6889810],[55.6359870,12.6889630],[55.6360330,12.6889460],[55.6361220,12.6889150],[55.6361910,12.6888840],[55.6362340,12.6888630],[55.6362750,12.6888400],[55.6363180,12.6888150],[55.6363380,12.6888000],[55.6363610,12.6887820],[55.6364040,12.6887510],[55.6364470,12.6887170],[55.6364880,12.6886750],[55.6365290,12.6886370],[55.6365950,12.6885860],[55.6366580,12.6885270],[55.6367400,12.6884580],[55.6368360,12.6883910],[55.6369250,12.6883360],[55.6370140,12.6882750],[55.6371000,12.6882170],[55.6371890,12.6881560],[55.6372680,12.6880720],[55.6373090,12.6880280],[55.6373920,12.6879510],[55.6374810,12.6878760],[55.6375650,12.6878040],[55.6376520,12.6877270],[55.6377350,12.6876390],[55.6378140,12.6875480],[55.6378930,12.6874620],[55.6379770,12.6873820],[55.6380610,12.6873040],[55.6381390,12.6872270],[55.6382260,12.6871510],[55.6383100,12.6870840],[55.6384040,12.6870180],[55.6384870,12.6869460],[55.6385760,12.6868720],[55.6386680,12.6868030],[55.6387520,12.6867360],[55.6388430,12.6866580],[55.6389270,12.6865820],[55.6390130,12.6865020],[55.6390950,12.6864080],[55.6391730,12.6863130],[55.6392600,12.6862250],[55.6393410,12.6861330],[55.6394150,12.6860240],[55.6394930,12.6859290],[55.6395670,12.6858170],[55.6396430,12.6857030],[55.6397140,12.6855970],[55.6397910,12.6854900],[55.6398670,12.6854000],[55.6399430,12.6853060],[55.6400220,12.6852130],[55.6401010,12.6851350],[55.6401410,12.6850890],[55.6401820,12.6850430],[55.6402450,12.6849850],[55.6403140,12.6849300],[55.6403800,12.6848780],[55.6404690,12.6848150],[55.6405580,12.6847510],[55.6406520,12.6846950],[55.6407430,12.6846400],[55.6408350,12.6845830],[55.6409240,12.6845070],[55.6410070,12.6844320],[55.6410910,12.6843580],[55.6411800,12.6842770],[55.6412670,12.6842020],[55.6413530,12.6841200],[55.6414470,12.6840390],[55.6415360,12.6839700],[55.6416250,12.6839030],[55.6417190,12.6838340],[55.6418030,12.6837520],[55.6418890,12.6836870],[55.6419800,12.6836280],[55.6420720,12.6835610],[55.6421630,12.6834970],[55.6422520,12.6834280],[55.6423390,12.6833550],[55.6424300,12.6832980],[55.6425190,12.6832340],[55.6426000,12.6831680],[55.6426870,12.6830900],[55.6427680,12.6830160],[55.6428590,12.6829460],[55.6429480,12.6828730],[55.6430370,12.6828060],[55.6431240,12.6827400],[55.6432100,12.6826700],[55.6432960,12.6825970],[55.6433850,12.6825190],[55.6434660,12.6824260],[55.6435500,12.6823530],[55.6436420,12.6822720],[55.6437230,12.6821840],[55.6438070,12.6820970],[55.6438830,12.6820000],[55.6439620,12.6818890],[55.6440280,12.6817760],[55.6440960,12.6816520],[55.6441620,12.6815170],[55.6442460,12.6814110],[55.6443280,12.6813300],[55.6444160,12.6812530],[55.6445050,12.6811750],[55.6445940,12.6810870],[55.6446730,12.6809930],[55.6447620,12.6809100],[55.6448480,12.6808390],[55.6449400,12.6807640],[55.6450290,12.6806910],[55.6451150,12.6806200],[55.6452060,12.6805520],[55.6453000,12.6804730],[55.6453770,12.6803830],[55.6454650,12.6802980],[55.6455520,12.6802240],[55.6456430,12.6801570],[55.6457320,12.6800920],[55.6458240,12.6800210],[55.6459150,12.6799480],[55.6460010,12.6798570],[55.6460830,12.6797700],[55.6461640,12.6796840],[55.6462530,12.6796130],[55.6463390,12.6795280],[55.6464180,12.6794310],[55.6464940,12.6793300],[55.6465780,12.6792400],[55.6466720,12.6791580],[55.6467660,12.6791030],[55.6468600,12.6790480],[55.6469510,12.6789990],[55.6470480,12.6789570],[55.6471440,12.6789200],[55.6472410,12.6788750],[55.6473370,12.6788360],[55.6474310,12.6787990],[55.6475280,12.6787610],[55.6476240,12.6787250],[55.6477210,12.6786850],[55.6478250,12.6786470],[55.6479270,12.6786010],[55.6480030,12.6785710],[55.6481040,12.6785270],[55.6482040,12.6784770],[55.6483000,12.6784280],[55.6483940,12.6783800],[55.6484980,12.6783280],[55.6485920,12.6782770],[55.6486860,12.6782270],[55.6487800,12.6781770],[55.6488770,12.6781320],[55.6489530,12.6781090],[55.6490490,12.6780750],[55.6491510,12.6780500],[55.6492500,12.6780320],[55.6493520,12.6780150],[55.6494530,12.6780150],[55.6495570,12.6780150],[55.6496590,12.6780140],[55.6497350,12.6780020],[55.6498420,12.6779700],[55.6499410,12.6779290],[55.6500400,12.6778800],[55.6500860,12.6778580],[55.6501590,12.6778220],[55.6502100,12.6777950],[55.6502860,12.6777640],[55.6503340,12.6777490],[55.6504060,12.6777250],[55.6504590,12.6777020],[55.6505100,12.6776790],[55.6505810,12.6776500],[55.6506290,12.6776300],[55.6507030,12.6776000],[55.6507790,12.6775760],[55.6508520,12.6775480],[55.6509240,12.6775100],[55.6509720,12.6774800],[55.6510430,12.6774320],[55.6510910,12.6773980],[55.6511140,12.6773780],[55.6511390,12.6773600],[55.6512330,12.6772890],[55.6513220,12.6772350],[55.6514090,12.6771670],[55.6514980,12.6770970],[55.6515920,12.6770300],[55.6516850,12.6769660],[55.6517570,12.6769230],[55.6518530,12.6768720],[55.6519500,12.6768250],[55.6520490,12.6767800],[55.6520990,12.6767630],[55.6521960,12.6767260],[55.6522440,12.6767170],[55.6523200,12.6766970],[55.6524140,12.6766500],[55.6524880,12.6766220],[55.6525770,12.6765690],[55.6526760,12.6765100],[55.6527240,12.6764770],[55.6527930,12.6764320],[55.6528840,12.6763510],[55.6529270,12.6763120],[55.6529450,12.6762950],[55.6529910,12.6762580],[55.6530750,12.6761660],[55.6531430,12.6760980],[55.6531860,12.6760490],[55.6532730,12.6759550],[55.6533590,12.6758680],[55.6534450,12.6757750],[55.6535320,12.6756800],[55.6536160,12.6755850],[55.6537020,12.6754940],[55.6537910,12.6754060],[55.6538820,12.6753270],[55.6539740,12.6752510],[55.6540680,12.6751740],[55.6541590,12.6751040],[55.6542480,12.6750330],[55.6543370,12.6749650],[55.6544310,12.6748890],[55.6545220,12.6748160],[55.6546190,12.6747510],[55.6547050,12.6746790],[55.6547960,12.6746130],[55.6548900,12.6745490],[55.6549790,12.6744870],[55.6550730,12.6744190],[55.6551650,12.6743560],[55.6552610,12.6742930],[55.6553580,12.6742340],[55.6554570,12.6741760],[55.6555480,12.6741190],[55.6556450,12.6740620],[55.6557440,12.6740010],[55.6558320,12.6739390],[55.6559210,12.6738760],[55.6560150,12.6738060],[55.6561070,12.6737330],[55.6562010,12.6736650],[55.6562920,12.6736050],[55.6563860,12.6735270],[55.6564750,12.6734530],[55.6565640,12.6733730],[55.6566550,12.6732960],[55.6567470,12.6732160],[55.6568330,12.6731440],[55.6569220,12.6730700],[55.6570160,12.6729880],[55.6571070,12.6729170],[55.6571990,12.6728400],[55.6572870,12.6727670],[55.6573790,12.6726970],[55.6574730,12.6726230],[55.6575640,12.6725540],[55.6576530,12.6724810],[55.6577220,12.6724290],[55.6577700,12.6723930],[55.6578660,12.6723100],[55.6579600,12.6722370],[55.6580520,12.6721650],[55.6581250,12.6721160],[55.6581940,12.6720650],[55.6582630,12.6720070],[55.6583260,12.6719570],[55.6584000,12.6719080],[55.6584960,12.6718520],[55.6585950,12.6718010],[55.6586940,12.6717550],[55.6587700,12.6717200],[55.6588440,12.6716870],[55.6589230,12.6716420],[55.6589940,12.6716060],[55.6590620,12.6715670],[55.6591590,12.6715090],[55.6592500,12.6714570],[55.6593420,12.6713930],[55.6594100,12.6713480],[55.6595020,12.6712860],[55.6595880,12.6712200],[55.6596820,12.6711680],[55.6597730,12.6711200],[55.6598670,12.6710680],[55.6599660,12.6710180],[55.6600650,12.6709710],[55.6601640,12.6709240],[55.6602630,12.6708680],[55.6603600,12.6708130],[55.6604540,12.6707590],[55.6605530,12.6707050],[55.6606490,12.6706480],[55.6607480,12.6705900],[55.6608250,12.6705430],[55.6609180,12.6704830],[55.6610120,12.6704200],[55.6611040,12.6703600],[55.6611950,12.6702890],[55.6612820,12.6702110],[55.6613530,12.6701530],[55.6614520,12.6700780],[55.6615460,12.6700150],[55.6616420,12.6699440],[55.6617080,12.6698860],[55.6617940,12.6698040],[55.6618600,12.6697410],[55.6619290,12.6696850],[55.6619750,12.6696450],[55.6620200,12.6696050],[55.6620860,12.6695430],[55.6621520,12.6694860],[55.6622210,12.6694280],[55.6622870,12.6693710],[55.6623530,12.6693230],[55.6624470,12.6692550],[55.6625360,12.6691820],[55.6625590,12.6691650],[55.6626270,12.6691130],[55.6627210,12.6690420],[55.6628130,12.6689770],[55.6629090,12.6689130],[55.6630050,12.6688440],[55.6630940,12.6687720],[55.6631880,12.6687100],[55.6632820,12.6686420],[55.6633790,12.6685790],[55.6634730,12.6685190],[55.6635640,12.6684480],[55.6636580,12.6683810],[55.6637520,12.6683090],[55.6638480,12.6682350],[55.6639420,12.6681670],[55.6640390,12.6681040],[55.6641300,12.6680250],[55.6642240,12.6679440],[55.6643130,12.6678630],[55.6644070,12.6677810],[55.6645010,12.6677050],[55.6645970,12.6676280],[55.6646890,12.6675560],[55.6647830,12.6674900],[55.6648770,12.6674180],[55.6649710,12.6673450],[55.6650640,12.6672780],[55.6651560,12.6672050],[55.6652500,12.6671280],[55.6653060,12.6670840],[55.6653790,12.6670370],[55.6654270,12.6670000],[55.6654760,12.6669640],[55.6655470,12.6668920],[55.6656330,12.6668140],[55.6657220,12.6667300],[55.6657880,12.6666690],[55.6658570,12.6666070],[55.6659020,12.6665680],[55.6659250,12.6665490],[55.6659910,12.6664870],[55.6660600,12.6664240],[55.6661260,12.6663600],[55.6662170,12.6662780],[55.6663080,12.6661980],[55.6664000,12.6661190],[55.6664910,12.6660420],[55.6665830,12.6659650],[55.6666770,12.6658890],[55.6667480,12.6658320],[55.6668160,12.6657720],[55.6669080,12.6656940],[55.6670010,12.6656170],[55.6670930,12.6655440],[55.6671870,12.6654730],[55.6672810,12.6653990],[55.6673720,12.6653260],[55.6674410,12.6652690],[55.6675320,12.6651910],[55.6675780,12.6651530],[55.6676260,12.6651140],[55.6676490,12.6650930],[55.6676940,12.6650530],[55.6677170,12.6650330],[55.6677400,12.6650130],[55.6677830,12.6649710],[55.6678290,12.6649250],[55.6678720,12.6648790],[55.6679180,12.6648360],[55.6679840,12.6647720],[55.6680300,12.6647300],[55.6680730,12.6646870],[55.6681180,12.6646440],[55.6681620,12.6646000],[55.6682070,12.6645570],[55.6682500,12.6645150],[55.6682730,12.6644950],[55.6683160,12.6644530],[55.6683390,12.6644330],[55.6683620,12.6644120],[55.6683850,12.6643920],[55.6684080,12.6643720],[55.6684610,12.6643240],[55.6685070,12.6642880],[55.6685530,12.6642510],[55.6685980,12.6642130],[55.6686670,12.6641600],[55.6687630,12.6640920],[55.6688340,12.6640390],[55.6688570,12.6640210],[55.6689280,12.6639670],[55.6689510,12.6639530],[55.6689760,12.6639380],[55.6690450,12.6638910],[55.6690700,12.6638750],[55.6691670,12.6638120],[55.6692610,12.6637490],[55.6693320,12.6637040],[55.6694050,12.6636570],[55.6694310,12.6636430],[55.6695020,12.6636000],[55.6696030,12.6635390],[55.6696540,12.6635110],[55.6696770,12.6634960],[55.6697020,12.6634800],[55.6697740,12.6634290],[55.6698220,12.6633970],[55.6699180,12.6633360],[55.6700150,12.6632800],[55.6700910,12.6632400],[55.6701900,12.6631880],[55.6702380,12.6631630],[55.6703140,12.6631260],[55.6704160,12.6630830],[55.6705150,12.6630440],[55.6705910,12.6630150],[55.6706650,12.6629860],[55.6707640,12.6629440],[55.6708400,12.6629110],[55.6709160,12.6628750],[55.6709670,12.6628500],[55.6710680,12.6628050],[55.6711670,12.6627650],[55.6712690,12.6627220],[55.6713450,12.6626850],[55.6714440,12.6626340],[55.6715450,12.6625790],[55.6716420,12.6625250],[55.6717410,12.6624700],[55.6717660,12.6624550],[55.6718120,12.6624240],[55.6718580,12.6623920],[55.6719510,12.6623150],[55.6720230,12.6622580],[55.6720940,12.6622050],[55.6721880,12.6621350],[55.6722360,12.6621010],[55.6723070,12.6620520],[55.6723780,12.6620010],[55.6724720,12.6619350],[55.6724970,12.6619180],[55.6725200,12.6619030],[55.6725960,12.6618570],[55.6726440,12.6618290],[55.6727180,12.6617910],[55.6727430,12.6617790],[55.6728220,12.6617440],[55.6728980,12.6617140],[55.6729520,12.6616930],[55.6729740,12.6616830],[55.6730000,12.6616730],[55.6730530,12.6616520],[55.6731040,12.6616290],[55.6732050,12.6615770],[55.6732540,12.6615500],[55.6732760,12.6615360],[55.6733470,12.6614930],[55.6733960,12.6614650],[55.6734210,12.6614550],[55.6734460,12.6614460],[55.6734720,12.6614400],[55.6735710,12.6614130],[55.6736750,12.6613810],[55.6737230,12.6613630],[55.6737990,12.6613320],[55.6738730,12.6612980],[55.6739440,12.6612620],[55.6739690,12.6612500],[55.6740180,12.6612230],[55.6740660,12.6611930],[55.6741370,12.6611490],[55.6742080,12.6611040],[55.6742820,12.6610580],[55.6743530,12.6610130],[55.6744240,12.6609670],[55.6744950,12.6609190],[55.6745660,12.6608700],[55.6746370,12.6608200],[55.6746850,12.6607880],[55.6747080,12.6607710],[55.6747790,12.6607220],[55.6748480,12.6606760],[55.6749210,12.6606310],[55.6750150,12.6605690],[55.6751120,12.6605100],[55.6751340,12.6604960],[55.6752080,12.6604550],[55.6752560,12.6604300],[55.6753530,12.6603770],[55.6753780,12.6603630],[55.6754010,12.6603480],[55.6754950,12.6602890],[55.6755660,12.6602370],[55.6756120,12.6602010],[55.6756800,12.6601480],[55.6757710,12.6600720],[55.6758150,12.6600340],[55.6758830,12.6599750],[55.6759720,12.6598970],[55.6760610,12.6598170],[55.6760840,12.6597970],[55.6761290,12.6597560],[55.6761500,12.6597370],[55.6762180,12.6596780],[55.6762610,12.6596400],[55.6762840,12.6596210],[55.6763730,12.6595400],[55.6764590,12.6594560],[55.6764800,12.6594340],[55.6765660,12.6593480],[55.6766340,12.6592850],[55.6766770,12.6592430],[55.6767410,12.6591830],[55.6768070,12.6591180],[55.6768700,12.6590520],[55.6769140,12.6590110],[55.6770020,12.6589310],[55.6770910,12.6588550],[55.6771370,12.6588200],[55.6771830,12.6587910],[55.6772050,12.6587800],[55.6772790,12.6587570],[55.6773550,12.6587470],[55.6773780,12.6587400],[55.6774770,12.6587090],[55.6775760,12.6586660],[55.6776240,12.6586440],[55.6777210,12.6585950],[55.6778140,12.6585430],[55.6778400,12.6585280],[55.6778880,12.6584970],[55.6779110,12.6584820],[55.6780050,12.6584180],[55.6780960,12.6583540],[55.6781900,12.6582820],[55.6782840,12.6582100],[55.6783300,12.6581740],[55.6783980,12.6581230],[55.6784950,12.6580550],[55.6785430,12.6580230],[55.6785890,12.6579900],[55.6786140,12.6579730],[55.6787080,12.6579060],[55.6788040,12.6578460],[55.6788300,12.6578330],[55.6788550,12.6578180],[55.6789260,12.6577760],[55.6790000,12.6577330],[55.6790710,12.6576900],[55.6791700,12.6576340],[55.6792660,12.6575740],[55.6792890,12.6575590],[55.6793850,12.6575050],[55.6794840,12.6574530],[55.6795100,12.6574380],[55.6795330,12.6574230],[55.6795810,12.6573920],[55.6796520,12.6573410],[55.6797000,12.6573020],[55.6797690,12.6572500],[55.6798650,12.6571770],[55.6799560,12.6571070],[55.6800050,12.6570720],[55.6800990,12.6570070],[55.6801950,12.6569320],[55.6802890,12.6568610],[55.6803350,12.6568190],[55.6803980,12.6567530],[55.6804890,12.6566710],[55.6805580,12.6566160],[55.6806540,12.6565520],[55.6807030,12.6565220],[55.6808010,12.6564660],[55.6809030,12.6564200],[55.6809790,12.6563920],[55.6810550,12.6563670],[55.6811310,12.6563420],[55.6812080,12.6563180],[55.6812860,12.6562910],[55.6813850,12.6562580],[55.6814870,12.6562220],[55.6815910,12.6561900],[55.6816900,12.6561500],[55.6817430,12.6561240],[55.6818370,12.6560660],[55.6819100,12.6560160],[55.6820040,12.6559480],[55.6820750,12.6558940],[55.6821690,12.6558220],[55.6822610,12.6557480],[55.6823550,12.6556830],[55.6824030,12.6556490],[55.6824990,12.6555850],[55.6825960,12.6555190],[55.6826870,12.6554450],[55.6827330,12.6554050],[55.6828240,12.6553280],[55.6829150,12.6552470],[55.6829810,12.6551810],[55.6830700,12.6550910],[55.6831590,12.6550030],[55.6832480,12.6549180],[55.6832710,12.6548970],[55.6832930,12.6548770],[55.6833620,12.6548170],[55.6834610,12.6547530],[55.6835620,12.6547150],[55.6836610,12.6546560],[55.6837100,12.6546300],[55.6837880,12.6546000],[55.6838640,12.6545950],[55.6839710,12.6545870],[55.6840470,12.6545640],[55.6841260,12.6545330],[55.6841510,12.6545230],[55.6842500,12.6544810],[55.6843540,12.6544400],[55.6844300,12.6544070],[55.6845320,12.6543570],[55.6846280,12.6543040],[55.6847070,12.6542590],[55.6848010,12.6541960],[55.6848970,12.6541440],[55.6849990,12.6541040],[55.6851000,12.6540660],[55.6851990,12.6540300],[55.6853010,12.6539940],[55.6854020,12.6539490],[55.6855010,12.6539110],[55.6856030,12.6538810],[55.6857040,12.6538520],[55.6858060,12.6538190],[55.6859100,12.6537870],[55.6860090,12.6537570],[55.6861130,12.6537290],[55.6862120,12.6537050],[55.6863130,12.6536810],[55.6864150,12.6536530],[55.6865130,12.6536230],[55.6865900,12.6536010],[55.6866890,12.6535740],[55.6867880,12.6535410],[55.6868860,12.6535080],[55.6869880,12.6534740],[55.6870620,12.6534490],[55.6871630,12.6534170],[55.6872620,12.6533820],[55.6873610,12.6533490],[55.6874620,12.6533250],[55.6875640,12.6533070],[55.6876650,12.6533050],[55.6877690,12.6532930],[55.6878710,12.6532800],[55.6879500,12.6532650],[55.6880510,12.6532430],[55.6881270,12.6532260],[55.6882060,12.6532080],[55.6882820,12.6531960],[55.6883890,12.6531840],[55.6884650,12.6531750],[55.6885690,12.6531510],[55.6886730,12.6531250],[55.6887490,12.6530930],[55.6888250,12.6530600],[55.6889260,12.6530220],[55.6889770,12.6530040],[55.6890530,12.6529740],[55.6891520,12.6529340],[55.6892540,12.6528950],[55.6893550,12.6528550],[55.6894540,12.6528190],[55.6895560,12.6527840],[55.6896570,12.6527570],[55.6897100,12.6527450],[55.6897870,12.6527270],[55.6898880,12.6527060],[55.6899920,12.6526910],[55.6900960,12.6526720],[55.6901470,12.6526660],[55.6902530,12.6526580],[55.6903040,12.6526530],[55.6903830,12.6526470],[55.6904640,12.6526410],[55.6905680,12.6526400],[55.6906470,12.6526420],[55.6907530,12.6526420],[55.6908320,12.6526470],[55.6909100,12.6526600],[55.6910170,12.6526770],[55.6910980,12.6526870],[55.6912050,12.6526930],[55.6912830,12.6526980],[55.6913620,12.6527040],[55.6914690,12.6527130],[55.6915470,12.6527200],[55.6916510,12.6527350],[55.6917550,12.6527450],[55.6918590,12.6527580],[55.6919630,12.6527710],[55.6920650,12.6527840],[55.6921690,12.6527970],[55.6922700,12.6528180],[55.6923740,12.6528390],[55.6924500,12.6528520],[55.6925520,12.6528710],[55.6926310,12.6528860],[55.6927320,12.6529060],[55.6928360,12.6529330],[55.6929380,12.6529590],[55.6930420,12.6529820],[55.6931460,12.6530050],[55.6932500,12.6530270],[55.6933510,12.6530400],[55.6934300,12.6530510],[55.6935340,12.6530720],[55.6936380,12.6530980],[55.6937420,12.6531230],[55.6938430,12.6531470],[55.6939470,12.6531700],[55.6940490,12.6531890],[55.6941530,12.6532010],[55.6942540,12.6532230],[55.6943580,12.6532450],[55.6944600,12.6532640],[55.6945610,12.6532830],[55.6946630,12.6533010],[55.6947640,12.6533110],[55.6948660,12.6533190],[55.6949670,12.6533290],[55.6950710,12.6533460],[55.6951500,12.6533580],[55.6952540,12.6533790],[55.6953300,12.6533870],[55.6954340,12.6533890],[55.6955350,12.6533820],[55.6956370,12.6533790],[55.6957410,12.6533810],[55.6958450,12.6533740],[55.6959230,12.6533700],[55.6960270,12.6533640],[55.6961290,12.6533660],[55.6962350,12.6533710],[55.6963390,12.6533810],[55.6964430,12.6533910],[55.6965470,12.6533930],[55.6966510,12.6533930],[55.6968470,12.6534110],[55.6969380,12.6534000],[55.6970370,12.6533950],[55.6971410,12.6533950],[55.6972480,12.6533990],[55.6973520,12.6533990],[55.6974560,12.6533990],[55.6975620,12.6533980],[55.6976660,12.6533980],[55.6977700,12.6533940],[55.6978740,12.6533830],[55.6979500,12.6533740],[55.6980290,12.6533650],[55.6980820,12.6533570],[55.6981580,12.6533450],[55.6982370,12.6533360],[55.6983180,12.6533300],[55.6983970,12.6533200],[55.6984750,12.6533080],[55.6985510,12.6532930],[55.6986270,12.6532830],[55.6987040,12.6532720],[55.6988050,12.6532540],[55.6988810,12.6532420],[55.6989830,12.6532260],[55.6990610,12.6532120],[55.6991120,12.6532010],[55.6991850,12.6531720],[55.6992620,12.6531460],[55.6993350,12.6531290],[55.6994140,12.6531140],[55.6994640,12.6531040],[55.6995380,12.6530860],[55.6996400,12.6530540],[55.6997410,12.6530240],[55.6998420,12.6530010],[55.6999440,12.6529820],[55.7000450,12.6529630],[55.7001210,12.6529440],[55.7002000,12.6529270],[55.7002990,12.6528980],[55.7003500,12.6528860],[55.7004260,12.6528700],[55.7005270,12.6528480],[55.7006290,12.6528250],[55.7007280,12.6527990],[55.7008290,12.6527730],[55.7009310,12.6527530],[55.7010290,12.6527340],[55.7011310,12.6527120],[55.7012320,12.6526900],[55.7013310,12.6526740],[55.7014330,12.6526620],[55.7015340,12.6526500],[55.7016330,12.6526380],[55.7017350,12.6526250],[55.7018360,12.6526130],[55.7019380,12.6526080],[55.7020390,12.6526010],[55.7021400,12.6525770],[55.7022390,12.6525300],[55.7023360,12.6524780],[55.7024320,12.6524470],[55.7025310,12.6524290],[55.7026300,12.6524160],[55.7027030,12.6524060],[55.7028000,12.6524070],[55.7028960,12.6524150],[55.7029930,12.6524340],[55.7030890,12.6524510],[55.7031850,12.6524750],[55.7032790,12.6525010],[55.7033730,12.6525260],[55.7034670,12.6525510],[55.7035630,12.6525810],[55.7036570,12.6526170],[55.7037510,12.6526540],[55.7038450,12.6526850],[55.7039390,12.6527150],[55.7040320,12.6527550],[55.7041290,12.6527950],[55.7042230,12.6528320],[55.7043190,12.6528700],[55.7043900,12.6528960],[55.7044860,12.6529100],[55.7045830,12.6529170],[55.7046820,12.6529220],[55.7047550,12.6529150],[55.7048520,12.6529010],[55.7049480,12.6528810],[55.7050440,12.6528550],[55.7051410,12.6528320],[55.7052350,12.6528020],[55.7053280,12.6527670],[55.7053990,12.6527410],[55.7054960,12.6527050],[55.7055920,12.6526630],[55.7056890,12.6526240],[55.7057820,12.6525800],[55.7058760,12.6525390],[55.7059700,12.6524960],[55.7060640,12.6524560],[55.7061580,12.6524200],[55.7062540,12.6523890],[55.7063250,12.6523670],[55.7064220,12.6523370],[55.7065150,12.6523040],[55.7066120,12.6522750],[55.7066850,12.6522550],[55.7067560,12.6522340],[55.7068550,12.6522110],[55.7069260,12.6521940],[55.7069770,12.6521820],[55.7070250,12.6521670],[55.7070990,12.6521460],[55.7071700,12.6521260],[55.7072430,12.6521100],[55.7073170,12.6520940],[55.7073900,12.6520730],[55.7074660,12.6520510],[55.7075650,12.6520230],[55.7076640,12.6519990],[55.7077630,12.6519730],[55.7078620,12.6519460],[55.7079610,12.6519210],[55.7080120,12.6519100],[55.7080880,12.6518910],[55.7081870,12.6518630],[55.7082850,12.6518280],[55.7083840,12.6517880],[55.7084810,12.6517470],[55.7085800,12.6517130],[55.7086530,12.6516890],[55.7087290,12.6516660],[55.7087770,12.6516530],[55.7088280,12.6516400],[55.7089020,12.6516190],[55.7089520,12.6516070],[55.7090260,12.6515840],[55.7091020,12.6515630],[55.7091760,12.6515350],[55.7092740,12.6514980],[55.7093710,12.6514610],[55.7094700,12.6514240],[55.7095690,12.6513840],[55.7096620,12.6513440],[55.7097610,12.6513010],[55.7098580,12.6512620],[55.7099520,12.6512210],[55.7100250,12.6511870],[55.7101190,12.6511430],[55.7102150,12.6511000],[55.7103120,12.6510600],[55.7103850,12.6510310],[55.7104560,12.6509990],[55.7105530,12.6509590],[55.7106490,12.6509170],[55.7107450,12.6508770],[55.7108420,12.6508390],[55.7109130,12.6508070],[55.7110060,12.6507650],[55.7111030,12.6507230],[55.7111510,12.6507030],[55.7112470,12.6506660],[55.7113180,12.6506340],[55.7114150,12.6505920],[55.7115110,12.6505470],[55.7115590,12.6505220],[55.7116070,12.6504940],[55.7117010,12.6504350],[55.7117720,12.6503920],[55.7118690,12.6503410],[55.7119650,12.6502870],[55.7120590,12.6502320],[55.7121300,12.6501930],[55.7122260,12.6501410],[55.7123220,12.6500880],[55.7124190,12.6500360],[55.7125180,12.6499930],[55.7125910,12.6499630],[55.7126880,12.6499250],[55.7127840,12.6498790],[55.7128800,12.6498330],[55.7129770,12.6497840],[55.7130500,12.6497470],[55.7131440,12.6496910],[55.7132380,12.6496320],[55.7133320,12.6495700],[55.7134230,12.6495050],[55.7134940,12.6494570],[55.7135850,12.6493860],[55.7136760,12.6493140],[55.7137680,12.6492380],[55.7138110,12.6491980],[55.7139020,12.6491190],[55.7139910,12.6490410],[55.7140800,12.6489550],[55.7141660,12.6488670],[55.7142550,12.6487900],[55.7143480,12.6487280],[55.7144420,12.6486570],[55.7145330,12.6485840],[55.7146200,12.6484990],[55.7147010,12.6483990],[55.7147590,12.6483160],[55.7148300,12.6481940],[55.7148990,12.6480690],[55.7149590,12.6479330],[55.7150150,12.6477860],[55.7150610,12.6476320],[55.7151040,12.6474740],[55.7151450,12.6473110],[55.7151850,12.6471460],[55.7152030,12.6470640],[55.7152230,12.6469830],[55.7152540,12.6468640],[55.7153040,12.6467100],[55.7153580,12.6465580],[55.7154130,12.6464100],[55.7154560,12.6463010],[55.7155000,12.6461920],[55.7155530,12.6460420],[55.7156060,12.6458930],[55.7156640,12.6457480],[55.7157200,12.6456000],[55.7157710,12.6454490],[55.7158220,12.6452960],[55.7158520,12.6451840],[55.7158930,12.6450360],[55.7159200,12.6449570],[55.7159510,12.6448520],[55.7159890,12.6447300],[55.7160140,12.6446540],[55.7160550,12.6445420],[55.7161080,12.6444030],[55.7161230,12.6443630],[55.7161360,12.6443240],[55.7161490,12.6442860],[55.7161610,12.6442450],[55.7161740,12.6442080],[55.7162200,12.6440510],[55.7162650,12.6438940],[55.7163060,12.6437360],[55.7163490,12.6435770],[55.7163790,12.6434580],[55.7164000,12.6433790],[55.7164100,12.6433380],[55.7164200,12.6432980],[55.7164300,12.6432580],[55.7164380,12.6432170],[55.7164450,12.6431750],[55.7164530,12.6431340],[55.7164580,12.6430920],[55.7164660,12.6430500],[55.7164730,12.6430080],[55.7164810,12.6429660],[55.7164880,12.6429240],[55.7164930,12.6428820],[55.7165010,12.6428400],[55.7165090,12.6427980],[55.7165190,12.6427120],[55.7165310,12.6426270],[55.7165440,12.6425020],[55.7165440,12.6424150],[55.7165390,12.6423300],[55.7165310,12.6422470],[55.7165240,12.6421660],[55.7165090,12.6420400],[55.7164960,12.6419130],[55.7164730,12.6417520],[55.7164530,12.6415810],[55.7164250,12.6414170],[55.7164000,12.6412460],[55.7163790,12.6410700],[55.7163640,12.6409000],[55.7163620,12.6407330],[55.7163440,12.6406280],[55.7163390,12.6405870],[55.7163340,12.6405400],[55.7163310,12.6404930],[55.7163310,12.6404480],[55.7163290,12.6403990],[55.7163290,12.6403540],[55.7163290,12.6403120],[55.7163290,12.6402660],[55.7163310,12.6402200],[55.7163310,12.6401730],[55.7163310,12.6401260],[55.7163310,12.6400830],[55.7163290,12.6400390],[55.7163240,12.6399950],[55.7163210,12.6399530],[55.7163130,12.6398620],[55.7163060,12.6397260],[55.7163010,12.6395450],[55.7162910,12.6393620],[55.7162880,12.6391810],[55.7162800,12.6390510],[55.7162750,12.6389600],[55.7162750,12.6388220],[55.7162780,12.6386860],[55.7162780,12.6385490],[55.7162750,12.6383710],[55.7162750,12.6382430],[55.7162730,12.6381100],[55.7162700,12.6379770],[55.7162730,12.6378380],[55.7162680,12.6376990],[55.7162700,12.6375490],[55.7162700,12.6373650],[55.7162600,12.6371890],[55.7162580,12.6370610],[55.7162550,12.6369310],[55.7162550,12.6368040],[55.7162500,12.6366730],[55.7162450,12.6365400],[55.7162400,12.6363540],[55.7162370,12.6361740],[55.7162350,12.6360850],[55.7162350,12.6359500],[55.7162320,12.6358610],[55.7162320,12.6357750],[55.7162320,12.6356900],[55.7162270,12.6355990],[55.7162200,12.6354680],[55.7162120,12.6353390],[55.7161990,12.6352100],[55.7161840,12.6350770],[55.7161690,12.6349020],[55.7161540,12.6347270],[55.7161510,12.6345450],[55.7161510,12.6344110],[55.7161460,12.6342710],[55.7161490,12.6341310],[55.7161490,12.6339940],[55.7161540,12.6338150],[55.7161490,12.6336410],[55.7161280,12.6335130],[55.7160880,12.6333470],[55.7160470,12.6331760],[55.7159960,12.6330020],[55.7159530,12.6328470],[55.7159050,12.6327000],[55.7158930,12.6326640],[55.7158650,12.6325940],[55.7158270,12.6324760],[55.7158040,12.6323960],[55.7157780,12.6323180],[55.7157560,12.6322380],[55.7157230,12.6321150],[55.7156870,12.6319470],[55.7156570,12.6317810],[55.7156340,12.6316540],[55.7156110,12.6315200],[55.7155880,12.6313970],[55.7155650,12.6312720],[55.7155380,12.6311460],[55.7155070,12.6310250],[55.7154740,12.6309050],[55.7154390,12.6307810],[55.7153930,12.6306240],[55.7153450,12.6304800],[55.7152890,12.6303280],[55.7152360,12.6301730],[55.7151780,12.6300220],[55.7151390,12.6299070],[55.7151240,12.6298680],[55.7151120,12.6298310],[55.7150840,12.6297570],[55.7150480,12.6296390],[55.7150050,12.6295260],[55.7149620,12.6294200],[55.7149140,12.6293070],[55.7148610,12.6291500],[55.7148380,12.6290700],[55.7148100,12.6289360],[55.7147920,12.6288840],[55.7147740,12.6288440],[55.7147340,12.6286880],[55.7146810,12.6285140],[55.7146350,12.6283480],[55.7146040,12.6282200],[55.7145610,12.6280520],[55.7145180,12.6278840],[55.7144600,12.6277360],[55.7143840,12.6276240],[55.7142980,12.6275260],[55.7142340,12.6274520],[55.7141710,12.6273790],[55.7141050,12.6273090],[55.7140370,12.6272390],[55.7139730,12.6271630],[55.7138870,12.6270600],[55.7137980,12.6269560],[55.7137150,12.6268470],[55.7136360,12.6267280],[55.7135830,12.6266220],[55.7135670,12.6265850],[55.7135520,12.6265480],[55.7135170,12.6264280],[55.7134890,12.6263030],[55.7134630,12.6261320],[55.7134410,12.6259590],[55.7134330,12.6258720],[55.7134180,12.6257020],[55.7134030,12.6255230],[55.7133920,12.6253470],[55.7133820,12.6252140],[55.7133750,12.6250380],[55.7133720,12.6249500],[55.7133700,12.6249080],[55.7133670,12.6248250],[55.7133650,12.6247070],[55.7133650,12.6246700],[55.7133600,12.6245960],[55.7133540,12.6245240],[55.7133520,12.6244890],[55.7133490,12.6244540],[55.7133420,12.6243860],[55.7133340,12.6242890],[55.7133270,12.6242270],[55.7133110,12.6241060],[55.7132940,12.6239780],[55.7132730,12.6238320],[55.7132630,12.6237080],[55.7132500,12.6235360],[55.7132400,12.6233990],[55.7132350,12.6233060],[55.7132280,12.6232120],[55.7132150,12.6230710],[55.7132020,12.6229290],[55.7131920,12.6228350],[55.7131770,12.6226910],[55.7131570,12.6225490],[55.7131390,12.6224560],[55.7131290,12.6224090],[55.7131110,12.6223180],[55.7131010,12.6222720],[55.7130780,12.6221830],[55.7130530,12.6221010],[55.7130250,12.6220160],[55.7129820,12.6218930],[55.7129390,12.6217690],[55.7128980,12.6216450],[55.7128700,12.6215600],[55.7128300,12.6214320],[55.7128020,12.6213500],[55.7127590,12.6212290],[55.7127330,12.6211480],[55.7127050,12.6210700],[55.7126750,12.6209910],[55.7126320,12.6208770],[55.7126170,12.6208380],[55.7125580,12.6206860],[55.7125300,12.6206110],[55.7124850,12.6204980],[55.7124570,12.6204240],[55.7124420,12.6203880],[55.7124110,12.6203140],[55.7123990,12.6202780],[55.7123530,12.6201670],[55.7122970,12.6200180],[55.7122840,12.6199790],[55.7122260,12.6198310],[55.7122110,12.6197930],[55.7121550,12.6196440],[55.7121090,12.6195310],[55.7120660,12.6194180],[55.7120360,12.6193430],[55.7119750,12.6191930],[55.7119320,12.6190810],[55.7118710,12.6189310],[55.7118560,12.6188940],[55.7117920,12.6187450],[55.7117440,12.6186340],[55.7116960,12.6185270],[55.7116530,12.6184160],[55.7116070,12.6183060],[55.7115620,12.6181950],[55.7115310,12.6181210],[55.7114700,12.6179730],[55.7114550,12.6179360],[55.7114100,12.6178240],[55.7113640,12.6177110],[55.7113160,12.6175990],[55.7112550,12.6174510],[55.7112240,12.6173770],[55.7111640,12.6172270],[55.7111180,12.6171170],[55.7110720,12.6170060],[55.7110270,12.6168960],[55.7109840,12.6167820],[55.7109560,12.6167060],[55.7109400,12.6166690],[55.7109250,12.6166320],[55.7109100,12.6165960],[55.7108520,12.6164470],[55.7108210,12.6163710],[55.7107930,12.6162940],[55.7107500,12.6161780],[55.7107070,12.6160610],[55.7106670,12.6159430],[55.7106290,12.6158230],[55.7106010,12.6157450],[55.7105600,12.6156280],[55.7105220,12.6155110],[55.7104790,12.6153940],[55.7104510,12.6153160],[55.7104230,12.6152410],[55.7103800,12.6151280],[55.7103240,12.6149760],[55.7102940,12.6149020],[55.7102410,12.6147500],[55.7102130,12.6146750],[55.7101850,12.6146000],[55.7101700,12.6145630],[55.7101420,12.6144880],[55.7100880,12.6143380],[55.7100450,12.6142260],[55.7100050,12.6141160],[55.7099620,12.6140050],[55.7099060,12.6138580],[55.7098780,12.6137820],[55.7098200,12.6136330],[55.7097940,12.6135570],[55.7097660,12.6134820],[55.7097390,12.6134060],[55.7097110,12.6133320],[55.7096520,12.6131850],[55.7096090,12.6130760],[55.7095530,12.6129270],[55.7095100,12.6128150],[55.7094700,12.6127000],[55.7094140,12.6125460],[55.7093860,12.6124710],[55.7093580,12.6123970],[55.7093280,12.6123250],[55.7092800,12.6122180],[55.7092210,12.6120710],[55.7091650,12.6119210],[55.7091070,12.6117730],[55.7090640,12.6116600],[55.7090360,12.6115860],[55.7089800,12.6114320],[55.7089550,12.6113550],[55.7089300,12.6112790],[55.7089140,12.6112400],[55.7088740,12.6111260],[55.7088280,12.6110140],[55.7087620,12.6108690],[55.7086990,12.6107230],[55.7086660,12.6106510],[55.7086180,12.6105440],[55.7085670,12.6104380],[55.7084980,12.6102930],[55.7084660,12.6102210],[55.7084330,12.6101480],[55.7083820,12.6100410],[55.7083110,12.6099030],[55.7082400,12.6097720],[55.7081710,12.6096310],[55.7081210,12.6095310],[55.7080850,12.6094620],[55.7080170,12.6093230],[55.7079810,12.6092520],[55.7079460,12.6091830],[55.7079130,12.6091110],[55.7078950,12.6090780],[55.7078420,12.6089780],[55.7077660,12.6088490],[55.7077070,12.6087520],[55.7076490,12.6086570],[55.7075730,12.6085310],[55.7075300,12.6084690],[55.7074710,12.6083750],[55.7074330,12.6083150],[55.7073950,12.6082500],[55.7073570,12.6081850],[55.7073170,12.6081240],[55.7072990,12.6080920],[55.7072790,12.6080590],[55.7072610,12.6080270],[55.7072410,12.6079950],[55.7072050,12.6079290],[55.7071290,12.6078020],[55.7070680,12.6077070],[55.7070170,12.6076480],[55.7069870,12.6075430],[55.7069290,12.6074140],[55.7068780,12.6073630],[55.7068370,12.6072960],[55.7068200,12.6072640],[55.7067820,12.6071950],[55.7067610,12.6071600],[55.7067440,12.6071260],[55.7067030,12.6070590],[55.7066830,12.6070260],[55.7066450,12.6069600],[55.7066040,12.6068940],[55.7065640,12.6068300],[55.7065180,12.6067660],[55.7064770,12.6067100],[55.7064340,12.6066730],[55.7063890,12.6066180],[55.7064040,12.6067040],[55.7063530,12.6066830],[55.7062820,12.6066090],[55.7062490,12.6065750],[55.7061910,12.6064930],[55.7061270,12.6064510],[55.7060690,12.6064050],[55.7060180,12.6063460],[55.7059700,12.6062990],[55.7058890,12.6062530],[55.7057980,12.6062660],[55.7056910,12.6062250],[55.7056070,12.6062030],[55.7055030,12.6061900],[55.7054220,12.6061750],[55.7053440,12.6061590],[55.7052880,12.6061550],[55.7052600,12.6061530],[55.7051740,12.6061450],[55.7050900,12.6061380],[55.7050090,12.6061240],[55.7049300,12.6061070],[55.7048490,12.6060900],[55.7047680,12.6060700],[55.7046870,12.6060470],[55.7045830,12.6060240],[55.7045300,12.6060100],[55.7045040,12.6060020],[55.7044510,12.6059830],[55.7043440,12.6059620],[55.7042630,12.6059430],[55.7041850,12.6059260],[55.7041030,12.6059020],[55.7040000,12.6058700],[55.7038960,12.6058410],[55.7038400,12.6058250],[55.7037640,12.6058060],[55.7036850,12.6057870],[55.7036040,12.6057650],[55.7035780,12.6057570],[55.7035530,12.6057520],[55.7034750,12.6057330],[55.7033780,12.6057050],[55.7033020,12.6056870],[55.7031980,12.6056620],[55.7031730,12.6056580],[55.7031170,12.6056490],[55.7030610,12.6056400],[55.7030360,12.6056280],[55.7030100,12.6056150],[55.7029850,12.6056050],[55.7029600,12.6055940],[55.7029340,12.6055830],[55.7028840,12.6055680],[55.7028580,12.6055590],[55.7028300,12.6055530],[55.7027800,12.6055410],[55.7027010,12.6055260],[55.7025970,12.6054970],[55.7025460,12.6054770],[55.7024400,12.6054480],[55.7023610,12.6054190],[55.7023380,12.6054080],[55.7022620,12.6053720],[55.7021560,12.6053390],[55.7021280,12.6053310],[55.7021020,12.6053230],[55.7020030,12.6052800],[55.7019250,12.6052530],[55.7018280,12.6051990],[55.7017300,12.6051500],[55.7016510,12.6051110],[55.7016000,12.6050930],[55.7014960,12.6050570],[55.7013970,12.6050220],[55.7013010,12.6049890],[55.7012220,12.6049660],[55.7011230,12.6049240],[55.7010270,12.6048770],[55.7009740,12.6048590],[55.7009200,12.6048420],[55.7008980,12.6048370],[55.7007960,12.6048100],[55.7006950,12.6047760],[55.7005960,12.6047630],[55.7005420,12.6047490],[55.7004610,12.6047270],[55.7003800,12.6047080],[55.7003270,12.6046990],[55.7002200,12.6046730],[55.7001190,12.6046380],[55.7000680,12.6046200],[55.7000430,12.6046120],[55.6999360,12.6045810],[55.6998860,12.6045620],[55.6998070,12.6045360],[55.6997590,12.6045140],[55.6996850,12.6044830],[55.6996340,12.6044640],[55.6995810,12.6044470],[55.6994770,12.6044150],[55.6994240,12.6043910],[55.6993730,12.6043670],[55.6992720,12.6043340],[55.6992440,12.6043210],[55.6991980,12.6043020],[55.6991220,12.6042730],[55.6990460,12.6042450],[55.6989450,12.6042030],[55.6988940,12.6041880],[55.6988410,12.6041720],[55.6987640,12.6041410],[55.6986650,12.6041110],[55.6985870,12.6040840],[55.6985390,12.6040640],[55.6984630,12.6040420],[55.6983610,12.6040170],[55.6983360,12.6040090],[55.6982620,12.6039840],[55.6981860,12.6039720],[55.6981350,12.6039560],[55.6980870,12.6039420],[55.6979860,12.6039030],[55.6979370,12.6038830],[55.6978330,12.6038480],[55.6977600,12.6038160],[55.6976610,12.6037730],[55.6975870,12.6037430],[55.6975110,12.6037060],[55.6974350,12.6036640],[55.6973870,12.6036450],[55.6973590,12.6036350],[55.6973080,12.6036080],[55.6972860,12.6035960],[55.6972580,12.6035830],[55.6972300,12.6035710],[55.6972040,12.6035590],[55.6971790,12.6035450],[55.6971540,12.6035340],[55.6971280,12.6035240],[55.6971030,12.6035130],[55.6970780,12.6035020],[55.6970550,12.6034920],[55.6970290,12.6034840],[55.6970070,12.6034760],[55.6969560,12.6034590],[55.6969030,12.6034420],[55.6968520,12.6034250],[55.6968260,12.6034190],[55.6967730,12.6034030],[55.6967480,12.6033930],[55.6967200,12.6033840],[55.6966950,12.6033750],[55.6966160,12.6033490],[55.6965370,12.6033210],[55.6964610,12.6033000],[55.6964080,12.6032860],[55.6963090,12.6032510],[55.6962580,12.6032370],[55.6961570,12.6032040],[55.6961060,12.6031880],[55.6960270,12.6031570],[55.6959460,12.6031260],[55.6959230,12.6031170],[55.6958950,12.6031100],[55.6958190,12.6030870],[55.6957180,12.6030570],[55.6956900,12.6030510],[55.6956160,12.6030320],[55.6955630,12.6030190],[55.6955150,12.6030030],[55.6954390,12.6029800],[55.6953630,12.6029550],[55.6952590,12.6029180],[55.6952080,12.6029000],[55.6951070,12.6028620],[55.6950810,12.6028490],[55.6949800,12.6028160],[55.6948810,12.6027910],[55.6947840,12.6027590],[55.6947590,12.6027500],[55.6946830,12.6027260],[55.6946090,12.6027020],[55.6945560,12.6026900],[55.6945030,12.6026740],[55.6944770,12.6026660],[55.6944240,12.6026510],[55.6943730,12.6026350],[55.6943480,12.6026270],[55.6942470,12.6025980],[55.6941430,12.6025670],[55.6940410,12.6025350],[55.6939900,12.6025210],[55.6939420,12.6025080],[55.6938910,12.6024920],[55.6938380,12.6024770],[55.6937900,12.6024640],[55.6937650,12.6024590],[55.6936580,12.6024410],[55.6936070,12.6024260],[55.6935030,12.6023990],[55.6934470,12.6023830],[55.6933430,12.6023500],[55.6932900,12.6023320],[55.6932390,12.6023140],[55.6932140,12.6023070],[55.6931860,12.6023000],[55.6931610,12.6022960],[55.6931350,12.6022910],[55.6931100,12.6022830],[55.6930850,12.6022780],[55.6930590,12.6022720],[55.6930310,12.6022680],[55.6930060,12.6022620],[55.6929580,12.6022440],[55.6929320,12.6022330],[55.6929070,12.6022280],[55.6928820,12.6022200],[55.6928560,12.6022120],[55.6928340,12.6022050],[55.6928080,12.6021990],[55.6927350,12.6021780],[55.6926840,12.6021700],[55.6925850,12.6021370],[55.6925040,12.6021220],[55.6923950,12.6021080],[55.6923190,12.6020920],[55.6922140,12.6020720],[55.6921100,12.6020460],[55.6920120,12.6020120],[55.6919130,12.6019860],[55.6918190,12.6019590],[55.6917220,12.6019200],[55.6916870,12.6019040],[55.6916690,12.6019020],[55.6915800,12.6018740],[55.6915120,12.6018320],[55.6914100,12.6018120],[55.6913210,12.6017860],[55.6912330,12.6017530],[55.6911360,12.6017240],[55.6910860,12.6017040],[55.6910600,12.6016890],[55.6910140,12.6016620],[55.6909710,12.6016350],[55.6909490,12.6016210],[55.6908750,12.6015690],[55.6908520,12.6015540],[55.6907630,12.6014910],[55.6906750,12.6014380],[55.6906260,12.6014100],[55.6905810,12.6013740],[55.6905300,12.6013500],[55.6904360,12.6013080],[55.6904130,12.6012920],[55.6903240,12.6012390],[55.6902250,12.6011930],[55.6902030,12.6011810],[55.6901570,12.6011540],[55.6900580,12.6011060],[55.6899620,12.6010480],[55.6899130,12.6010210],[55.6898630,12.6009910],[55.6897660,12.6009350],[55.6897380,12.6009250],[55.6897130,12.6009120],[55.6896240,12.6008640],[55.6895990,12.6008490],[55.6895300,12.6008090],[55.6894640,12.6007630],[55.6894210,12.6007370],[55.6893250,12.6006930],[55.6892310,12.6006570],[55.6891290,12.6006060],[55.6890330,12.6005540],[55.6890100,12.6005420],[55.6889110,12.6004910],[55.6888600,12.6004710],[55.6887560,12.6004260],[55.6887080,12.6003950],[55.6886370,12.6003440],[55.6885690,12.6003090],[55.6884770,12.6002380],[55.6884040,12.6001860],[55.6883300,12.6001340],[55.6883050,12.6001170],[55.6882290,12.6000690],[55.6881600,12.6000220],[55.6880920,12.5999730],[55.6880690,12.5999580],[55.6880210,12.5999270],[55.6879470,12.5998790],[55.6879220,12.5998630],[55.6878510,12.5998090],[55.6877800,12.5997570],[55.6877540,12.5997400],[55.6877030,12.5997080],[55.6876530,12.5996740],[55.6876270,12.5996600],[55.6875540,12.5996170],[55.6874830,12.5995650],[55.6874140,12.5995000],[55.6873910,12.5994800],[55.6873690,12.5994640],[55.6872950,12.5994140],[55.6872720,12.5994000],[55.6871730,12.5993170],[55.6871200,12.5992820],[55.6870290,12.5992070],[55.6869600,12.5991550],[55.6869400,12.5991380],[55.6868430,12.5990740],[55.6868210,12.5990570],[55.6867470,12.5990010],[55.6866760,12.5989510],[55.6866330,12.5989200],[55.6865640,12.5988730],[55.6864910,12.5988230],[55.6864450,12.5987880],[55.6863740,12.5987340],[55.6862980,12.5986820],[55.6862720,12.5986670],[55.6861710,12.5986060],[55.6861000,12.5985600],[55.6860520,12.5985380],[55.6860030,12.5985200],[55.6859250,12.5984890],[55.6858210,12.5984680],[55.6857400,12.5984420],[55.6856890,12.5984350],[55.6856630,12.5984310],[55.6856150,12.5984190],[55.6855900,12.5984100],[55.6855670,12.5984020],[55.6855420,12.5983940],[55.6855160,12.5983840],[55.6854930,12.5983740],[55.6854680,12.5983650],[55.6854220,12.5983480],[55.6853720,12.5983330],[55.6853490,12.5983250],[55.6852980,12.5983070],[55.6852470,12.5982870],[55.6851690,12.5982510],[55.6851180,12.5982270],[55.6850470,12.5981950],[55.6849480,12.5981560],[55.6849230,12.5981460],[55.6848260,12.5981090],[55.6847220,12.5980810],[55.6846740,12.5980630],[55.6845720,12.5980300],[55.6844960,12.5980140],[55.6844480,12.5980040],[55.6843440,12.5979730],[55.6842960,12.5979660],[55.6841970,12.5979310],[55.6841740,12.5979260],[55.6841280,12.5979170],[55.6840520,12.5978900],[55.6839530,12.5978310],[55.6839050,12.5978100],[55.6838310,12.5977810],[55.6837350,12.5977480],[55.6836660,12.5977190],[55.6835900,12.5977010],[55.6835650,12.5976940],[55.6835170,12.5976820],[55.6834910,12.5976740],[55.6834460,12.5976520],[55.6834000,12.5976330],[55.6833570,12.5976150],[55.6833110,12.5976020],[55.6832860,12.5975970],[55.6832380,12.5975900],[55.6831870,12.5975820],[55.6831640,12.5975740],[55.6831160,12.5975520],[55.6830900,12.5975380],[55.6830680,12.5975270],[55.6830190,12.5975070],[55.6829710,12.5974830],[55.6829230,12.5974690],[55.6828750,12.5974530],[55.6828490,12.5974440],[55.6827990,12.5974230],[55.6827500,12.5973990],[55.6826590,12.5973470],[55.6826360,12.5973350],[55.6826130,12.5973250],[55.6825910,12.5973170],[55.6825420,12.5972900],[55.6824790,12.5972460],[55.6823880,12.5972070],[55.6823160,12.5971690],[55.6822250,12.5971220],[55.6821770,12.5971010],[55.6821080,12.5970690],[55.6820370,12.5970350],[55.6819640,12.5969990],[55.6819180,12.5969800],[55.6818170,12.5969360],[55.6817660,12.5969170],[55.6817400,12.5969040],[55.6817180,12.5968850],[55.6816720,12.5968500],[55.6816470,12.5968390],[55.6815960,12.5968150],[55.6815530,12.5967890],[55.6814840,12.5967510],[55.6814610,12.5967400],[55.6814380,12.5967280],[55.6813650,12.5966920],[55.6812630,12.5966490],[55.6812350,12.5966300],[55.6811360,12.5965710],[55.6810450,12.5965320],[55.6809510,12.5965000],[55.6808550,12.5964640],[55.6807860,12.5964390],[55.6807610,12.5964310],[55.6807410,12.5964230],[55.6806970,12.5963970],[55.6806240,12.5963640],[55.6805980,12.5963560],[55.6805150,12.5963290],[55.6804360,12.5963010],[55.6803350,12.5962760],[55.6802250,12.5962350],[55.6801750,12.5962150],[55.6801260,12.5961980],[55.6800990,12.5961860],[55.6800170,12.5961560],[55.6799690,12.5961340],[55.6799230,12.5961050],[55.6798220,12.5960550],[55.6797970,12.5960410],[55.6797710,12.5960280],[55.6796980,12.5959800],[55.6796520,12.5959480],[55.6795810,12.5959180],[55.6795100,12.5959170],[55.6794410,12.5959130],[55.6794210,12.5959110],[55.6793170,12.5959060],[55.6792410,12.5958970],[55.6792230,12.5958990],[55.6791870,12.5959080],[55.6791520,12.5959160],[55.6791370,12.5959240],[55.6791010,12.5959420],[55.6790680,12.5959580],[55.6790250,12.5959850],[55.6789640,12.5960650],[55.6789490,12.5960840],[55.6789340,12.5961020],[55.6789030,12.5961360],[55.6788420,12.5962390],[55.6788190,12.5962840],[55.6788090,12.5963090],[55.6787840,12.5963570],[55.6787610,12.5964130],[55.6787330,12.5964730],[55.6787210,12.5965030],[55.6787080,12.5965360],[55.6786800,12.5965920],[55.6786490,12.5966720],[55.6785990,12.5967980],[55.6785890,12.5968310],[55.6785480,12.5969270],[55.6785020,12.5970220],[55.6784620,12.5971100],[55.6784060,12.5972070],[55.6783600,12.5972740],[55.6783270,12.5973420],[55.6782940,12.5974120],[55.6782710,12.5974470],[55.6782180,12.5975160],[55.6781850,12.5975570],[55.6781770,12.5975780],[55.6781700,12.5975970],[55.6781620,12.5976130],[55.6781550,12.5976290],[55.6781490,12.5976450],[55.6781420,12.5976580],[55.6781370,12.5976750],[55.6781270,12.5977010],[55.6781220,12.5977130],[55.6781140,12.5977360],[55.6780960,12.5977800],[55.6780730,12.5978260],[55.6780710,12.5978300],[55.6780610,12.5978390],[55.6780580,12.5978380],[55.6780580,12.5978400],[55.6780560,12.5978410],[55.6780560,12.5978440],[55.6780560,12.5978430],[55.6780560,12.5978440],[55.6780560,12.5978440],[55.6780560,12.5978450],[55.6780560,12.5978450],[55.6780560,12.5978450],[55.6780560,12.5978450],[55.6780560,12.5978450],[55.6780560,12.5978450],[55.6780560,12.5978460],[55.6780560,12.5978460],[55.6780560,12.5978460],[55.6780560,12.5978470],[55.6780510,12.5978740],[55.6780480,12.5978750],[55.6780450,12.5978760],[55.6780450,12.5978760],[55.6780450,12.5978760],[55.6780450,12.5978770],[55.6780480,12.5978760],[55.6780450,12.5978830],[55.6780380,12.5978900],[55.6780350,12.5978950],[55.6780350,12.5978950],[55.6780330,12.5978930],[55.6780330,12.5978940],[55.6780330,12.5978940],[55.6780330,12.5978940],[55.6780330,12.5978940],[55.6780330,12.5978940],[55.6780330,12.5978940],[55.6780330,12.5978940],[55.6780330,12.5978940],[55.6780330,12.5978940],[55.6780330,12.5978940],[55.6780330,12.5978940],[55.6780350,12.5978930],[55.6780350,12.5978950],[55.6780050,12.5979200],[55.6779920,12.5979450],[55.6779570,12.5980420],[55.6779540,12.5980540],[55.6779520,12.5980560],[55.6779520,12.5980540],[55.6779520,12.5980480],[55.6779520,12.5980450],[55.6779520,12.5980450],[55.6779520,12.5980460],[55.6779520,12.5980460],[55.6779520,12.5980450],[55.6779490,12.5980450],[55.6779490,12.5980450],[55.6779520,12.5980260],[55.6779570,12.5980080],[55.6779620,12.5979900],[55.6779640,12.5979770],[55.6779670,12.5979620],[55.6780100,12.5978710],[55.6780100,12.5978760],[55.6780180,12.5978220],[55.6780330,12.5977750],[55.6780510,12.5977300],[55.6780610,12.5976900],[55.6780680,12.5976570],[55.6780730,12.5976400],[55.6780760,12.5976270],[55.6780630,12.5976190],[55.6780580,12.5976420],[55.6780630,12.5976630],[55.6780660,12.5976720],[55.6780680,12.5976740],[55.6780680,12.5976750],[55.6780680,12.5976750],[55.6780710,12.5976750],[55.6780710,12.5976770],[55.6780710,12.5976790],[55.6780710,12.5976790],[55.6780710,12.5976790],[55.6780680,12.5976790],[55.6780680,12.5976790],[55.6780680,12.5976790],[55.6780610,12.5977160],[55.6780630,12.5977090],[55.6780630,12.5977070],[55.6780610,12.5977080],[55.6780560,12.5977170],[55.6780510,12.5977310],[55.6780380,12.5977480],[55.6780330,12.5977540],[55.6780250,12.5977670],[55.6780100,12.5978050],[55.6780070,12.5978110],[55.6780070,12.5978140],[55.6780070,12.5978140],[55.6780070,12.5978140],[55.6780070,12.5978140],[55.6780100,12.5978140],[55.6780100,12.5978160],[55.6780100,12.5978140],[55.6780100,12.5978140],[55.6780100,12.5978160],[55.6780100,12.5978160],[55.6780100,12.5978160],[55.6780100,12.5978160],[55.6780100,12.5978160],[55.6780100,12.5978160],[55.6780100,12.5978160],[55.6780100,12.5978160],[55.6780100,12.5978160],[55.6780100,12.5978160],[55.6780100,12.5978160],[55.6780100,12.5978140],[55.6780100,12.5978160],[55.6780100,12.5978160],[55.6780100,12.5978160],[55.6780120,12.5978080],[55.6780070,12.5978350],[55.6779950,12.5978530],[55.6779920,12.5978630],[55.6779870,12.5979000],[55.6779850,12.5979120],[55.6779850,12.5979270],[55.6779820,12.5979440],[55.6779770,12.5979670],[55.6779720,12.5979870],[55.6779570,12.5980110],[55.6779520,12.5980260],[55.6779460,12.5980380],[55.6779210,12.5980960],[55.6779110,12.5981130],[55.6778960,12.5981470],[55.6778880,12.5981630],[55.6778750,12.5981580],[55.6778780,12.5981580],[55.6778780,12.5981590],[55.6778800,12.5981550],[55.6778800,12.5981540],[55.6778800,12.5981500],[55.6778800,12.5981500],[55.6778800,12.5981490],[55.6778800,12.5981480],[55.6778800,12.5981460],[55.6778800,12.5981460],[55.6778800,12.5981480],[55.6778800,12.5981470],[55.6778800,12.5981470],[55.6778800,12.5981470],[55.6778800,12.5981460],[55.6778830,12.5981420],[55.6778830,12.5981420],[55.6778830,12.5981390],[55.6778830,12.5981430],[55.6778780,12.5981490],[55.6778730,12.5981540],[55.6778450,12.5981730],[55.6778120,12.5981950],[55.6777640,12.5982150],[55.6777640,12.5982160],[55.6777640,12.5982240],[55.6777690,12.5982290],[55.6777710,12.5982290],[55.6777710,12.5982310],[55.6777740,12.5982300],[55.6777740,12.5982320],[55.6777790,12.5982380],[55.6777610,12.5983250],[55.6777640,12.5983510],[55.6777610,12.5984100],[55.6776930,12.5984310],[55.6776880,12.5984620],[55.6776850,12.5985180],[55.6776770,12.5986350],[55.6776650,12.5987230],[55.6776650,12.5987450],[55.6776520,12.5988880],[55.6776190,12.5990080],[55.6776190,12.5990070],[55.6775890,12.5990170],[55.6775890,12.5990170],[55.6775710,12.5990210],[55.6775610,12.5990240],[55.6775480,12.5990290],[55.6774820,12.5990520],[55.6774310,12.5990590],[55.6773800,12.5990350],[55.6773420,12.5989550],[55.6773200,12.5988500],[55.6773120,12.5988000],[55.6773040,12.5987640],[55.6773020,12.5987620],[55.6772990,12.5987430],[55.6773150,12.5987090],[55.6773120,12.5987140],[55.6773150,12.5987120],[55.6773450,12.5988270],[55.6773800,12.5988800],[55.6774160,12.5989750],[55.6774190,12.5989810],[55.6774260,12.5990050],[55.6774520,12.5990620],[55.6774950,12.5990430],[55.6775430,12.5990000],[55.6775840,12.5989370],[55.6775910,12.5989240],[55.6776220,12.5989250],[55.6776720,12.5988490],[55.6776850,12.5989020],[55.6777180,12.5989840],[55.6777100,12.5989960],[55.6777100,12.5989960],[55.6777130,12.5989970],[55.6777100,12.5989960],[55.6777100,12.5989960],[55.6777130,12.5989970],[55.6777130,12.5989960],[55.6777130,12.5989960],[55.6777130,12.5989960],[55.6777130,12.5989960],[55.6777100,12.5990050],[55.6776900,12.5990370],[55.6776650,12.5991080],[55.6776930,12.5991970],[55.6777210,12.5992170],[55.6777560,12.5992370],[55.6777610,12.5992400],[55.6777710,12.5992510],[55.6777920,12.5992700],[55.6778220,12.5993160],[55.6778530,12.5993830],[55.6778980,12.5993890],[55.6779390,12.5993800],[55.6779520,12.5993180],[55.6779540,12.5992950],[55.6779770,12.5992630],[55.6779950,12.5992280],[55.6780000,12.5992100],[55.6779920,12.5991200],[55.6779920,12.5991260],[55.6779950,12.5991330],[55.6779970,12.5991330],[55.6779970,12.5991320],[55.6779950,12.5991340],[55.6779970,12.5991360],[55.6779950,12.5991390],[55.6779920,12.5991510],[55.6779850,12.5991750],[55.6779740,12.5992070],[55.6779640,12.5992340],[55.6779570,12.5992570],[55.6779440,12.5992790],[55.6779190,12.5993500],[55.6778800,12.5994070],[55.6778650,12.5994120],[55.6778350,12.5993850],[55.6777990,12.5993020],[55.6777760,12.5992660],[55.6777660,12.5992470],[55.6777560,12.5992290],[55.6777460,12.5992110],[55.6777360,12.5991940],[55.6777230,12.5991820],[55.6777000,12.5991480],[55.6776930,12.5991250],[55.6776750,12.5990790],[55.6776620,12.5990300],[55.6776600,12.5990250],[55.6776670,12.5990090],[55.6776650,12.5989240],[55.6776620,12.5988880],[55.6776650,12.5988620],[55.6776670,12.5988350],[55.6776720,12.5987570],[55.6776770,12.5987050],[55.6776830,12.5986530],[55.6776850,12.5986020],[55.6776930,12.5985580],[55.6776980,12.5985350],[55.6777030,12.5984860],[55.6777100,12.5984380],[55.6777210,12.5983650],[55.6777230,12.5983410],[55.6777260,12.5983160],[55.6777310,12.5982910],[55.6777540,12.5982610],[55.6777790,12.5982420],[55.6778220,12.5982160],[55.6778470,12.5981920],[55.6778780,12.5981450],[55.6778910,12.5981310],[55.6779130,12.5980990],[55.6779340,12.5980590],[55.6779540,12.5980120],[55.6779620,12.5979970],[55.6779950,12.5979240],[55.6780180,12.5978660],[55.6780200,12.5978740],[55.6780100,12.5978780],[55.6780150,12.5978670],[55.6780150,12.5978660],[55.6780150,12.5978650],[55.6780150,12.5978640],[55.6780150,12.5978630],[55.6780150,12.5978590],[55.6780180,12.5978620],[55.6780180,12.5978640],[55.6780180,12.5978640],[55.6780180,12.5978640],[55.6780150,12.5978690],[55.6780150,12.5978690],[55.6780150,12.5978690],[55.6780150,12.5978690],[55.6780180,12.5978690],[55.6780180,12.5978720],[55.6780180,12.5978720],[55.6780180,12.5978720],[55.6780180,12.5978680],[55.6780180,12.5978680],[55.6780180,12.5978680],[55.6780180,12.5978680],[55.6780180,12.5978680],[55.6780280,12.5978470],[55.6780280,12.5978470],[55.6780280,12.5978470],[55.6780280,12.5978470],[55.6780300,12.5978490],[55.6780300,12.5978450],[55.6780300,12.5978450],[55.6780330,12.5978450],[55.6780330,12.5978450],[55.6780330,12.5978450],[55.6780330,12.5978450],[55.6780280,12.5978320],[55.6780300,12.5978350],[55.6780200,12.5978300],[55.6780180,12.5978280],[55.6780180,12.5978280],[55.6780180,12.5978280],[55.6780180,12.5978280],[55.6780180,12.5978270],[55.6780180,12.5978270],[55.6780200,12.5978360],[55.6780180,12.5978310],[55.6780180,12.5978300],[55.6780180,12.5978300],[55.6780180,12.5978350],[55.6780200,12.5978470],[55.6780180,12.5978490],[55.6780180,12.5978490],[55.6780180,12.5978640],[55.6780180,12.5978650],[55.6780150,12.5978660],[55.6780020,12.5978460],[55.6780050,12.5978470],[55.6780070,12.5978480],[55.6780070,12.5978470],[55.6780070,12.5978440],[55.6780100,12.5978460],[55.6780120,12.5978480],[55.6780120,12.5978530],[55.6780120,12.5978600],[55.6780120,12.5978630],[55.6780150,12.5978640],[55.6780150,12.5978690],[55.6780150,12.5978690],[55.6780120,12.5978690],[55.6780180,12.5978720],[55.6780200,12.5978650],[55.6780180,12.5978660],[55.6780180,12.5978670],[55.6780180,12.5978670],[55.6780200,12.5978670],[55.6780180,12.5978670],[55.6780200,12.5978670],[55.6780200,12.5978670],[55.6780200,12.5978670],[55.6780200,12.5978670],[55.6780200,12.5978670],[55.6780200,12.5978780],[55.6780200,12.5978810],[55.6780200,12.5978810],[55.6780200,12.5978810],[55.6780120,12.5978750],[55.6780100,12.5978760],[55.6780120,12.5978770],[55.6780120,12.5978770],[55.6780120,12.5978770],[55.6780120,12.5978770],[55.6780120,12.5978770],[55.6780120,12.5978770],[55.6780120,12.5978770],[55.6780120,12.5978780],[55.6780120,12.5978780],[55.6780120,12.5978780],[55.6780120,12.5978770],[55.6780120,12.5978770],[55.6780120,12.5978780],[55.6780120,12.5978780],[55.6780120,12.5978780],[55.6780120,12.5978780],[55.6780100,12.5978830],[55.6780100,12.5978860],[55.6780100,12.5978860],[55.6780100,12.5978860],[55.6780120,12.5978870],[55.6780120,12.5978890],[55.6780120,12.5978890],[55.6780120,12.5978890],[55.6780120,12.5978890],[55.6780120,12.5978890],[55.6780120,12.5978840],[55.6780100,12.5978770],[55.6780070,12.5978680],[55.6780050,12.5978670],[55.6780020,12.5978570],[55.6780000,12.5978470],[55.6780020,12.5978660],[55.6779900,12.5978890],[55.6779640,12.5978580],[55.6779390,12.5979020],[55.6779520,12.5979510],[55.6779620,12.5979710],[55.6779640,12.5979740],[55.6779820,12.5979990],[55.6779790,12.5980020],[55.6779790,12.5980030],[55.6779790,12.5980040],[55.6779790,12.5980060],[55.6779770,12.5980060],[55.6779770,12.5980080],[55.6779740,12.5980090],[55.6779770,12.5980120],[55.6779770,12.5980120],[55.6779790,12.5980110],[55.6779820,12.5980120],[55.6779820,12.5980120],[55.6779850,12.5980130],[55.6779820,12.5980130],[55.6779790,12.5980120],[55.6779790,12.5980120],[55.6779790,12.5980120],[55.6779820,12.5980130],[55.6779820,12.5980140],[55.6779790,12.5980130],[55.6779790,12.5980130],[55.6779790,12.5980140],[55.6779790,12.5980050],[55.6779820,12.5980050],[55.6779820,12.5980050],[55.6779850,12.5980050],[55.6779850,12.5980060],[55.6779870,12.5980060],[55.6779870,12.5980060],[55.6779870,12.5980060],[55.6779900,12.5980060],[55.6779900,12.5980060],[55.6779920,12.5980060],[55.6779920,12.5980060],[55.6779920,12.5980060],[55.6779970,12.5979710],[55.6780000,12.5979500],[55.6780180,12.5978940],[55.6780230,12.5978830],[55.6780610,12.5978370],[55.6780730,12.5977660],[55.6780710,12.5977580],[55.6780710,12.5977620],[55.6780710,12.5977630],[55.6780710,12.5977620],[55.6780710,12.5977620],[55.6780710,12.5977640],[55.6780710,12.5977640],[55.6780730,12.5977660],[55.6780660,12.5977640],[55.6780660,12.5977640],[55.6780660,12.5977640],[55.6780660,12.5977630],[55.6780660,12.5977630],[55.6780660,12.5977630],[55.6780680,12.5977630],[55.6780680,12.5977630],[55.6780680,12.5977630],[55.6780680,12.5977630],[55.6780680,12.5977630],[55.6780680,12.5977630],[55.6780710,12.5977620],[55.6780710,12.5977620],[55.6780710,12.5977620],[55.6780710,12.5977610],[55.6780710,12.5977640],[55.6780680,12.5977670],[55.6780630,12.5977680],[55.6780630,12.5977680],[55.6780630,12.5977680],[55.6780630,12.5977700],[55.6780510,12.5977790],[55.6780480,12.5977920],[55.6780480,12.5977950],[55.6780510,12.5977900],[55.6780510,12.5977900],[55.6780510,12.5977900],[55.6780510,12.5977900],[55.6780510,12.5977900],[55.6780510,12.5977900],[55.6780530,12.5977900],[55.6780530,12.5977900],[55.6780530,12.5977900],[55.6780530,12.5977920],[55.6780560,12.5977920],[55.6780560,12.5977920],[55.6780530,12.5977950],[55.6780560,12.5978110],[55.6780560,12.5978110],[55.6780560,12.5978120],[55.6780560,12.5978130],[55.6780580,12.5978140],[55.6780580,12.5978160],[55.6780580,12.5978160],[55.6780580,12.5978180],[55.6780530,12.5978290],[55.6780530,12.5978300],[55.6780510,12.5978320],[55.6780510,12.5978340],[55.6780510,12.5978340],[55.6780510,12.5978340],[55.6780510,12.5978340],[55.6780510,12.5978350],[55.6780510,12.5978360],[55.6780530,12.5978360],[55.6780530,12.5978360],[55.6780530,12.5978360],[55.6780530,12.5978370],[55.6780560,12.5978450],[55.6780530,12.5978460],[55.6780530,12.5978460],[55.6780510,12.5978490],[55.6780480,12.5978500],[55.6780480,12.5978500],[55.6780450,12.5978460],[55.6780430,12.5978390],[55.6780430,12.5978390],[55.6780430,12.5978390],[55.6780400,12.5978450],[55.6780430,12.5978510],[55.6780430,12.5978510],[55.6780430,12.5978500],[55.6780430,12.5978500],[55.6780430,12.5978500],[55.6780450,12.5978500],[55.6780450,12.5978500],[55.6780450,12.5978500],[55.6780450,12.5978510],[55.6780450,12.5978510],[55.6780450,12.5978510],[55.6780480,12.5978540],[55.6780480,12.5978540],[55.6780480,12.5978540],[55.6780480,12.5978540],[55.6780480,12.5978540],[55.6780480,12.5978550],[55.6780480,12.5978550],[55.6780480,12.5978550],[55.6780510,12.5978550],[55.6780510,12.5978560],[55.6780510,12.5978560],[55.6780510,12.5978560],[55.6780510,12.5978560],[55.6780510,12.5978560],[55.6780510,12.5978570],[55.6780530,12.5978570],[55.6780530,12.5978570],[55.6780530,12.5978570],[55.6780530,12.5978570],[55.6780530,12.5978570],[55.6780530,12.5978570],[55.6780530,12.5978580],[55.6780530,12.5978580],[55.6780530,12.5978580],[55.6780530,12.5978580],[55.6780530,12.5978580],[55.6780560,12.5978590],[55.6780560,12.5978590],[55.6780560,12.5978590],[55.6780580,12.5978600],[55.6780580,12.5978620],[55.6780580,12.5978620],[55.6780580,12.5978630],[55.6780580,12.5978630],[55.6780580,12.5978630],[55.6780610,12.5978630],[55.6780610,12.5978640],[55.6780610,12.5978640],[55.6780610,12.5978640],[55.6780610,12.5978640],[55.6780630,12.5978660],[55.6780630,12.5978670],[55.6780630,12.5978680],[55.6780630,12.5978680],[55.6780660,12.5978690],[55.6780660,12.5978690],[55.6780660,12.5978710],[55.6780660,12.5978710],[55.6780660,12.5978720],[55.6780680,12.5978720],[55.6780680,12.5978730],[55.6780680,12.5978730],[55.6780680,12.5978730],[55.6780680,12.5978740],[55.6780680,12.5978740],[55.6780680,12.5978740],[55.6780680,12.5978740],[55.6780680,12.5978720],[55.6780630,12.5978690],[55.6780630,12.5978690],[55.6780630,12.5978710],[55.6780660,12.5978710],[55.6780660,12.5978710],[55.6780660,12.5978710],[55.6780660,12.5978710],[55.6780660,12.5978720],[55.6780660,12.5978720],[55.6780660,12.5978720],[55.6780660,12.5978730],[55.6780660,12.5978730],[55.6780660,12.5978730],[55.6780660,12.5978730],[55.6780660,12.5978740],[55.6780680,12.5978740],[55.6780680,12.5978740],[55.6780680,12.5978750],[55.6780680,12.5978750],[55.6780680,12.5978750],[55.6780630,12.5978830],[55.6780610,12.5978850],[55.6780610,12.5978850],[55.6780610,12.5978860],[55.6780610,12.5978860],[55.6780610,12.5978860],[55.6780630,12.5978860],[55.6780630,12.5978870],[55.6780630,12.5978870],[55.6780630,12.5978870],[55.6780630,12.5978890],[55.6780630,12.5978870],[55.6780630,12.5978870],[55.6780630,12.5978870],[55.6780630,12.5978870],[55.6780630,12.5978890],[55.6780630,12.5978890],[55.6780400,12.5979130],[55.6780450,12.5979280],[55.6780580,12.5979380],[55.6780630,12.5979420],[55.6780630,12.5979410],[55.6780610,12.5979350],[55.6780660,12.5979260],[55.6780680,12.5979240],[55.6780780,12.5979140],[55.6780840,12.5979000],[55.6780840,12.5978860],[55.6780840,12.5978830],[55.6780840,12.5978930],[55.6780840,12.5978940],[55.6780840,12.5978920],[55.6780860,12.5978900],[55.6780860,12.5978900],[55.6780860,12.5978890],[55.6780860,12.5978900],[55.6780890,12.5978870],[55.6780910,12.5978870],[55.6780910,12.5978840],[55.6780890,12.5978820],[55.6780860,12.5978810],[55.6780840,12.5978810],[55.6780840,12.5978810],[55.6780840,12.5978810],[55.6780810,12.5978850],[55.6780780,12.5978840],[55.6780760,12.5978820],[55.6780710,12.5978800],[55.6780680,12.5978800],[55.6780630,12.5978750],[55.6780630,12.5978740]],\r\n\t\t\t\t\tgraphDist          : [0.00,248.91,262.03,273.03,283.10,293.10,305.10,317.10,329.10,341.10,352.10,363.10,373.10,399.10,414.10,432.10,443.10,454.10,473.11,486.17,497.17,508.17,527.17,538.17,548.24,559.24,571.24,582.24,593.24,603.27,613.33,624.03,634.10,644.16,654.57,667.55,678.33,688.41,698.45,710.47,720.48,734.49,746.50,757.54,769.55,781.56,792.59,807.48,820.48,833.50,845.53,857.56,867.67,879.01,889.53,901.14,911.67,923.62,934.79,945.84,956.84,966.85,978.50,989.11,1003.33,1019.99,1030.09,1041.59,1052.72,1064.50,1076.03,1087.93,1099.94,1112.43,1125.33,1135.41,1147.17,1162.39,1175.01,1186.86,1198.94,1211.04,1223.25,1233.54,1246.99,1259.68,1272.63,1286.19,1297.46,1310.64,1322.92,1334.96,1351.27,1367.65,1377.97,1389.20,1404.96,1417.65,1433.78,1445.82,1457.82,1473.83,1484.79,1495.69,1506.13,1517.27,1529.43,1540.26,1550.91,1562.23,1573.31,1583.60,1596.21,1607.35,1617.60,1627.92,1645.85,1656.35,1667.99,1678.91,1693.35,1704.31,1717.39,1736.23,1755.18,1768.64,1781.43,1793.30,1805.61,1816.09,1826.86,1838.55,1852.44,1865.54,1875.89,1888.27,1898.34,1916.51,1929.34,1940.77,1952.56,1964.91,1976.00,1987.57,1998.73,2020.31,2033.19,2043.69,2057.87,2076.56,2087.97,2099.47,2111.18,2122.22,2135.64,2148.47,2158.92,2169.95,2180.14,2191.81,2207.42,2218.53,2229.91,2245.84,2258.19,2270.22,2281.77,2291.99,2302.82,2315.55,2328.28,2342.05,2352.58,2365.78,2379.74,2390.79,2401.30,2411.62,2422.56,2435.27,2450.17,2466.07,2479.84,2491.55,2502.12,2513.34,2524.42,2536.74,2555.36,2568.14,2579.99,2590.56,2603.08,2615.80,2636.64,2649.59,2663.01,2677.35,2688.98,2701.68,2713.61,2725.08,2738.71,2749.53,2761.15,2775.75,2786.17,2799.97,2810.68,2821.11,2831.63,2842.91,2854.19,2864.75,2875.27,2890.09,2901.96,2913.36,2923.68,2935.30,2949.50,2960.66,2978.24,2998.51,3015.23,3031.27,3047.32,3062.33,3072.65,3088.36,3099.36,3118.16,3128.23,3140.23,3152.23,3165.82,3183.82,3194.28,3204.32,3214.40,3229.41,3239.75,3250.41,3261.42,3273.42,3286.42,3296.61,3320.61,3340.67,3353.67,3364.67,3377.67,3390.67,3401.67,3412.67,3429.67,3443.67,3453.69,3464.69,3475.69,3492.69,3502.69,3522.69,3532.69,3546.71,3568.71,3585.71,3599.78,3609.84,3626.84,3636.85,3647.87,3664.87,3676.87,3689.87,3702.21,3715.21,3727.21,3738.21,3749.21,3760.21,3775.21,3788.21,3799.21,3809.21,3821.23,3833.23,3844.23,3857.23,3868.23,3884.23,3895.24,3907.24,3917.35,3929.74,3940.74,3954.74,3964.74,3975.76,3985.76,3995.80,4006.81,4016.81,4031.81,4043.89,4053.89,4064.89,4074.89,4085.89,4102.96,4112.96,4124.96,4135.96,4148.96,4161.96,4173.96,4185.96,4201.96,4216.96,4229.96,4243.96,4258.96,4272.96,4285.96,4298.96,4309.96,4319.96,4332.96,4344.96,4357.97,4368.97,4380.97,4391.97,4402.97,4415.97,4428.97,4439.97,4449.98,4460.98,4475.98,4485.98,4500.98,4510.98,4521.04,4532.04,4546.04,4557.26,4569.33,4581.33,4593.33,4604.33,4617.39,4630.39,4641.39,4654.45,4668.45,4681.45,4694.45,4705.45,4715.45,4726.45,4737.45,4753.45,4764.45,4775.46,4787.46,4797.46,4808.46,4820.46,4832.46,4845.46,4860.46,4872.46,4898.46,4914.46,4930.46,4943.46,4955.46,4970.46,4982.46,4994.46,5005.46,5016.46,5029.46,5040.46,5055.46,5069.46,5086.10,5096.14,5111.54,5125.88,5142.89,5154.99,5165.01,5192.01,5222.01,5253.02,5279.02,5298.02,5311.51,5324.63,5337.34,5348.34,5358.34,5371.34,5383.34,5406.34,5418.34,5438.34,5459.34,5475.34,5489.34,5501.34,5512.34,5524.34,5535.34,5554.34,5566.34,5583.34,5595.34,5607.35,5618.35,5628.37,5641.40,5652.54,5662.61,5675.73,5687.73,5700.79,5713.79,5728.86,5740.86,5751.99,5763.04,5779.20,5792.53,5808.71,5825.30,5839.33,5852.37,5862.44,5874.01,5887.13,5904.82,5915.69,5926.01,5936.78,5953.74,5977.30,5993.37,6011.39,6029.65,6040.73,6058.04,6072.97,6089.51,6099.72,6114.42,6127.43,6139.39,6162.73,6173.18,6185.51,6195.68,6209.57,6223.50,6241.17,6254.90,6265.84,6277.23,6287.49,6298.88,6315.16,6333.27,6344.60,6358.05,6370.16,6381.77,6393.24,6404.31,6415.86,6431.11,6444.44,6454.75,6468.18,6479.69,6495.31,6505.51,6517.31,6530.03,6542.32,6557.78,6571.84,6587.02,6597.34,6610.13,6621.95,6632.12,6645.40,6670.26,6683.67,6695.51,6708.59,6719.27,6731.17,6744.31,6755.92,6768.23,6779.82,6791.14,6803.66,6819.72,6834.24,6849.02,6861.95,6875.08,6887.96,6898.03,6913.63,6925.31,6938.92,6950.78,6965.95,6978.11,6990.93,7003.60,7016.27,7028.24,7040.66,7053.12,7068.52,7079.82,7091.83,7104.88,7115.58,7128.43,7139.89,7151.76,7163.69,7173.93,7187.21,7198.34,7213.77,7227.61,7239.94,7253.37,7270.63,7294.26,7315.67,7327.82,7340.02,7354.89,7369.58,7381.26,7391.53,7403.72,7418.98,7431.86,7442.98,7457.47,7470.13,7481.06,7500.01,7512.26,7524.09,7545.18,7555.61,7567.80,7578.73,7588.94,7603.08,7615.79,7626.07,7636.26,7648.57,7660.00,7675.60,7687.68,7697.78,7708.74,7724.09,7737.36,7749.34,7762.24,7774.55,7794.00,7806.75,7819.73,7831.65,7843.34,7857.31,7869.71,7880.39,7891.43,7901.78,7912.01,7922.01,7933.87,7946.01,7957.71,7969.03,7981.25,7992.00,8002.08,8017.52,8028.76,8040.68,8052.52,8064.42,8076.51,8086.57,8099.97,8113.99,8126.88,8141.31,8153.39,8165.39,8177.63,8188.75,8200.65,8214.17,8227.06,8239.88,8250.22,8261.80,8273.40,8288.46,8302.98,8315.41,8327.15,8339.55,8349.92,8363.41,8378.02,8388.91,8412.67,8444.82,8477.00,8509.18,8534.34,8569.45,8592.66,8605.91,8618.06,8630.36,8642.60,8655.32,8668.15,8680.06,8692.29,8705.18,8715.85,8732.03,8747.35,8759.75,8779.00,8795.30,8810.62,8824.96,8840.22,8861.17,8879.44,8892.73,8913.61,8936.55,8948.18,8962.53,8981.59,8994.88,9010.49,9021.16,9036.08,9048.46,9065.77,9079.05,9091.53,9103.74,9113.76,9126.09,9138.82,9150.57,9163.13,9174.15,9186.33,9199.57,9217.25,9229.39,9239.76,9251.47,9265.03,9275.79,9287.31,9300.37,9313.12,9325.35,9336.97,9351.43,9363.03,9375.09,9386.71,9396.75,9413.10,9425.69,9437.71,9449.73,9462.14,9474.14,9485.92,9496.32,9508.76,9533.31,9543.58,9554.85,9566.90,9578.63,9590.81,9602.58,9614.14,9626.65,9638.50,9650.72,9662.53,9674.83,9687.15,9698.98,9711.64,9722.98,9734.79,9746.30,9757.32,9768.97,9782.64,9794.86,9806.53,9818.12,9832.51,9846.87,9858.70,9872.84,9885.53,9896.89,9907.17,9919.79,9932.62,9943.56,9956.81,9971.98,9992.99,10015.17,10026.53,10037.36,10050.75,10061.73,10071.78,10085.19,10096.58,10109.24,10124.56,10156.00,10174.88,10186.46,10201.19,10230.38,10244.69,10261.45,10274.99,10292.85,10310.19,10322.54,10335.84,10347.02,10365.75,10377.64,10391.39,10402.47,10413.31,10423.54,10434.31,10449.58,10461.32,10478.46,10489.48,10502.14,10518.07,10533.42,10545.16,10564.89,10575.13,10588.16,10599.67,10614.46,10626.89,10640.17,10663.89,10677.17,10687.65,10702.97,10718.81,10733.88,10745.93,10755.96,10768.08,10778.96,10792.55,10803.69,10817.57,10833.62,10848.88,10864.09,10900.18,10910.59,10936.72,10949.04,10959.42,10977.35,10993.40,11004.46,11021.29,11031.82,11043.16,11055.56,11075.69,11093.56,11110.79,11121.85,11131.96,11151.10,11163.51,11174.30,11187.60,11197.84,11209.25,11225.13,11257.85,11271.28,11292.48,11310.73,11321.42,11337.37,11362.16,11387.32,11400.94,11412.68,11443.05,11453.38,11467.58,11510.84,11543.94,11555.21,11580.38,11608.90,11633.05,11661.17,11679.36,11711.45,11730.06,11741.50,11765.64,11788.32,11803.59,11815.18,11834.69,11874.73,11911.82,11922.37,11934.68,11953.82,11965.72,11987.13,11998.35,12012.63,12026.81,12040.07,12056.86,12073.74,12085.09,12097.36,12118.42,12134.66,12145.74,12159.65,12171.93,12183.26,12195.60,12208.64,12220.74,12231.22,12245.19,12256.37,12267.93,12280.28,12298.29,12314.52,12325.14,12337.44,12348.74,12360.39,12371.43,12382.64,12418.02,12439.96,12451.55,12463.68,12476.78,12498.96,12522.92,12533.88,12554.73,12568.05,12579.81,12594.05,12605.45,12624.37,12637.66,12650.25,12661.57,12672.19,12685.18,12708.99,12734.15,12759.20,12782.35,12792.99,12805.34,12821.36,12838.07,12848.95,12867.41,12882.67,12893.65,12937.74,12959.83,12978.30,12990.47,13001.85,13013.23,13033.12,13057.08,13067.46,13077.78,13097.00,13122.48,13139.52,13154.74,13167.79,13178.98,13223.30,13234.99,13283.06,13295.79,13322.74,13358.85,13376.77,13441.61,13452.86,13521.92,13532.56,13601.61,13615.89,13634.91,13651.02,13720.08,13731.59,13754.94,13845.33,13858.00,13878.57,13965.28,14046.32,14056.48,14069.01,14079.88,14091.91,14102.05,14112.46,14125.29,14141.41,14152.41,14165.68,14178.49,14189.50,14201.08,14212.94,14226.75,14237.21,14249.13,14261.51,14273.66,14285.55,14297.44,14312.01,14323.57,14335.20,14347.29,14357.97,14369.56,14381.73,14397.11,14408.35,14422.50,14433.87,14444.75,14455.58,14467.31,14485.34,14497.64,14509.05,14520.74,14532.37,14544.56,14556.09,14566.77,14578.67,14590.01,14601.57,14612.56,14622.94,14634.32,14645.14,14655.64,14668.06,14678.88,14689.36,14703.47,14714.54,14725.46,14736.40,14746.94,14757.33,14768.21,14780.39,14790.91,14802.44,14813.25,14824.26,14834.60,14845.13,14856.22,14867.02,14879.31,14900.08,14917.19,14933.37,14952.06,14962.33,14984.88,14998.14,15010.40,15021.79,15032.12,15047.97,15061.99,15072.26,15088.97,15106.68,15124.34,15142.08,15153.34,15163.73,15182.46,15199.30,15213.33,15223.70,15238.17,15248.89,15262.56,15276.73,15287.77,15301.65,15313.18,15324.35,15334.60,15349.91,15361.57,15372.70,15383.44,15394.81,15406.42,15417.78,15428.49,15440.47,15451.20,15461.73,15472.88,15483.84,15495.09,15505.36,15516.97,15528.61,15539.22,15550.63,15561.69,15572.69,15583.55,15594.27,15605.41,15616.11,15626.81,15637.69,15648.69,15660.31,15670.84,15681.92,15692.09,15702.59,15713.33,15725.86,15737.21,15748.58,15762.14,15772.67,15782.71,15795.56,15807.97,15820.00,15831.42,15842.79,15855.62,15867.23,15878.70,15890.34,15901.47,15912.70,15924.65,15935.80,15948.03,15959.54,15970.59,15981.20,15992.33,16003.74,16014.99,16026.35,16037.43,16048.51,16059.57,16069.87,16080.71,16091.04,16102.42,16114.20,16125.13,16135.84,16146.36,16157.33,16168.74,16179.64,16190.43,16202.04,16212.60,16223.42,16234.22,16245.79,16256.58,16268.30,16279.52,16291.18,16301.62,16312.71,16324.09,16335.59,16346.53,16358.53,16369.27,16380.89,16391.80,16403.06,16414.58,16426.96,16437.92,16449.25,16459.98,16470.94,16483.18,16494.49,16505.77,16518.27,16529.10,16539.80,16550.66,16563.49,16574.18,16584.75,16595.70,16608.11,16619.30,16630.51,16643.42,16654.87,16665.97,16677.29,16689.48,16700.36,16711.59,16723.87,16735.13,16746.94,16758.81,16769.48,16781.39,16793.27,16805.18,16816.06,16828.08,16839.19,16850.11,16862.35,16874.94,16886.11,16897.18,16908.80,16920.05,16931.61,16947.23,16959.77,16971.11,16986.38,16998.61,17010.25,17026.83,17036.96,17049.51,17068.46,17078.55,17096.40,17106.52,17117.54,17128.94,17140.35,17153.43,17163.56,17176.24,17189.27,17203.96,17216.44,17231.97,17248.97,17261.61,17280.84,17293.19,17303.66,17314.58,17325.41,17337.32,17349.42,17362.28,17374.67,17386.86,17399.74,17414.09,17425.30,17441.68,17452.47,17466.43,17479.20,17490.68,17505.57,17517.15,17527.32,17539.29,17556.01,17567.24,17577.38,17589.52,17600.89,17612.12,17623.62,17635.47,17647.65,17659.19,17674.91,17687.01,17699.33,17712.07,17723.52,17735.22,17746.25,17757.46,17769.54,17782.32,17793.42,17804.96,17815.54,17826.47,17837.84,17848.83,17860.13,17871.27,17882.65,17894.21,17905.81,17917.07,17928.78,17940.76,17951.29,17961.96,17973.30,17985.03,17996.67,18007.82,18019.70,18030.98,18042.43,18053.64,18065.04,18075.61,18086.57,18098.23,18109.30,18120.96,18131.76,18143.23,18154.67,18166.20,18178.78,18189.28,18200.16,18212.05,18225.39,18239.33,18251.17,18263.42,18275.92,18287.45,18298.09,18309.68,18321.32,18335.28,18348.59,18359.21,18371.10,18382.16,18392.32,18404.04,18415.01,18427.85,18439.71,18452.32,18465.17,18476.47,18487.20,18499.31,18511.44,18523.38,18534.95,18546.50,18558.01,18569.16,18580.69,18591.94,18604.52,18615.58,18628.26,18640.63,18653.20,18665.42,18677.93,18688.04,18700.93,18712.29,18724.03,18734.18,18748.20,18761.41,18775.00,18785.66,18797.17,18811.14,18824.88,18838.03,18849.52,18860.14,18872.12,18883.20,18893.57,18904.76,18916.46,18928.00,18939.41,18951.29,18962.17,18973.50,18986.25,18997.95,19009.24,19020.63,19032.23,19043.62,19055.45,19068.18,19079.66,19092.36,19104.32,19115.47,19127.29,19138.78,19150.66,19163.12,19174.36,19185.74,19197.15,19208.47,19220.02,19232.69,19243.29,19255.28,19268.73,19279.49,19289.55,19301.61,19313.02,19323.22,19336.95,19354.85,19365.24,19378.88,19389.42,19402.40,19414.26,19425.56,19437.09,19448.65,19460.48,19472.93,19484.77,19495.15,19507.13,19518.72,19530.10,19541.46,19553.87,19565.15,19576.49,19588.54,19601.92,19621.80,19632.21,19653.99,19664.38,19674.78,19692.64,19707.82,19721.06,19733.49,19748.17,19758.86,19772.07,19784.47,19798.64,19821.29,19839.15,19849.55,19868.36,19880.70,19891.10,19901.50,19911.90,19931.14,19945.30,19957.71,19970.96,19981.75,19995.29,20007.42,20019.74,20039.86,20068.00,20104.11,20115.30,20146.44,20158.27,20169.62,20196.45,20207.15,20226.39,20240.86,20258.15,20273.45,20293.64,20328.76,20339.48,20375.70,20387.38,20420.69,20434.19,20447.88,20462.11,20488.27,20499.92,20511.81,20521.88,20534.57,20547.95,20560.76,20570.93,20581.69,20593.60,20615.68,20638.14,20648.31,20660.10,20674.04,20685.72,20697.25,20707.67,20723.38,20740.37,20752.74,20780.21,20814.02,20826.18,20840.66,20875.18,20887.04,20898.46,20911.80,20924.11,20948.34,20977.38,21003.94,21028.11,21063.31,21074.03,21106.43,21143.52,21162.75,21175.30,21188.34,21201.15,21216.23,21228.51,21250.59,21279.90,21305.06,21329.23,21371.33,21383.15,21395.22,21417.23,21433.91,21444.32,21455.83,21470.12,21482.48,21504.24,21516.63,21544.23,21555.45,21567.08,21600.48,21611.52,21624.33,21635.37,21654.06,21664.43,21688.69,21699.04,21730.48,21741.98,21753.73,21776.88,21790.90,21801.29,21813.57,21826.90,21837.26,21863.95,21873.96,21899.25,21911.79,21923.49,21949.44,21971.52,21982.92,22002.55,22017.81,22028.44,22040.72,22054.60,22065.07,22090.23,22102.64,22114.87,22140.02,22155.51,22167.26,22183.89,22196.07,22209.15,22220.60,22243.29,22254.99,22266.51,22291.65,22302.18,22316.40,22328.86,22339.26,22351.54,22364.03,22376.49,22401.51,22412.72,22423.93,22446.14,22458.53,22470.83,22482.39,22503.97,22516.82,22529.02,22557.62,22569.26,22581.20,22607.34,22618.76,22631.12,22642.56,22663.45,22675.82,22688.17,22698.18,22725.20,22737.15,22749.66,22776.48,22794.68,22806.24,22818.05,22830.43,22843.71,22858.61,22869.85,22892.11,22903.92,22917.04,22948.69,22971.96,22983.70,22995.69,23017.05,23027.21,23052.21,23064.82,23077.43,23110.79,23132.28,23144.25,23156.12,23171.52,23185.51,23215.79,23229.92,23240.84,23253.25,23265.15,23277.38,23289.02,23301.64,23323.26,23334.07,23345.69,23357.86,23369.77,23381.18,23392.57,23406.21,23427.35,23441.08,23452.39,23462.81,23475.48,23487.96,23498.02,23510.38,23521.88,23533.97,23571.08,23607.19,23619.69,23632.23,23644.67,23656.89,23674.16,23686.51,23696.59,23709.47,23721.24,23737.18,23749.52,23761.53,23948.84,23959.41,23971.49,23984.17,23994.32,24006.01,24017.35,24029.64,24042.58,24054.32,24067.02,24078.77,24090.38,24102.22,24113.94,24125.46,24137.71,24148.88,24160.73,24171.85,24183.34,24195.49,24206.91,24217.00,24229.97,24242.13,24254.27,24266.15,24276.45,24288.20,24300.21,24313.06,24325.18,24337.09,24350.42,24362.53,24374.71,24386.04,24399.43,24411.30,24422.35,24432.92,24445.63,24456.21,24469.25,24481.88,24492.79,24504.02,24516.17,24528.74,24538.81,24551.07,24562.83,24575.31,24586.70,24598.76,24611.59,24623.23,24634.73,24647.68,24659.80,24675.42,24685.55,24697.35,24711.24,24721.67,24732.31,24744.21,24754.43,24766.37,24776.39,24787.35,24802.40,24816.05,24829.51,24841.38,24851.56,24864.42,24875.06,24886.99,24899.07,24910.83,24922.77,24934.65,24946.75,24958.23,24971.43,24983.14,24995.05,25006.17,25017.65,25029.34,25040.96,25052.94,25065.09,25077.25,25089.20,25100.61,25112.58,25124.43,25136.25,25148.38,25160.53,25172.44,25184.02,25195.34,25206.98,25220.03,25234.26,25246.00,25257.26,25268.78,25280.20,25291.98,25302.01,25315.09,25327.72,25339.46,25351.05,25362.56,25374.47,25386.21,25396.29,25408.84,25420.71,25433.01,25444.78,25456.53,25468.27,25480.16,25563.48,25574.39,25585.40,25596.97,25608.86,25620.60,25632.33,25644.29,25656.21,25668.12,25681.58,25692.14,25704.85,25714.91,25728.82,25742.96,25755.83,25767.15,25778.54,25789.15,25800.85,25810.91,25823.46,25834.05,25846.59,25856.70,25869.60,25881.52,25892.47,25902.76,25915.76,25930.08,25940.49,25954.53,25967.20,25981.26,25994.32,26006.91,26016.92,26027.62,26049.09,26065.55,26076.15,26091.03,26102.80,26115.47,26126.99,26138.74,26150.06,26161.65,26173.13,26184.36,26196.99,26208.94,26220.14,26231.68,26243.28,26254.96,26266.20,26277.88,26289.79,26301.25,26312.29,26323.72,26336.42,26347.19,26359.73,26370.78,26384.28,26395.00,26405.96,26416.53,26427.97,26439.37,26451.25,26462.12,26473.69,26485.00,26495.81,26507.32,26519.10,26531.51,26543.93,26553.98,26565.69,26577.54,26590.94,26601.33,26614.06,26625.17,26636.98,26648.25,26659.92,26671.23,26681.97,26693.96,26705.14,26716.38,26727.09,26738.39,26749.90,26761.37,26772.60,26783.81,26793.99,26807.21,26818.11,26829.40,26841.71,26851.87,26862.98,26875.78,26886.46,26896.99,26910.02,26922.45,26936.20,26950.04,26962.32,26972.96,26984.46,26995.57,27007.22,27019.32,27033.66,27049.71,27059.71,27071.02,27082.93,27094.22,27106.31,27117.87,27128.30,27142.48,27153.01,27164.71,27180.06,27190.67,27204.62,27216.39,27227.38,27240.17,27254.00,27265.77,27277.39,27289.31,27302.28,27316.07,27327.19,27337.21,27348.56,27361.52,27373.96,27387.37,27398.03,27409.47,27421.82,27433.95,27446.65,27457.34,27469.02,27480.49,27491.06,27503.46,27515.42,27527.55,27539.39,27549.96,27560.38,27575.51,27585.52,27597.75,27608.95,27624.94,27636.99,27649.30,27660.83,27672.09,27687.16,27697.64,27710.11,27721.87,27733.29,27745.75,27756.50,27768.54,27781.26,27794.51,27806.07,27818.91,27830.31,27841.56,27857.91,27868.71,27880.15,27892.18,27903.81,27915.18,27927.49,27939.57,27951.45,27962.72,27974.58,27986.08,27997.65,28009.48,28020.64,28032.48,28043.97,28055.08,28066.45,28077.83,28089.42,28101.97,28114.50,28126.12,28138.41,28149.84,28162.44,28172.72,28183.69,28196.24,28208.31,28220.61,28234.04,28245.77,28257.25,28268.01,28282.80,28295.43,28307.64,28318.02,28335.89,28356.42,28367.69,28384.95,28417.08,28453.19,28484.32,28504.51,28516.60,28528.28,28539.18,28551.24,28563.01,28577.11,28589.44,28603.70,28617.97,28635.18,28649.45,28663.71,28678.95,28696.18,28710.44,28726.68,28740.95,28754.22,28765.57,28777.88,28794.82,28807.32,28818.15,28832.25,28846.31,28858.53,28869.78,28885.09,28897.19,28909.32,28920.83,28931.93,28944.03,28956.49,28967.46,28978.11,29002.91,29015.19,29030.49,29047.74,29070.92,29096.11,29120.27,29143.42,29166.60,29185.82,29205.04,29222.30,29240.50,29258.71,29272.01,29284.30,29300.38,29311.64,29323.17,29336.31,29350.39,29364.15,29374.83,29387.45,29399.97,29412.52,29423.87,29435.26,29445.53,29458.58,29471.87,29483.30,29495.82,29507.38,29519.44,29530.14,29541.61,29552.28,29563.14,29575.52,29587.36,29600.77,29614.02,29629.54,29641.00,29653.26,29665.49,29676.17,29689.15,29703.65,29715.93,29727.64,29739.74,29752.31,29764.24,29774.56,29788.07,29799.52,29812.72,29826.05,29838.16,29849.34,29861.66,29874.44,29888.24,29901.74,29920.14,29932.43,29945.72,29961.27,29974.53,29993.42,30007.71,30018.14,30030.25,30042.02,30052.51,30065.26,30077.38,30089.23,30103.19,30114.12,30125.73,30138.33,30151.73,30162.58,30174.31,30185.67,30197.13,30223.94,30241.20,30251.55,30265.73,30279.70,30291.45,30302.93,30313.06,30324.71,30337.12,30347.70,30379.93,30412.09,30423.07,30435.76,30448.94,30458.97,30470.54,30482.27,30493.65,30505.00,30516.53,30527.19,30541.29,30553.71,30573.53,30584.19,30596.09,30607.94,30619.43,30631.12,30642.85,30685.95,30728.05,30738.76,30762.95,30774.23,30786.17,30814.13,30826.24,30837.76,30849.21,30859.75,30872.29,30883.57,30899.79,30912.19,30930.92,30941.19,30983.60,31005.10,31018.29,31029.51,31048.02,31061.81,31073.56,31085.53,31097.94,31109.95,31120.75,31131.80,31144.55,31157.09,31171.12,31182.11,31196.82,31210.36,31220.91,31233.21,31245.49,31256.93,31275.25,31296.48,31307.38,31320.79,31334.31,31354.25,31364.73,31378.62,31394.00,31404.53,31423.55,31458.51,31471.05,31484.38,31496.91,31508.69,31526.93,31544.13,31560.21,31582.64,31598.89,31611.22,31625.45,31641.66,31651.72,31664.09,31692.24,31704.68,31718.98,31730.73,31741.62,31752.57,31789.59,31801.35,31824.09,31836.01,31852.26,31864.49,31874.65,31885.12,31896.50,31906.73,31917.38,31936.50,31947.98,31968.19,31979.01,31991.43,32004.21,32017.61,32028.26,32041.38,32051.38,32062.87,32079.33,32090.46,32101.49,32112.88,32124.24,32137.54,32150.52,32162.13,32178.32,32189.12,32199.80,32216.21,32227.38,32252.79,32266.22,32276.59,32290.08,32306.39,32317.13,32331.09,32343.47,32357.69,32370.99,32391.33,32405.22,32415.62,32428.21,32440.51,32453.11,32465.41,32476.26,32489.35,32500.86,32512.38,32534.37,32545.65,32558.46,32569.06,32580.90,32591.66,32603.06,32614.28,32631.70,32643.87,32662.10,32672.56,32686.39,32700.55,32713.30,32725.26,32737.07,32749.13,32761.48,32773.14,32794.09,32804.53,32814.98,32828.57,32839.14,32851.33,32863.20,32874.36,32886.58,32899.36,32922.07,32934.71,32948.02,32961.14,32974.41,32986.60,32998.92,33010.09,33023.58,33035.29,33052.61,33066.56,33080.87,33091.27,33101.76,33116.07,33126.42,33138.68,33152.32,33165.17,33175.85,33200.83,33220.06,33241.92,33253.71,33282.85,33320.97,33353.10,33377.28,33389.77,33401.58,33411.99,33424.42,33437.93,33453.26,33468.75,33487.80,33517.92,33533.58,33546.97,33560.28,33582.19,33592.64,33612.55,33625.81,33640.13,33662.21,33675.68,33691.60,33704.67,33716.10,33727.73,33739.31,33752.98,33767.91,33788.02,33803.82,33817.04,33827.10,33838.53,33850.19,33869.49,33879.82,33892.38,33916.58,33930.22,33941.58,33962.81,33973.10,33983.80,33994.08,34004.52,34015.40,34025.79,34046.37,34058.02,34070.60,34081.02,34097.48,34117.54,34140.50,34151.90,34163.09,34191.29,34203.15,34218.71,34228.86,34240.85,34256.98,34283.14,34297.42,34307.64,34319.62,34342.06,34354.46,34365.81,34389.78,34416.53,34451.65,34479.81,34517.92,34545.07,34574.22,34626.75,34647.96,34659.40,34671.04,34681.43,34693.66,34714.22,34726.30,34741.87,34756.12,34766.32,34778.28,34794.59,34809.88,34821.82,34831.87,34859.39,34870.72,34883.82,34902.05,34914.34,34925.89,34937.11,34949.99,34976.56,34987.64,35005.08,35021.28,35034.51,35046.96,35058.56,35069.79,35087.86,35098.85,35116.56,35127.02,35162.26,35174.33,35186.83,35198.19,35210.41,35220.97,35231.29,35252.05,35262.56,35285.78,35296.36,35346.28,35358.01,35373.88,35387.80,35398.31,35409.59,35422.49,35444.54,35458.29,35478.51,35491.97,35538.91,35551.55,35576.82,35591.95,35602.74,35614.19,35629.45,35640.56,35651.75,35676.94,35728.46,35740.31,35753.56,35765.66,35780.43,35793.40,35814.37,35828.18,35838.62,35861.64,35900.77,35930.11,35960.22,35990.39,36017.58,36046.73,36062.01,36079.25,36095.52,36108.83,36122.15,36133.46,36147.76,36162.97,36177.30,36192.53,36205.85,36218.20,36228.29,36240.63,36252.07,36270.29,36320.49,36333.13,36348.29,36360.82,36372.86,36384.37,36403.64,36421.02,36434.82,36463.61,36504.69,36545.81,36594.72,36606.28,36658.38,36670.04,36711.79,36727.75,36763.82,36776.36,36788.16,36809.32,36820.80,36833.17,36845.23,36856.99,36867.96,36889.15,36906.09,36916.43,36930.92,36943.92,36962.15,36976.74,36990.96,37003.28,37015.00,37028.16,37039.68,37059.74,37072.05,37083.64,37094.00,37106.17,37136.30,37156.74,37172.88,37184.76,37194.81,37206.73,37218.17,37242.16,37254.48,37267.86,37281.15,37297.41,37315.63,37343.77,37361.02,37375.37,37390.63,37406.37,37416.80,37444.94,37462.18,37492.32,37528.40,37544.67,37556.88,37569.38,37580.75,37603.94,37616.69,37653.52,37680.59,37701.69,37712.79,37729.49,37745.16,37756.25,37817.65,37837.75,37868.36,37888.88,37900.72,37916.57,37932.82,37943.77,37975.75,37999.95,38024.00,38042.58,38060.76,38085.10,38098.38,38109.22,38119.58,38130.12,38140.52,38157.56,38196.88,38220.04,38248.94,38261.60,38291.71,38308.59,38320.23,38331.51,38342.73,38354.18,38376.88,38391.24,38446.31,38456.69,38477.89,38492.16,38515.59,38526.18,38538.50,38549.41,38561.39,38573.78,38628.85,38640.32,38664.36,38676.77,38693.87,38706.43,38716.92,38730.12,38740.73,38751.60,38814.67,38827.84,38838.04,38849.16,38871.33,38892.17,38902.79,38933.93,38968.22,39041.04,39102.12,39180.79,39253.81,39323.87,39333.88,39345.05,39356.12,39378.31,39397.49,39427.70,39445.91,39498.37,39511.97,39523.48,39549.61,39562.84,39575.12,39609.23,39619.58,39637.31,39648.40,39696.94,39744.75,39756.13,39766.36,39777.28,39809.42,39822.07,39861.84,39872.41,39882.52,39893.26,39905.41,39922.93,39950.64,39991.75,40021.42,40041.62,40089.69,40108.90,40122.23,40132.57,40142.97,40189.47,40200.95,40235.05,40252.06,40266.30,40280.08,40290.97,40302.84,40361.88,40411.96,40423.34,40435.38,40468.49,40512.55,40525.94,40536.99,40548.89,40593.76,40604.99,40652.06,40716.38,40785.09,40796.87,40828.67,40870.87,40882.78,40893.67,40906.18,40991.23,41005.32,41033.47,41049.34,41078.95,41094.75,41111.56,41169.63,41185.61,41198.92,41224.06,41239.11,41272.25,41285.50,41297.86,41310.19,41330.10,41341.69,41416.75,41427.79,41463.50,41474.86,41489.11,41514.25,41536.39,41601.04,41612.14,41626.67,41638.31,41650.43,41740.03,41750.29,41840.72,41933.33,42024.00,42036.38,42098.41,42130.55,42156.69,42180.88,42200.10,42210.93,42222.19,42240.79,42265.93,42298.04,42309.80,42322.47,42355.64,42367.26,42377.83,42422.94,42437.76,42481.24,42493.57,42526.65,42562.41,42601.37,42635.50,42646.24,42656.73,42669.75,42682.56,42720.15,42731.66,42766.80,42776.87,42793.16,42806.91,42818.74,42829.16,42839.60,42849.65,42872.35,42882.44,42895.13,42905.47,42916.69,42929.08,42943.29,42954.47,42971.96,42985.29,42999.39,43013.38,43028.04,43043.15,43053.55,43076.64,43101.72,43116.16,43127.15,43138.57,43149.74,43160.14,43170.67,43185.35,43195.61,43209.84,43225.13,43242.69,43255.01,43279.13,43318.50,43329.80,43355.30,43367.21,43378.10,43388.81,43400.07,43413.51,43423.53,43440.29,43468.34,43520.36,43546.39,43564.44,43578.49,43591.54,43603.60,43613.99,43624.04,43640.14,43650.42,43662.76,43690.80,43706.16,43737.16,43747.16,43757.17,43788.17,43819.17,43844.23,43856.23,43869.29,43891.29,43914.29,43936.29,43958.29,43971.29,43983.29,43994.29,44008.29,44021.35,44034.83,44142.23,44178.63,44319.63,44332.63,44344.63,44355.70,44369.45,44383.52,44395.94,44406.94,44550.00,44693.06,44726.06,44865.06,44902.06,45042.06,45182.06,45322.06,45335.06,45488.06,45652.06,45806.06,45816.29,45826.41,45838.03,45848.36,45860.24,45873.26,45889.26,45905.26,45924.27,45944.27,45965.27,45987.27,46009.27,46033.27,46053.27,46076.27,46098.31,46118.35,46136.39,46154.41,46170.44,46181.30,46191.41,46205.94,46217.46,46229.95,46248.16,46267.29,46277.36,46288.40,46299.50,46312.59,46323.69,46337.70,46347.70,46360.70,46371.70,46381.71,46404.77,46420.77,46433.77,46448.77,46464.78,46497.78,46534.78,46545.00,46704.00,46730.00,46743.00,46767.01,46905.02,46916.17,47043.17,47174.31,47361.24,47381.24,47391.25,47428.25,47453.25,47487.25,47657.25,47839.25,47860.25,47877.25,47889.25,47907.25,47930.25,48068.25,48195.25,48317.25,48439.25,48501.25,48543.25,48588.25,48659.25,48696.25,48827.26,48851.26,48874.26,48892.29,48919.57,49008.96,49092.96,49190.06,49215.88,49249.39,49296.02,49310.12,49360.14,49432.58,49478.59,49561.05,49571.62,49673.91,49684.20,49717.46,49734.38,49754.78,49770.78,49782.93,49850.93,49904.06,49925.06,49937.06,50012.06,50085.06,50103.12,50114.12,50125.23,50163.23,50202.23,50213.23,50228.24,50250.24,50286.28,50327.28,50366.29,50435.29,50446.12,50537.43,50588.73,50626.73,50710.17,50720.66,50786.66,50796.66,50807.00,50847.00,50882.38,50892.75,50939.86,50988.74,51042.16,51083.06,51171.41,51182.14,51224.19,51260.26,51271.44,51281.88,51325.88,51372.54,51415.54,51462.33,51506.23,51552.37,51562.67,51574.69,51584.79,51594.99,51606.17,51626.75,51647.15,51665.15,51683.03,51693.20,51711.72,51732.05,51742.49,51765.00,51789.65,51807.03,51825.67,51839.48,51852.71,51863.13,51873.65,51887.70,51907.80,51920.93,51934.50,51952.38,51965.64,51975.64,51990.65,52006.72,52016.72,52027.72,52038.73,52058.73,52080.73,52099.73,52116.75,52128.24,52139.08,52158.47,52177.63,52188.96,52213.97,52233.96,52262.91,52284.31,52298.08,52312.92,52323.98,52334.63,52350.82,52376.01,52392.14,52406.17,52442.02,52471.02,52499.41,52532.41,52562.41,52591.41,52610.41,52631.64,52660.96,52687.70,52716.03,52741.42,52768.41,52780.73,52826.48,52838.00,52849.15,52871.02,52884.91,52907.24,52925.67,52961.07,52984.88,53021.56,53045.22,53091.12,53109.72,53155.22,53222.55,53239.34,53249.72,53260.76,53275.47,53309.87,53354.33,53384.79,53396.86,53407.05,53418.10,53469.03,53480.52,53518.53,53550.68,53594.35,53604.80,53659.06,53711.52,53728.59,53743.20,53754.89,53765.75,53779.40,53822.80,53832.97,53844.74,53855.01,53886.26,53898.26,53936.57,53988.25,54045.51,54087.60,54100.60,54114.60,54126.66,54141.66,54156.66,54190.81,54204.93,54217.93,54237.93,54292.34,54349.34,54369.34,54388.34,54403.35,54417.36,54434.36,54445.36,54460.66,54475.66,54489.66,54507.66,54522.88,54537.23,54556.23,54573.23,54586.23,54601.51,54617.72,54636.72,54651.72,54665.72,54682.72,54700.72,54711.28,54726.33,54742.37,54752.38,54769.38,54786.38,54802.38,54812.38,54823.38,54834.71,54847.72,54863.03,54888.69,54903.23,54917.17,54929.47,54942.47,54956.78,54966.79,54979.92,54991.69,55004.57,55017.58,55029.58,55041.59,55051.92,55062.93,55072.93,55088.97,55099.04,55109.07,55124.08,55136.08,55147.17,55158.53,55168.58,55178.87,55197.87,55208.87,55220.09,55233.32,55245.32,55258.32,55283.32,55294.32,55309.32,55320.01,55330.20,55341.20,55354.20,55372.25,55390.27,55412.27,55445.27,55456.27,55471.27,55492.27,55503.27,55514.27,55532.27,55549.27,55564.27,55581.27,55594.27,55608.27,55621.27,55635.27,55646.27,55684.28,55708.41,55724.41,55741.41,55754.41,55769.54,55786.54,55801.54,55816.54,55830.54,55869.00,55885.48,55897.80,55909.22,55944.60,55954.80,55965.08,56005.32,56029.67,56046.32,56056.33,56075.58,56089.59,56123.58,56134.65,56159.65,56173.65,56184.65,56197.66,56207.66,56218.66,56228.67,56240.68,56251.68,56275.70,56292.70,56304.71,56328.72,56338.75,56360.75,56374.75,56386.76,56399.76,56420.76,56434.76,56446.76,56473.08,56485.54,56497.54,56513.54,56540.54,56553.55,56568.55,56599.55,56632.60,56643.60,56673.82,56696.82,56708.82,56732.09,56753.13,56783.29,56811.30,56822.49,56858.70,56887.42,56908.43,56932.43,56954.43,56967.49,56984.49,57006.49,57021.78,57036.83,57052.83,57066.83,57089.83,57111.83,57137.83,57152.05,57173.05,57184.05,57204.05,57223.05,57237.05,57263.45,57286.45,57301.45,57317.45,57331.45,57345.46,57368.53,57389.53,57415.53,57425.53,57435.87,57448.91,57463.92,57490.31,57506.31,57520.31,57546.31,57574.31,57591.31,57602.53,57614.53,57639.53,57651.53,57666.55,57701.55,57719.55,57748.16,57764.16,57776.23,57808.29,57823.51,57845.51,57885.51,57921.51,57948.62,57977.62,58023.63,58053.76,58064.76,58077.76,58098.76,58109.76,58126.76,58138.78,58158.78,58192.78,58230.78,58259.05,58283.05,58295.05,58313.06,58341.12,58354.12,58375.13,58385.16,58405.16,58437.16,58480.16,58503.33,58518.33,58551.39,58572.39,58584.39,58595.40,58610.40,58658.40,58701.40,58723.40,58740.40,58770.41,58792.41,58808.41,58820.41,58849.41,58883.41,58897.41,58920.41,58944.41,58961.41,58973.41,59009.41,59034.41,59046.41,59056.41,59072.41,59094.41,59105.41,59116.41,59160.41,59176.41,59188.41,59227.41,59244.41,59256.41,59279.41,59304.43,59324.43,59348.43,59365.49,59377.49,59389.49,59406.49,59422.49,59459.49,59472.51,59509.51,59522.51,59545.51,59572.51,59585.51,59596.51,59628.51,59641.51,59658.52,59686.52,59697.53,59710.53,59728.53,59782.53,59795.53,59807.53,59833.53,59851.53,59865.53,59881.53,59906.53,59917.53,59927.59,59942.59,59963.59,59989.65,60003.65,60020.65,60056.65,60076.65,60095.65,60106.65,60123.65,60141.65,60156.65,60188.65,60213.71,60225.93,60237.93,60283.93,60309.93,60339.93,60350.38,60362.61,60374.61,60386.61,60427.61,60446.61,60459.61,60480.61,60505.61,60516.61,60528.74,60539.02,60576.02,60587.02,60625.02,60637.02,60648.02,60668.88,60681.74,60694.09,60704.86,60732.86,60743.16,60775.43,60787.72,60799.79,60814.07,60835.38,60846.39,60877.52,60889.53,60899.53,60909.55,60933.55,60949.55,60961.55,60980.55,60997.58,61022.59,61034.59,61059.59,61071.60,61098.60,61138.60,61150.95,61162.96,61191.09,61202.12,61232.12,61243.15,61277.15],\r\n\t\t\t\t\tgraphEle           : [-209.00,39.00,26.00,15.00,23.00,33.00,45.00,57.00,69.00,81.00,92.00,99.00,109.00,91.00,102.00,84.00,91.00,102.00,89.00,80.00,73.00,84.00,67.00,66.00,56.00,45.00,39.00,34.00,43.00,43.00,33.00,35.00,43.00,39.00,41.00,39.00,36.00,27.00,17.00,5.00,-5.00,-19.00,-31.00,-42.00,-54.00,-66.00,-77.00,-63.00,-50.00,-37.00,-25.00,-13.00,-3.00,8.00,18.00,28.00,33.00,39.00,32.00,22.00,12.00,16.00,16.00,16.00,18.00,21.00,20.00,21.00,22.00,25.00,25.00,28.00,27.00,19.00,10.00,6.00,7.00,12.00,6.00,5.00,3.00,5.00,-2.00,-3.00,-2.00,-4.00,0.00,-11.00,-16.00,-19.00,-20.00,-12.00,-19.00,-27.00,-31.00,-20.00,-34.00,-24.00,-35.00,-38.00,-46.00,-39.00,-48.00,-55.00,-57.00,-62.00,-55.00,-62.00,-66.00,-68.00,-61.00,-71.00,-76.00,-75.00,-72.00,-74.00,-86.00,-79.00,-75.00,-82.00,-90.00,-97.00,-102.00,-120.00,-138.00,-150.00,-154.00,-155.00,-152.00,-147.00,-151.00,-151.00,-143.00,-142.00,-147.00,-145.00,-149.00,-141.00,-150.00,-145.00,-139.00,-142.00,-141.00,-139.00,-137.00,-125.00,-118.00,-109.00,-96.00,-80.00,-70.00,-60.00,-53.00,-46.00,-39.00,-30.00,-24.00,-17.00,-11.00,-7.00,-1.00,4.00,15.00,12.00,24.00,18.00,26.00,32.00,39.00,42.00,48.00,55.00,59.00,61.00,58.00,64.00,64.00,64.00,57.00,47.00,33.00,18.00,8.00,-2.00,1.00,-1.00,-1.00,9.00,3.00,8.00,11.00,11.00,9.00,17.00,34.00,39.00,29.00,39.00,42.00,39.00,42.00,44.00,39.00,45.00,47.00,39.00,45.00,49.00,47.00,39.00,39.00,37.00,27.00,17.00,7.00,-7.00,-18.00,-27.00,-35.00,-40.00,-32.00,-22.00,-26.00,-7.00,-7.00,-7.00,-7.00,-22.00,-12.00,3.00,-8.00,10.00,16.00,16.00,28.00,33.00,15.00,18.00,8.00,8.00,23.00,32.00,25.00,14.00,2.00,-11.00,-21.00,-45.00,-47.00,-34.00,-39.00,-26.00,-13.00,-10.00,1.00,18.00,30.00,36.00,41.00,44.00,27.00,17.00,-3.00,-13.00,-27.00,-49.00,-32.00,-46.00,-42.00,-31.00,-41.00,-52.00,-69.00,-81.00,-94.00,-92.00,-79.00,-67.00,-56.00,-45.00,-34.00,-19.00,-6.00,5.00,15.00,27.00,39.00,50.00,53.00,58.00,48.00,57.00,51.00,41.00,35.00,24.00,10.00,0.00,-11.00,-21.00,-29.00,-28.00,-36.00,-51.00,-55.00,-65.00,-76.00,-86.00,-97.00,-82.00,-80.00,-68.00,-57.00,-44.00,-31.00,-19.00,-11.00,5.00,20.00,33.00,47.00,62.00,74.00,87.00,96.00,107.00,113.00,120.00,128.00,127.00,130.00,134.00,125.00,120.00,117.00,116.00,115.00,111.00,106.00,103.00,103.00,98.00,96.00,96.00,101.00,95.00,96.00,94.00,92.00,88.00,87.00,88.00,87.00,84.00,71.00,59.00,64.00,59.00,62.00,66.00,77.00,74.00,68.00,79.00,72.00,74.00,80.00,81.00,89.00,81.00,84.00,93.00,91.00,69.00,85.00,91.00,88.00,78.00,69.00,63.00,57.00,46.00,57.00,62.00,69.00,64.00,54.00,42.00,52.00,58.00,52.00,35.00,41.00,31.00,4.00,-26.00,-57.00,-83.00,-102.00,-107.00,-102.00,-100.00,-99.00,-101.00,-88.00,-76.00,-53.00,-41.00,-21.00,0.00,16.00,30.00,42.00,53.00,65.00,76.00,95.00,107.00,124.00,136.00,148.00,159.00,169.00,182.00,193.00,199.00,190.00,202.00,215.00,216.00,205.00,217.00,212.00,207.00,191.00,198.00,195.00,187.00,199.00,186.00,196.00,206.00,194.00,209.00,217.00,213.00,205.00,211.00,198.00,207.00,190.00,205.00,201.00,185.00,179.00,189.00,184.00,170.00,173.00,167.00,186.00,185.00,173.00,174.00,172.00,183.00,182.00,174.00,168.00,168.00,166.00,165.00,180.00,165.00,163.00,160.00,161.00,154.00,152.00,150.00,147.00,162.00,149.00,141.00,142.00,139.00,136.00,132.00,129.00,126.00,124.00,120.00,122.00,117.00,118.00,109.00,102.00,102.00,98.00,112.00,99.00,90.00,85.00,90.00,83.00,79.00,78.00,76.00,76.00,78.00,70.00,64.00,74.00,68.00,65.00,60.00,55.00,58.00,57.00,57.00,48.00,49.00,63.00,65.00,69.00,66.00,73.00,75.00,78.00,71.00,78.00,83.00,82.00,83.00,79.00,81.00,84.00,86.00,88.00,81.00,89.00,94.00,94.00,91.00,93.00,96.00,79.00,94.00,74.00,76.00,69.00,70.00,69.00,69.00,73.00,76.00,61.00,66.00,71.00,83.00,82.00,90.00,92.00,96.00,100.00,86.00,85.00,87.00,95.00,97.00,106.00,105.00,109.00,104.00,115.00,104.00,98.00,97.00,94.00,98.00,112.00,112.00,110.00,107.00,106.00,93.00,85.00,83.00,83.00,93.00,102.00,103.00,98.00,98.00,95.00,92.00,89.00,83.00,83.00,89.00,95.00,104.00,99.00,96.00,90.00,92.00,90.00,84.00,84.00,91.00,93.00,92.00,82.00,79.00,86.00,87.00,82.00,82.00,87.00,85.00,80.00,77.00,79.00,78.00,80.00,80.00,87.00,85.00,87.00,86.00,87.00,84.00,75.00,63.00,60.00,39.00,7.00,-25.00,-57.00,-82.00,-117.00,-140.00,-153.00,-156.00,-157.00,-155.00,-153.00,-153.00,-153.00,-151.00,-148.00,-144.00,-129.00,-114.00,-102.00,-83.00,-67.00,-52.00,-38.00,-23.00,-3.00,15.00,28.00,48.00,70.00,80.00,94.00,112.00,124.00,135.00,144.00,156.00,165.00,179.00,181.00,184.00,188.00,192.00,201.00,196.00,196.00,192.00,185.00,184.00,180.00,177.00,178.00,177.00,177.00,170.00,178.00,177.00,180.00,176.00,177.00,177.00,172.00,180.00,182.00,184.00,189.00,189.00,193.00,195.00,197.00,201.00,203.00,205.00,211.00,205.00,189.00,184.00,183.00,185.00,185.00,187.00,191.00,186.00,192.00,186.00,185.00,186.00,186.00,189.00,193.00,193.00,193.00,189.00,188.00,188.00,186.00,190.00,193.00,195.00,195.00,188.00,193.00,187.00,196.00,186.00,186.00,194.00,197.00,193.00,196.00,183.00,179.00,197.00,175.00,183.00,175.00,187.00,186.00,194.00,190.00,195.00,190.00,182.00,160.00,173.00,181.00,178.00,201.00,199.00,191.00,187.00,170.00,155.00,153.00,166.00,174.00,174.00,168.00,164.00,168.00,165.00,172.00,163.00,148.00,149.00,162.00,162.00,159.00,162.00,153.00,160.00,149.00,144.00,148.00,153.00,159.00,153.00,153.00,148.00,152.00,162.00,147.00,135.00,147.00,148.00,150.00,152.00,156.00,168.00,163.00,158.00,143.00,128.00,114.00,78.00,68.00,94.00,82.00,72.00,55.00,40.00,31.00,17.00,8.00,0.00,0.00,-18.00,-33.00,-16.00,-16.00,-11.00,0.00,11.00,17.00,29.00,36.00,34.00,33.00,64.00,52.00,73.00,69.00,78.00,91.00,73.00,98.00,108.00,103.00,82.00,92.00,89.00,123.00,90.00,93.00,118.00,98.00,74.00,102.00,84.00,116.00,107.00,118.00,94.00,82.00,97.00,98.00,84.00,123.00,86.00,78.00,75.00,86.00,89.00,76.00,78.00,76.00,76.00,70.00,63.00,73.00,62.00,74.00,90.00,74.00,80.00,69.00,81.00,88.00,77.00,81.00,75.00,65.00,76.00,73.00,72.00,84.00,68.00,82.00,82.00,81.00,84.00,77.00,79.00,80.00,107.00,95.00,98.00,90.00,93.00,71.00,93.00,94.00,78.00,91.00,93.00,107.00,113.00,97.00,88.00,86.00,85.00,86.00,90.00,106.00,131.00,112.00,89.00,97.00,92.00,106.00,95.00,97.00,114.00,99.00,100.00,140.00,121.00,108.00,112.00,114.00,103.00,117.00,107.00,117.00,107.00,126.00,110.00,114.00,129.00,117.00,118.00,76.00,72.00,120.00,123.00,147.00,111.00,128.00,66.00,67.00,136.00,137.00,68.00,82.00,66.00,78.00,147.00,137.00,153.00,71.00,65.00,73.00,155.00,74.00,74.00,71.00,70.00,74.00,69.00,65.00,69.00,76.00,75.00,72.00,69.00,69.00,67.00,66.00,70.00,77.00,77.00,69.00,63.00,62.00,59.00,52.00,56.00,63.00,66.00,64.00,65.00,64.00,60.00,60.00,66.00,66.00,65.00,61.00,62.00,58.00,50.00,49.00,47.00,49.00,47.00,46.00,47.00,47.00,47.00,47.00,46.00,47.00,46.00,45.00,44.00,44.00,44.00,43.00,44.00,43.00,43.00,43.00,43.00,42.00,42.00,38.00,38.00,42.00,42.00,42.00,41.00,41.00,38.00,41.00,41.00,24.00,7.00,-9.00,-26.00,-36.00,-58.00,-71.00,-83.00,-94.00,-104.00,-119.00,-132.00,-133.00,-120.00,-103.00,-86.00,-69.00,-58.00,-48.00,-30.00,-14.00,-1.00,8.00,20.00,26.00,34.00,42.00,43.00,51.00,56.00,59.00,59.00,45.00,40.00,39.00,37.00,38.00,39.00,38.00,38.00,35.00,36.00,37.00,37.00,39.00,39.00,39.00,37.00,38.00,38.00,39.00,40.00,41.00,41.00,40.00,40.00,40.00,40.00,42.00,43.00,44.00,43.00,42.00,42.00,41.00,40.00,35.00,25.00,15.00,4.00,-2.00,-8.00,-15.00,-21.00,-25.00,-29.00,-32.00,-38.00,-43.00,-47.00,-50.00,-52.00,-52.00,-54.00,-56.00,-61.00,-62.00,-64.00,-65.00,-65.00,-65.00,-67.00,-70.00,-72.00,-74.00,-76.00,-76.00,-76.00,-77.00,-79.00,-82.00,-83.00,-84.00,-84.00,-82.00,-82.00,-83.00,-85.00,-86.00,-86.00,-86.00,-84.00,-82.00,-83.00,-86.00,-86.00,-87.00,-87.00,-86.00,-84.00,-85.00,-87.00,-90.00,-91.00,-93.00,-93.00,-91.00,-92.00,-93.00,-95.00,-96.00,-96.00,-96.00,-92.00,-93.00,-94.00,-97.00,-98.00,-97.00,-97.00,-92.00,-92.00,-92.00,-92.00,-95.00,-96.00,-95.00,-92.00,-94.00,-95.00,-96.00,-100.00,-101.00,-100.00,-97.00,-98.00,-98.00,-99.00,-103.00,-103.00,-103.00,-100.00,-100.00,-100.00,-99.00,-99.00,-103.00,-101.00,-101.00,-102.00,-103.00,-104.00,-105.00,-108.00,-112.00,-112.00,-100.00,-101.00,-103.00,-110.00,-103.00,-109.00,-109.00,-104.00,-87.00,-81.00,-79.00,-71.00,-63.00,-53.00,-50.00,-42.00,-32.00,-20.00,-9.00,4.00,20.00,32.00,51.00,55.00,55.00,53.00,53.00,55.00,51.00,50.00,50.00,46.00,48.00,38.00,39.00,54.00,59.00,67.00,66.00,62.00,54.00,47.00,42.00,44.00,59.00,48.00,55.00,60.00,66.00,58.00,57.00,58.00,56.00,57.00,50.00,46.00,42.00,38.00,37.00,36.00,36.00,36.00,39.00,36.00,36.00,36.00,36.00,36.00,37.00,39.00,39.00,38.00,38.00,37.00,37.00,38.00,38.00,38.00,38.00,38.00,38.00,37.00,37.00,37.00,37.00,37.00,37.00,37.00,37.00,37.00,37.00,37.00,37.00,37.00,37.00,35.00,35.00,36.00,39.00,45.00,54.00,54.00,49.00,41.00,33.00,24.00,15.00,7.00,1.00,-1.00,0.00,7.00,17.00,23.00,30.00,35.00,40.00,42.00,40.00,34.00,27.00,21.00,14.00,12.00,11.00,6.00,2.00,-1.00,-2.00,-2.00,-1.00,0.00,0.00,0.00,-4.00,-10.00,-16.00,-21.00,-27.00,-32.00,-38.00,-43.00,-47.00,-48.00,-47.00,-41.00,-33.00,-23.00,-13.00,-4.00,6.00,17.00,28.00,38.00,46.00,53.00,57.00,58.00,48.00,41.00,39.00,36.00,36.00,36.00,36.00,37.00,38.00,39.00,38.00,38.00,38.00,38.00,39.00,40.00,40.00,41.00,41.00,41.00,42.00,42.00,43.00,43.00,43.00,43.00,43.00,42.00,40.00,35.00,27.00,23.00,13.00,4.00,0.00,-4.00,-5.00,0.00,10.00,27.00,37.00,47.00,52.00,45.00,42.00,42.00,41.00,41.00,42.00,44.00,46.00,41.00,39.00,38.00,37.00,37.00,37.00,38.00,45.00,46.00,34.00,15.00,5.00,-16.00,-26.00,-36.00,-53.00,-67.00,-79.00,-90.00,-102.00,-111.00,-123.00,-134.00,-147.00,-164.00,-181.00,-191.00,-209.00,-221.00,-231.00,-241.00,-251.00,-269.00,-282.00,-292.00,-304.00,-310.00,-305.00,-313.00,-301.00,-286.00,-314.00,-278.00,-283.00,-314.00,-314.00,-313.00,-292.00,-288.00,-307.00,-297.00,-287.00,-291.00,-311.00,-276.00,-280.00,-312.00,-310.00,-287.00,-277.00,-278.00,-288.00,-274.00,-274.00,-276.00,-280.00,-287.00,-287.00,-279.00,-276.00,-275.00,-275.00,-263.00,-275.00,-279.00,-279.00,-274.00,-272.00,-272.00,-262.00,-272.00,-258.00,-254.00,-275.00,-248.00,-245.00,-238.00,-264.00,-271.00,-270.00,-257.00,-269.00,-251.00,-224.00,-242.00,-266.00,-236.00,-230.00,-261.00,-224.00,-243.00,-254.00,-265.00,-270.00,-258.00,-270.00,-255.00,-228.00,-253.00,-229.00,-271.00,-273.00,-271.00,-251.00,-265.00,-259.00,-251.00,-237.00,-245.00,-225.00,-216.00,-229.00,-222.00,-214.00,-183.00,-190.00,-191.00,-184.00,-167.00,-177.00,-157.00,-151.00,-168.00,-166.00,-164.00,-141.00,-152.00,-159.00,-155.00,-142.00,-152.00,-132.00,-127.00,-145.00,-143.00,-140.00,-116.00,-136.00,-134.00,-127.00,-142.00,-151.00,-139.00,-150.00,-159.00,-184.00,-187.00,-183.00,-158.00,-168.00,-160.00,-145.00,-136.00,-126.00,-118.00,-135.00,-133.00,-130.00,-107.00,-116.00,-130.00,-139.00,-144.00,-132.00,-128.00,-123.00,-144.00,-144.00,-146.00,-124.00,-135.00,-147.00,-149.00,-137.00,-133.00,-130.00,-153.00,-154.00,-156.00,-133.00,-143.00,-155.00,-156.00,-145.00,-157.00,-145.00,-140.00,-162.00,-170.00,-170.00,-153.00,-171.00,-173.00,-175.00,-163.00,-176.00,-163.00,-161.00,-180.00,-187.00,-185.00,-163.00,-185.00,-182.00,-180.00,-164.00,-156.00,-170.00,-170.00,-161.00,-134.00,-154.00,-151.00,-152.00,-142.00,-148.00,-168.00,-179.00,-179.00,-184.00,-186.00,-189.00,-191.00,-181.00,-194.00,-198.00,-198.00,-191.00,-188.00,-187.00,-186.00,-174.00,-187.00,-194.00,-195.00,-188.00,-183.00,-182.00,-177.00,-173.00,-172.00,-173.00,-136.00,-172.00,-165.00,-162.00,-162.00,-160.00,-146.00,-139.00,-134.00,-130.00,-134.00,-147.00,-159.00,-161.00,15.00,13.00,11.00,6.00,2.00,-1.00,-2.00,-2.00,2.00,-1.00,-6.00,-7.00,-7.00,-5.00,-3.00,-3.00,-4.00,-4.00,-3.00,-3.00,-4.00,-8.00,-10.00,-15.00,-13.00,-13.00,-17.00,-19.00,-25.00,-27.00,-30.00,-32.00,-29.00,-26.00,-29.00,-32.00,-35.00,-42.00,-49.00,-48.00,-45.00,-39.00,-42.00,-48.00,-53.00,-55.00,-60.00,-67.00,-67.00,-59.00,-60.00,-64.00,-65.00,-65.00,-64.00,-65.00,-63.00,-53.00,-54.00,-59.00,-62.00,-57.00,-65.00,-65.00,-53.00,-54.00,-53.00,-55.00,-53.00,-52.00,-56.00,-61.00,-54.00,-56.00,-61.00,-69.00,-64.00,-60.00,-65.00,-63.00,-60.00,-61.00,-63.00,-60.00,-57.00,-56.00,-54.00,-56.00,-57.00,-55.00,-54.00,-54.00,-53.00,-51.00,-54.00,-55.00,-59.00,-53.00,-51.00,-50.00,-49.00,-50.00,-47.00,-44.00,-44.00,-44.00,-44.00,-47.00,-42.00,-42.00,-42.00,-41.00,-40.00,-39.00,-42.00,-47.00,-43.00,-44.00,-46.00,-47.00,-45.00,-44.00,-47.00,-45.00,-42.00,-39.00,-38.00,-37.00,-36.00,-38.00,40.00,38.00,38.00,38.00,38.00,39.00,40.00,41.00,43.00,45.00,51.00,57.00,66.00,74.00,85.00,96.00,105.00,112.00,119.00,125.00,133.00,137.00,141.00,147.00,148.00,149.00,142.00,136.00,133.00,133.00,126.00,116.00,110.00,104.00,100.00,95.00,92.00,88.00,86.00,81.00,66.00,57.00,51.00,44.00,42.00,40.00,41.00,43.00,45.00,46.00,47.00,46.00,42.00,40.00,39.00,38.00,40.00,42.00,42.00,44.00,47.00,48.00,49.00,47.00,41.00,34.00,29.00,27.00,20.00,20.00,21.00,21.00,24.00,25.00,27.00,26.00,25.00,23.00,24.00,21.00,17.00,11.00,6.00,0.00,-4.00,-2.00,-9.00,-14.00,-12.00,-14.00,-18.00,-20.00,-24.00,-28.00,-35.00,-37.00,-36.00,-35.00,-35.00,-36.00,-36.00,-34.00,-31.00,-29.00,-23.00,-16.00,-14.00,-16.00,-25.00,-29.00,-29.00,-19.00,-10.00,-1.00,9.00,18.00,29.00,40.00,49.00,55.00,57.00,57.00,60.00,62.00,56.00,41.00,37.00,36.00,33.00,33.00,37.00,39.00,45.00,56.00,65.00,75.00,87.00,96.00,107.00,115.00,122.00,127.00,135.00,138.00,140.00,144.00,148.00,156.00,156.00,161.00,164.00,165.00,162.00,152.00,148.00,150.00,153.00,158.00,156.00,160.00,160.00,162.00,163.00,164.00,156.00,156.00,157.00,163.00,156.00,149.00,144.00,144.00,144.00,152.00,144.00,139.00,137.00,137.00,143.00,139.00,140.00,144.00,146.00,149.00,144.00,140.00,134.00,127.00,125.00,122.00,120.00,119.00,110.00,101.00,102.00,106.00,108.00,110.00,114.00,118.00,121.00,122.00,119.00,116.00,108.00,105.00,104.00,104.00,106.00,107.00,105.00,104.00,104.00,93.00,82.00,78.00,73.00,72.00,76.00,82.00,89.00,94.00,98.00,103.00,110.00,114.00,112.00,105.00,96.00,86.00,77.00,73.00,56.00,38.00,34.00,17.00,-15.00,-51.00,-82.00,-102.00,-106.00,-108.00,-108.00,-104.00,-96.00,-83.00,-71.00,-57.00,-43.00,-26.00,-12.00,2.00,17.00,34.00,48.00,64.00,78.00,91.00,102.00,114.00,130.00,141.00,147.00,160.00,173.00,184.00,194.00,207.00,216.00,222.00,223.00,225.00,229.00,234.00,235.00,234.00,211.00,199.00,184.00,167.00,144.00,119.00,95.00,72.00,49.00,30.00,11.00,-6.00,-24.00,-42.00,-55.00,-67.00,-82.00,-88.00,-87.00,-81.00,-73.00,-62.00,-53.00,-44.00,-35.00,-26.00,-25.00,-17.00,-11.00,-1.00,9.00,16.00,23.00,23.00,19.00,12.00,4.00,-3.00,-10.00,-19.00,-20.00,-14.00,-2.00,11.00,21.00,32.00,43.00,52.00,62.00,74.00,83.00,91.00,95.00,100.00,103.00,109.00,119.00,125.00,135.00,142.00,147.00,154.00,158.00,163.00,169.00,163.00,150.00,138.00,126.00,113.00,101.00,83.00,70.00,65.00,64.00,67.00,73.00,82.00,91.00,99.00,110.00,117.00,125.00,134.00,141.00,143.00,141.00,141.00,141.00,165.00,182.00,192.00,205.00,216.00,224.00,232.00,236.00,235.00,224.00,219.00,187.00,219.00,218.00,220.00,222.00,225.00,225.00,226.00,226.00,226.00,225.00,220.00,212.00,209.00,220.00,224.00,226.00,226.00,226.00,225.00,220.00,177.00,219.00,214.00,194.00,193.00,196.00,221.00,225.00,226.00,228.00,234.00,237.00,229.00,213.00,202.00,185.00,175.00,133.00,130.00,117.00,106.00,88.00,77.00,66.00,57.00,48.00,43.00,36.00,35.00,27.00,16.00,8.00,4.00,14.00,26.00,30.00,35.00,25.00,36.00,21.00,0.00,-9.00,-21.00,-33.00,-50.00,-55.00,-46.00,-32.00,-27.00,-9.00,22.00,33.00,45.00,56.00,64.00,46.00,57.00,54.00,74.00,81.00,93.00,106.00,122.00,125.00,130.00,102.00,107.00,93.00,96.00,101.00,103.00,137.00,138.00,119.00,121.00,105.00,106.00,107.00,108.00,113.00,108.00,108.00,124.00,124.00,104.00,109.00,107.00,114.00,119.00,125.00,119.00,114.00,115.00,103.00,96.00,101.00,90.00,79.00,92.00,86.00,79.00,74.00,68.00,69.00,60.00,53.00,29.00,35.00,33.00,23.00,8.00,-1.00,-12.00,-12.00,-23.00,-30.00,-48.00,-36.00,-46.00,-35.00,-36.00,-44.00,-53.00,-51.00,-46.00,-55.00,-56.00,-75.00,-67.00,-56.00,-47.00,-44.00,-48.00,-49.00,-42.00,-41.00,-37.00,-51.00,-45.00,-33.00,-22.00,-21.00,-25.00,-28.00,-22.00,-30.00,-31.00,-49.00,-41.00,-31.00,-21.00,-16.00,-17.00,-15.00,-6.00,2.00,-2.00,-12.00,-7.00,3.00,12.00,14.00,11.00,13.00,20.00,11.00,10.00,-4.00,8.00,5.00,15.00,20.00,18.00,13.00,16.00,20.00,10.00,5.00,-16.00,-1.00,-22.00,-32.00,-61.00,-99.00,-131.00,-155.00,-166.00,-167.00,-170.00,-163.00,-168.00,-157.00,-143.00,-141.00,-111.00,-98.00,-85.00,-72.00,-51.00,-41.00,-22.00,-11.00,2.00,23.00,35.00,50.00,57.00,63.00,73.00,80.00,67.00,77.00,94.00,108.00,119.00,127.00,133.00,137.00,149.00,153.00,153.00,135.00,143.00,138.00,159.00,162.00,160.00,156.00,161.00,155.00,158.00,144.00,144.00,153.00,163.00,156.00,144.00,156.00,150.00,146.00,131.00,130.00,142.00,147.00,139.00,126.00,152.00,138.00,140.00,136.00,117.00,114.00,103.00,81.00,56.00,21.00,-7.00,-45.00,-72.00,-101.00,-148.00,-169.00,-180.00,-184.00,-189.00,-188.00,-204.00,-203.00,-194.00,-180.00,-176.00,-176.00,-192.00,-177.00,-179.00,-183.00,-202.00,-202.00,-194.00,-177.00,-174.00,-176.00,-176.00,-183.00,-202.00,-202.00,-188.00,-187.00,-174.00,-174.00,-175.00,-174.00,-177.00,-182.00,-194.00,-201.00,-175.00,-173.00,-162.00,-173.00,-174.00,-168.00,-173.00,-177.00,-175.00,-194.00,-201.00,-160.00,-170.00,-160.00,-164.00,-174.00,-166.00,-159.00,-175.00,-170.00,-189.00,-201.00,-160.00,-158.00,-177.00,-163.00,-158.00,-158.00,-173.00,-167.00,-169.00,-192.00,-155.00,-155.00,-155.00,-157.00,-151.00,-152.00,-166.00,-156.00,-153.00,-172.00,-133.00,-105.00,-75.00,-45.00,-18.00,11.00,26.00,43.00,59.00,72.00,85.00,96.00,110.00,125.00,138.00,152.00,164.00,152.00,160.00,172.00,161.00,143.00,187.00,179.00,181.00,171.00,168.00,175.00,164.00,149.00,155.00,129.00,170.00,129.00,173.00,174.00,122.00,126.00,153.00,168.00,147.00,150.00,150.00,132.00,132.00,120.00,122.00,120.00,120.00,141.00,151.00,150.00,161.00,150.00,132.00,120.00,131.00,119.00,119.00,120.00,120.00,137.00,148.00,150.00,158.00,149.00,119.00,131.00,118.00,119.00,113.00,114.00,106.00,83.00,71.00,58.00,45.00,29.00,11.00,-17.00,-34.00,-48.00,-63.00,-73.00,-83.00,-111.00,-128.00,-158.00,-194.00,-210.00,-217.00,-225.00,-224.00,-217.00,-215.00,-184.00,-202.00,-214.00,-214.00,-222.00,-215.00,-215.00,-164.00,-184.00,-206.00,-214.00,-214.00,-222.00,-213.00,-213.00,-184.00,-160.00,-180.00,-164.00,-182.00,-200.00,-213.00,-214.00,-214.00,-221.00,-213.00,-213.00,-182.00,-159.00,-180.00,-183.00,-213.00,-213.00,-214.00,-214.00,-222.00,-214.00,-228.00,-214.00,-159.00,-159.00,-180.00,-182.00,-200.00,-209.00,-212.00,-211.00,-210.00,-210.00,-155.00,-155.00,-175.00,-174.00,-187.00,-191.00,-185.00,-179.00,-174.00,-168.00,-105.00,-106.00,-101.00,-96.00,-118.00,-133.00,-127.00,-158.00,-128.00,-58.00,-119.00,-55.00,-125.00,-55.00,-57.00,-63.00,-69.00,-91.00,-72.00,-96.00,-114.00,-71.00,-59.00,-57.00,-35.00,-22.00,-19.00,-53.00,-55.00,-42.00,-50.00,-93.00,-51.00,-43.00,-38.00,-39.00,-7.00,-4.00,-37.00,-38.00,-30.00,-24.00,-21.00,-8.00,3.00,44.00,73.00,93.00,141.00,122.00,135.00,145.00,155.00,201.00,211.00,177.00,193.00,194.00,187.00,178.00,182.00,130.00,180.00,182.00,182.00,211.00,174.00,181.00,173.00,174.00,132.00,132.00,179.00,120.00,183.00,182.00,211.00,173.00,175.00,182.00,189.00,104.00,91.00,119.00,104.00,75.00,60.00,44.00,102.00,87.00,75.00,100.00,86.00,53.00,40.00,29.00,18.00,-1.00,3.00,-72.00,-81.00,-51.00,-55.00,-69.00,-94.00,-72.00,-13.00,-17.00,-23.00,-25.00,-27.00,-102.00,-107.00,-23.00,-110.00,-22.00,-19.00,40.00,8.00,-18.00,4.00,-15.00,-18.00,-8.00,8.00,33.00,1.00,5.00,7.00,40.00,40.00,39.00,-2.00,-1.00,36.00,24.00,-9.00,24.00,-4.00,30.00,35.00,39.00,42.00,42.00,6.00,4.00,39.00,36.00,24.00,32.00,31.00,21.00,31.00,36.00,40.00,45.00,42.00,42.00,53.00,57.00,52.00,63.00,66.00,56.00,70.00,61.00,75.00,63.00,68.00,45.00,70.00,83.00,88.00,80.00,91.00,84.00,92.00,80.00,90.00,76.00,86.00,72.00,70.00,46.00,79.00,71.00,47.00,40.00,36.00,36.00,29.00,28.00,26.00,24.00,52.00,104.00,130.00,148.00,162.00,175.00,187.00,193.00,203.00,219.00,228.00,219.00,193.00,188.00,219.00,229.00,219.00,188.00,219.00,194.00,182.00,195.00,217.00,196.00,218.00,196.00,185.00,197.00,186.00,186.00,199.00,187.00,80.00,44.00,185.00,196.00,184.00,185.00,198.00,198.00,186.00,185.00,42.00,185.00,218.00,79.00,42.00,182.00,42.00,182.00,195.00,42.00,196.00,42.00,42.00,42.00,42.00,44.00,41.00,28.00,12.00,-4.00,-23.00,-43.00,-64.00,-86.00,-108.00,-132.00,-152.00,-175.00,-197.00,-217.00,-235.00,-253.00,-269.00,-268.00,-258.00,-244.00,-233.00,-221.00,-203.00,-184.00,-174.00,-163.00,-152.00,-139.00,-128.00,-114.00,-104.00,-91.00,-80.00,-70.00,-75.00,-91.00,-104.00,-119.00,-135.00,-102.00,-139.00,-148.00,11.00,-15.00,-28.00,-52.00,-190.00,-201.00,-74.00,-205.00,-22.00,-42.00,-32.00,5.00,-20.00,14.00,-156.00,26.00,47.00,30.00,42.00,24.00,47.00,-83.00,44.00,-78.00,44.00,106.00,84.00,43.00,-28.00,-65.00,66.00,90.00,67.00,65.00,44.00,-43.00,41.00,137.00,112.00,145.00,99.00,112.00,62.00,-9.00,37.00,-45.00,-52.00,49.00,41.00,73.00,59.00,39.00,39.00,41.00,109.00,66.00,45.00,41.00,-34.00,39.00,57.00,68.00,79.00,117.00,78.00,87.00,102.00,124.00,106.00,69.00,108.00,39.00,42.00,132.00,90.00,128.00,47.00,55.00,121.00,131.00,121.00,81.00,46.00,44.00,90.00,135.00,92.00,131.00,49.00,51.00,86.00,51.00,48.00,46.00,90.00,132.00,89.00,44.00,87.00,42.00,39.00,37.00,32.00,28.00,23.00,39.00,21.00,39.00,22.00,28.00,33.00,21.00,18.00,36.00,18.00,35.00,18.00,26.00,21.00,24.00,28.00,14.00,27.00,26.00,19.00,6.00,-6.00,4.00,-11.00,-27.00,-37.00,-26.00,-35.00,-15.00,-37.00,-42.00,-29.00,-18.00,-23.00,-30.00,-13.00,-5.00,20.00,1.00,28.00,18.00,28.00,39.00,46.00,54.00,69.00,54.00,42.00,55.00,85.00,56.00,46.00,13.00,-17.00,-46.00,-65.00,-86.00,-115.00,-141.00,-168.00,-192.00,-166.00,-177.00,-219.00,-218.00,-228.00,-247.00,-244.00,-223.00,-205.00,-170.00,-193.00,-157.00,-180.00,-136.00,-119.00,-162.00,-96.00,-80.00,-70.00,-62.00,-48.00,-82.00,-38.00,-52.00,-63.00,-61.00,-52.00,-4.00,-14.00,21.00,-1.00,39.00,49.00,-5.00,46.00,62.00,60.00,69.00,77.00,88.00,45.00,45.00,49.00,57.00,88.00,96.00,131.00,82.00,139.00,103.00,90.00,104.00,94.00,95.00,80.00,114.00,102.00,115.00,95.00,147.00,90.00,110.00,91.00,76.00,88.00,105.00,94.00,91.00,92.00,92.00,76.00,91.00,92.00,85.00,76.00,89.00,74.00,88.00,69.00,84.00,70.00,53.00,51.00,42.00,55.00,39.00,29.00,28.00,45.00,29.00,39.00,34.00,41.00,54.00,39.00,64.00,50.00,49.00,53.00,48.00,48.00,44.00,49.00,39.00,27.00,14.00,2.00,-10.00,-20.00,-31.00,-41.00,-55.00,-57.00,-47.00,-32.00,-32.00,-21.00,-18.00,-8.00,2.00,-9.00,-2.00,-1.00,12.00,24.00,37.00,16.00,17.00,2.00,-2.00,8.00,5.00,18.00,0.00,-18.00,-40.00,-73.00,-84.00,-99.00,-120.00,-131.00,-142.00,-160.00,-177.00,-192.00,-209.00,-222.00,-236.00,-249.00,-263.00,-274.00,-250.00,-272.00,-288.00,-271.00,-284.00,-279.00,-262.00,-247.00,-262.00,-248.00,-286.00,-270.00,-282.00,-281.00,-246.00,-238.00,-246.00,-284.00,-267.00,-280.00,-274.00,-256.00,-242.00,-262.00,-269.00,-244.00,-236.00,-247.00,-234.00,-224.00,-213.00,-211.00,-199.00,-188.00,-164.00,-147.00,-135.00,-153.00,-159.00,-137.00,-143.00,-131.00,-128.00,-111.00,-97.00,-95.00,-121.00,-121.00,-123.00,-107.00,-84.00,-97.00,-112.00,-81.00,-104.00,-103.00,-73.00,-96.00,-108.00,-93.00,-72.00,-100.00,-72.00,-65.00,-97.00,-69.00,-90.00,-66.00,-88.00,-99.00,-82.00,-60.00,-59.00,-58.00,-42.00,-54.00,-75.00,-53.00,-73.00,-71.00,-50.00,-47.00,-27.00,-40.00,-54.00,-74.00,-51.00,-42.00,-26.00,-40.00,-26.00,-3.00,-24.00,-50.00,-54.00,-64.00,-51.00,-66.00,-82.00,-78.00,-64.00,-90.00,-118.00,-107.00,-118.00,-106.00,-87.00,-75.00,-60.00,-89.00,-107.00,-81.00,-97.00,-109.00,-79.00,-74.00,-52.00,-20.00,-56.00,-83.00,-112.00,-78.00,-108.00,-119.00,-106.00,-85.00,-74.00,-79.00,-67.00,-47.00,-13.00,-45.00,-73.00,-49.00,-59.00,-75.00,-47.00,-46.00,-53.00,-43.00,-23.00,9.00,-24.00,-47.00,-32.00,-59.00,-38.00,-26.00,-37.00,-22.00,26.00,-9.00,-31.00,-14.00,-38.00,-16.00,0.00,-12.00,17.00,51.00,39.00,16.00,-6.00,-5.00,7.00,-21.00,4.00,0.00,-10.00,-10.00,12.00,1.00,-10.00,-54.00,-70.00,-82.00,-121.00,-138.00,-150.00,-127.00,-152.00,-172.00,-152.00,-135.00,-141.00,-129.00,-112.00,-96.00,-59.00,-46.00,-83.00,-96.00,-119.00,-92.00,-79.00,-90.00,-58.00,-63.00,-72.00,-44.00,-33.00,-30.00,-12.00,42.00,55.00,43.00,17.00,-1.00,-13.00,3.00,28.00,17.00,9.00,-6.00,15.00,41.00,27.00,42.00,78.00,72.00,55.00,44.00,29.00,47.00,32.00,14.00,39.00,51.00,39.00,85.00,75.00,45.00,39.00,51.00,39.00,43.00,82.00,73.00,86.00,73.00,48.00,37.00,35.00,37.00,74.00,77.00,39.00,35.00,24.00,35.00,24.00,16.00,14.00,42.00,52.00,26.00,14.00,2.00,14.00,5.00,-6.00,11.00,11.00,9.00,-1.00,-25.00,-41.00,-53.00,-72.00,-87.00,-80.00,-92.00,-117.00,-129.00,-156.00,-136.00,-136.00,-140.00,-168.00,-175.00,-145.00,-152.00,-186.00],\r\n\t\t\t\t\tgraphSpeed         : [],\r\n\t\t\t\t\tgraphHr            : [],\r\n\t\t\t\t\tgraphAtemp         : [],\r\n\t\t\t\t\tgraphCad           : [],\r\n\t\t\t\t\tgraphGrade         : [],\r\n\t\t\t\t\twaypoints          : [],\r\n\t\t\t\t\tunit               : \"0\",\r\n\t\t\t\t\tunitspeed          : \"0\",\r\n\t\t\t\t\tcolor1             : [\"#3366cc\"],\r\n\t\t\t\t\tcolor2             : \"#3366cc\",\r\n\t\t\t\t\tcolor3             : \"#ff0000\",\r\n\t\t\t\t\tcolor4             : \"#ff77bd\",\r\n\t\t\t\t\tcolor5             : \"#beecff\",\r\n\t\t\t\t\tcolor6             : \"#beecff\",\r\n\t\t\t\t\tcolor7             : \"#ff77bd\",\r\n\t\t\t\t\tchartFrom1         : \"\",\r\n\t\t\t\t\tchartTo1           : \"\",\r\n\t\t\t\t\tchartFrom2         : \"\",\r\n\t\t\t\t\tchartTo2           : \"\",\r\n\t\t\t\t\tstartIcon          : \"\",\r\n\t\t\t\t\tendIcon            : \"\",\r\n\t\t\t\t\tcurrentIcon        : \"\",\r\n\t\t\t\t\twaypointIcon       : \"\",\r\n\t\t\t\t\tcurrentpositioncon : \"\",\r\n\t\t\t\t\tusegpsposition     : \"\",\r\n\t\t\t\t\tzoomOnScrollWheel  : \"\",\r\n\t\t\t\t\tngGalleries        : [],\r\n\t\t\t\t\tngImages           : [],\r\n\t\t\t\t\tpluginUrl          : \"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/plugins\",\r\n\t\t\t\t\tTFApiKey           : \"AIzaSyBEHuzTdfowE4WGJfQwG5hgXaIKV-xllt0\",\r\n\t\t\t\t\tlangs              : {\r\n\t\t\t\t\t\taltitude        : \"H\u00f6he\",\r\n\t\t\t\t\t\tcurrentPosition : \"Aktuelle Position\",\r\n\t\t\t\t\t\tspeed           : \"Geschwindigkeit\",\r\n\t\t\t\t\t\tgrade           : \"Steigung\",\r\n\t\t\t\t\t\theartRate       : \"Herzfrequenz\",\r\n\t\t\t\t\t\tatemp           : \"Temperatur\",\r\n\t\t\t\t\t\tcadence         : \"Trittfrequenz\",\r\n\t\t\t\t\t\tgoFullScreen    : \"Vollbildansicht\",\r\n\t\t\t\t\t\texitFullFcreen  : \"Vollbild verlassen\",\r\n\t\t\t\t\t\thideImages      : \"Bilder verbergen\",\r\n\t\t\t\t\t\tshowImages      : \"Bilder zeigen\",\r\n\t\t\t\t\t\tbackToCenter\t: \"Zur\u00fcck zur Mitte\"\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\r\n\t\t\t});\r\n\r\n\t\t<\/script><br \/>\n\r\n\t\t<div id=\"wpgpxmaps_8220_929938\" class=\"wpgpxmaps\">\r\n\t\t\t<div id=\"map_8220_929938_cont\" style=\"width:100%; height:450px;position:relative\" >\r\n\t\t\t\t<div id=\"map_8220_929938\" style=\"width:100%; height:450px\"><\/div>\r\n\t\t\t\t<div id=\"wpgpxmaps_8220_929938_osm_footer\" class=\"wpgpxmaps_osm_footer\" style=\"display:none;\"><span> &copy; <a href=\"http:\/\/www.openstreetmap.org\/copyright\">OpenStreetMap<\/a> contributors<\/span><\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<canvas id=\"myChart_8220_929938\" class=\"plot\" style=\"width:100%; height:200px\"><\/canvas>\r\n\t\t\t<div id=\"ngimages_8220_929938\" class=\"ngimages\" style=\"display:none\"><\/div>\r\n\t\t\t<div id=\"report_8220_929938\" class=\"report\"><\/div>\r\n\t\t<\/div>\r\n\t\t\r\n\t\t<script type=\"text\/javascript\">\r\n\r\n\t\t\tjQuery(document).ready(function() {\r\n\r\n\t\t\t\tjQuery( \"#wpgpxmaps_8220_929938\" ).wpgpxmaps( {\r\n\t\t\t\t\ttargetId           : \"8220_929938\",\r\n\t\t\t\t\tmapType            : \"HYBRID\",\r\n\t\t\t\t\tmapData            : [[55.6780630,12.5978730],[55.6780630,12.5978740],[55.6780510,12.5978860],[55.6780480,12.5978850],[55.6780450,12.5978850],[55.6780450,12.5978860],[55.6780430,12.5978870],[55.6780430,12.5978850],[55.6780430,12.5978850],[55.6780430,12.5978820],[55.6780430,12.5978810],[55.6780430,12.5978810],[55.6780430,12.5978800],[55.6780430,12.5978800],[55.6780430,12.5978650],[55.6780450,12.5978600],[55.6780450,12.5978600],[55.6780450,12.5978590],[55.6780450,12.5978590],[55.6780480,12.5978590],[55.6780480,12.5978580],[55.6780480,12.5978580],[55.6780480,12.5978560],[55.6780480,12.5978530],[55.6780400,12.5978690],[55.6780380,12.5978750],[55.6780400,12.5978760],[55.6780400,12.5978760],[55.6780510,12.5978770],[55.6780480,12.5978710],[55.6780450,12.5978840],[55.6780380,12.5978850],[55.6780380,12.5978850],[55.6780380,12.5978850],[55.6780380,12.5978840],[55.6780400,12.5978910],[55.6780380,12.5978990],[55.6780660,12.5978900],[55.6780730,12.5979020],[55.6780710,12.5979040],[55.6780760,12.5979000],[55.6780760,12.5978990],[55.6780760,12.5978980],[55.6780730,12.5979010],[55.6780710,12.5979030],[55.6780710,12.5979030],[55.6780680,12.5979050],[55.6780680,12.5979080],[55.6780660,12.5979110],[55.6780580,12.5979280],[55.6780400,12.5979680],[55.6780280,12.5980140],[55.6780100,12.5980420],[55.6780070,12.5980400],[55.6779850,12.5981960],[55.6779590,12.5983230],[55.6779210,12.5984210],[55.6779060,12.5984570],[55.6778960,12.5984880],[55.6778830,12.5985140],[55.6778220,12.5986250],[55.6777690,12.5986960],[55.6776830,12.5987440],[55.6776190,12.5987230],[55.6775480,12.5986750],[55.6774690,12.5985680],[55.6774160,12.5984810],[55.6773630,12.5984290],[55.6773350,12.5983970],[55.6773070,12.5983410],[55.6772940,12.5982960],[55.6772790,12.5982290],[55.6772740,12.5982010],[55.6773020,12.5981410],[55.6771900,12.5980830],[55.6771060,12.5980260],[55.6770330,12.5979230],[55.6769640,12.5978350],[55.6769360,12.5977980],[55.6768930,12.5977430],[55.6768270,12.5976370],[55.6767760,12.5975540],[55.6767050,12.5974230],[55.6767180,12.5974250],[55.6766750,12.5973600],[55.6766290,12.5972840],[55.6766220,12.5972880],[55.6766010,12.5971990],[55.6765780,12.5971260],[55.6764950,12.5970400],[55.6764360,12.5969730],[55.6764010,12.5969310],[55.6763860,12.5969090],[55.6763530,12.5968680],[55.6763370,12.5968480],[55.6763070,12.5968090],[55.6762940,12.5967890],[55.6762820,12.5967710],[55.6762540,12.5967290],[55.6762410,12.5967070],[55.6762180,12.5966720],[55.6761900,12.5966310],[55.6761770,12.5966100],[55.6761520,12.5965670],[55.6761140,12.5965020],[55.6760990,12.5964820],[55.6760660,12.5964450],[55.6760180,12.5963920],[55.6759870,12.5963600],[55.6759620,12.5963230],[55.6759390,12.5962820],[55.6759140,12.5962450],[55.6758580,12.5961920],[55.6757890,12.5961390],[55.6757560,12.5961120],[55.6757310,12.5960890],[55.6757100,12.5960670],[55.6756950,12.5960460],[55.6756700,12.5960070],[55.6756620,12.5959920],[55.6756520,12.5959640],[55.6756470,12.5959530],[55.6756600,12.5960320],[55.6756770,12.5961020],[55.6756830,12.5961220],[55.6756930,12.5961680],[55.6756930,12.5961810],[55.6756850,12.5961650],[55.6756830,12.5961440],[55.6756830,12.5961430],[55.6756800,12.5961310],[55.6756600,12.5960540],[55.6756670,12.5960580],[55.6756800,12.5960490],[55.6756930,12.5960350],[55.6757260,12.5959890],[55.6757410,12.5959390],[55.6757640,12.5959210],[55.6757740,12.5958890],[55.6757740,12.5958800],[55.6757740,12.5958670],[55.6757760,12.5958450],[55.6757740,12.5958340],[55.6757490,12.5958310],[55.6757000,12.5957850],[55.6756900,12.5957800],[55.6756850,12.5957940],[55.6757210,12.5957900],[55.6757050,12.5957580],[55.6757100,12.5957620]],\r\n\t\t\t\t\tgraphDist          : [0.00,11.06,21.22,42.27,53.28,81.28,91.29,106.35,139.35,179.35,191.35,207.35,218.35,231.35,241.42,253.43,266.43,276.43,288.43,299.46,311.46,322.46,333.46,343.53,357.23,367.25,378.27,389.27,400.41,410.45,420.63,446.21,460.21,472.21,482.21,497.67,507.94,523.51,535.47,550.54,565.63,576.69,589.69,604.70,615.70,632.70,652.71,678.71,696.71,717.75,750.57,766.41,776.62,786.69,808.59,819.26,829.37,849.63,868.76,879.97,890.38,905.49,916.93,929.80,940.87,952.64,964.29,974.40,985.46,995.49,1005.71,1017.07,1027.30,1038.00,1053.41,1063.58,1075.69,1086.76,1099.75,1114.07,1130.99,1143.08,1154.75,1178.30,1200.28,1211.80,1225.40,1235.60,1253.70,1265.96,1286.50,1310.17,1322.37,1357.79,1370.97,1388.72,1437.75,1449.88,1467.43,1479.60,1493.04,1511.49,1526.62,1539.23,1561.20,1571.41,1582.58,1597.27,1609.93,1625.36,1639.85,1664.79,1690.56,1701.02,1711.99,1723.75,1738.15,1750.45,1760.85,1785.01,1807.31,1819.11,1833.10,1846.11,1858.21,1884.88,1914.93,1928.43,1939.67,1950.67,1964.74,1978.20,1988.26,2016.47,2040.58,2054.39,2067.14,2083.32,2093.82,2117.13,2139.41,2152.09,2165.16,2175.68,2208.49,2232.75,2251.25,2268.63,2284.11,2294.19],\r\n\t\t\t\t\tgraphEle           : [-145.00,-147.00,-148.00,-167.00,-156.00,-128.00,-118.00,-113.00,-134.00,-94.00,-94.00,-78.00,-67.00,-54.00,-44.00,-32.00,-19.00,-9.00,3.00,14.00,14.00,25.00,36.00,44.00,39.00,49.00,54.00,53.00,64.00,74.00,84.00,75.00,89.00,77.00,75.00,90.00,94.00,79.00,68.00,53.00,42.00,31.00,18.00,3.00,-8.00,-25.00,-45.00,-71.00,-89.00,-110.00,-78.00,-92.00,-97.00,-107.00,-102.00,-99.00,-104.00,-124.00,-143.00,-154.00,-156.00,-166.00,-163.00,-158.00,-153.00,-150.00,-147.00,-147.00,-156.00,-150.00,-158.00,-167.00,-157.00,-155.00,-155.00,-155.00,-152.00,-155.00,-144.00,-155.00,-148.00,-154.00,-153.00,-131.00,-152.00,-147.00,-140.00,-135.00,-124.00,-118.00,-100.00,-77.00,-65.00,-30.00,-17.00,-8.00,41.00,53.00,36.00,48.00,61.00,79.00,94.00,106.00,127.00,117.00,123.00,126.00,128.00,143.00,129.00,152.00,132.00,136.00,145.00,138.00,140.00,152.00,147.00,171.00,150.00,161.00,154.00,162.00,150.00,166.00,136.00,131.00,120.00,109.00,103.00,109.00,99.00,115.00,91.00,95.00,84.00,83.00,82.00,105.00,83.00,95.00,92.00,101.00,126.00,108.00,126.00,120.00,119.00,129.00],\r\n\t\t\t\t\tgraphSpeed         : [],\r\n\t\t\t\t\tgraphHr            : [],\r\n\t\t\t\t\tgraphAtemp         : [],\r\n\t\t\t\t\tgraphCad           : [],\r\n\t\t\t\t\tgraphGrade         : [],\r\n\t\t\t\t\twaypoints          : [],\r\n\t\t\t\t\tunit               : \"0\",\r\n\t\t\t\t\tunitspeed          : \"0\",\r\n\t\t\t\t\tcolor1             : [\"#3366cc\"],\r\n\t\t\t\t\tcolor2             : \"#3366cc\",\r\n\t\t\t\t\tcolor3             : \"#ff0000\",\r\n\t\t\t\t\tcolor4             : \"#ff77bd\",\r\n\t\t\t\t\tcolor5             : \"#beecff\",\r\n\t\t\t\t\tcolor6             : \"#beecff\",\r\n\t\t\t\t\tcolor7             : \"#ff77bd\",\r\n\t\t\t\t\tchartFrom1         : \"\",\r\n\t\t\t\t\tchartTo1           : \"\",\r\n\t\t\t\t\tchartFrom2         : \"\",\r\n\t\t\t\t\tchartTo2           : \"\",\r\n\t\t\t\t\tstartIcon          : \"\",\r\n\t\t\t\t\tendIcon            : \"\",\r\n\t\t\t\t\tcurrentIcon        : \"\",\r\n\t\t\t\t\twaypointIcon       : \"\",\r\n\t\t\t\t\tcurrentpositioncon : \"\",\r\n\t\t\t\t\tusegpsposition     : \"\",\r\n\t\t\t\t\tzoomOnScrollWheel  : \"\",\r\n\t\t\t\t\tngGalleries        : [],\r\n\t\t\t\t\tngImages           : [],\r\n\t\t\t\t\tpluginUrl          : \"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/plugins\",\r\n\t\t\t\t\tTFApiKey           : \"AIzaSyBEHuzTdfowE4WGJfQwG5hgXaIKV-xllt0\",\r\n\t\t\t\t\tlangs              : {\r\n\t\t\t\t\t\taltitude        : \"H\u00f6he\",\r\n\t\t\t\t\t\tcurrentPosition : \"Aktuelle Position\",\r\n\t\t\t\t\t\tspeed           : \"Geschwindigkeit\",\r\n\t\t\t\t\t\tgrade           : \"Steigung\",\r\n\t\t\t\t\t\theartRate       : \"Herzfrequenz\",\r\n\t\t\t\t\t\tatemp           : \"Temperatur\",\r\n\t\t\t\t\t\tcadence         : \"Trittfrequenz\",\r\n\t\t\t\t\t\tgoFullScreen    : \"Vollbildansicht\",\r\n\t\t\t\t\t\texitFullFcreen  : \"Vollbild verlassen\",\r\n\t\t\t\t\t\thideImages      : \"Bilder verbergen\",\r\n\t\t\t\t\t\tshowImages      : \"Bilder zeigen\",\r\n\t\t\t\t\t\tbackToCenter\t: \"Zur\u00fcck zur Mitte\"\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\r\n\t\t\t});\r\n\r\n\t\t<\/script><br \/>\n\r\n\t\t<div id=\"wpgpxmaps_8220_1096493\" class=\"wpgpxmaps\">\r\n\t\t\t<div id=\"map_8220_1096493_cont\" style=\"width:100%; height:450px;position:relative\" >\r\n\t\t\t\t<div id=\"map_8220_1096493\" style=\"width:100%; height:450px\"><\/div>\r\n\t\t\t\t<div id=\"wpgpxmaps_8220_1096493_osm_footer\" class=\"wpgpxmaps_osm_footer\" style=\"display:none;\"><span> &copy; <a href=\"http:\/\/www.openstreetmap.org\/copyright\">OpenStreetMap<\/a> contributors<\/span><\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<canvas id=\"myChart_8220_1096493\" class=\"plot\" style=\"width:100%; height:200px\"><\/canvas>\r\n\t\t\t<div id=\"ngimages_8220_1096493\" class=\"ngimages\" style=\"display:none\"><\/div>\r\n\t\t\t<div id=\"report_8220_1096493\" class=\"report\"><\/div>\r\n\t\t<\/div>\r\n\t\t\r\n\t\t<script type=\"text\/javascript\">\r\n\r\n\t\t\tjQuery(document).ready(function() {\r\n\r\n\t\t\t\tjQuery( \"#wpgpxmaps_8220_1096493\" ).wpgpxmaps( {\r\n\t\t\t\t\ttargetId           : \"8220_1096493\",\r\n\t\t\t\t\tmapType            : \"HYBRID\",\r\n\t\t\t\t\tmapData            : [[55.6757920,12.5959120],[55.6757870,12.5958840],[55.6757870,12.5958870],[55.6757790,12.5958840],[55.6757820,12.5958790],[55.6757790,12.5958820],[55.6757820,12.5958810],[55.6757820,12.5958810],[55.6757820,12.5958810],[55.6757870,12.5958740],[55.6757840,12.5958740],[55.6757870,12.5958730],[55.6757890,12.5958670],[55.6757890,12.5958600],[55.6757890,12.5958580],[55.6757870,12.5958580],[55.6757890,12.5958600],[55.6757890,12.5958580],[55.6757890,12.5958580],[55.6757890,12.5958580],[55.6757890,12.5958600],[55.6757890,12.5958600],[55.6757890,12.5958600],[55.6757890,12.5958600],[55.6757890,12.5958610],[55.6757890,12.5958610],[55.6757890,12.5958610],[55.6757890,12.5958610],[55.6757890,12.5958620],[55.6757890,12.5958620],[55.6757890,12.5958630],[55.6757890,12.5958630],[55.6757890,12.5958640],[55.6757890,12.5958650],[55.6757870,12.5958650],[55.6757870,12.5958660],[55.6757870,12.5958660],[55.6757870,12.5958670],[55.6757870,12.5958670],[55.6757870,12.5958690],[55.6757870,12.5958690],[55.6757870,12.5958690],[55.6757870,12.5958710],[55.6757870,12.5958710],[55.6757740,12.5958930],[55.6757590,12.5959340],[55.6757540,12.5959510],[55.6757260,12.5960110],[55.6757050,12.5960560],[55.6756850,12.5960840],[55.6756800,12.5960870],[55.6756800,12.5960890],[55.6756770,12.5960870],[55.6756650,12.5960890],[55.6756550,12.5960920],[55.6756520,12.5960910],[55.6756770,12.5961050],[55.6757430,12.5961640],[55.6757510,12.5961720],[55.6757590,12.5961810],[55.6758300,12.5962580],[55.6758930,12.5963360],[55.6759470,12.5963940],[55.6760200,12.5964830],[55.6760430,12.5965110],[55.6760630,12.5965420],[55.6760960,12.5965840],[55.6761600,12.5966640],[55.6761770,12.5966940],[55.6762180,12.5967690],[55.6762610,12.5968590],[55.6762840,12.5969270],[55.6763070,12.5970220],[55.6763400,12.5970810],[55.6763420,12.5970860],[55.6763170,12.5970820],[55.6762940,12.5970800],[55.6762760,12.5970740],[55.6762510,12.5970730],[55.6762180,12.5970620],[55.6762210,12.5970410],[55.6762230,12.5970450],[55.6762280,12.5970490],[55.6762360,12.5970530],[55.6762360,12.5970540],[55.6762380,12.5970540],[55.6762360,12.5970530],[55.6762360,12.5970530],[55.6762380,12.5970540],[55.6762380,12.5970540],[55.6762380,12.5970540],[55.6762360,12.5970550],[55.6762360,12.5970550],[55.6762360,12.5970550],[55.6762360,12.5970550],[55.6762360,12.5970550],[55.6762360,12.5970550],[55.6762360,12.5970570],[55.6762360,12.5970570],[55.6762360,12.5970570],[55.6762360,12.5970570],[55.6762360,12.5970570],[55.6762360,12.5970570],[55.6762360,12.5970570],[55.6762360,12.5970570],[55.6762360,12.5970580],[55.6762360,12.5970580],[55.6762360,12.5970580],[55.6762360,12.5970580],[55.6762360,12.5970570],[55.6762360,12.5970570],[55.6762360,12.5970570],[55.6762360,12.5970570],[55.6762360,12.5970570],[55.6762380,12.5970570]],\r\n\t\t\t\t\tgraphDist          : [0.00,32.05,64.05,87.47,99.50,109.50,141.50,164.50,185.50,198.52,213.49,235.56,254.62,273.87,294.00,305.07,317.14,327.87,339.87,350.87,360.87,372.87,384.87,396.87,407.87,422.87,438.87,449.87,461.87,474.87,485.94,496.94,506.94,517.99,529.00,544.00,557.00,568.00,578.01,592.01,604.14,614.14,627.27,638.27,650.67,663.68,674.75,689.85,700.52,710.95,722.07,735.07,747.16,762.32,781.96,803.01,813.04,823.10,836.14,851.18,861.59,879.44,894.59,913.79,930.27,948.84,967.16,977.82,988.18,999.54,1010.66,1020.80,1031.43,1046.04,1056.18,1066.85,1077.19,1087.40,1097.90,1108.63,1119.45,1148.48,1158.52,1172.62,1183.62,1226.62,1246.65,1269.65,1285.86,1297.86,1314.86,1325.93,1341.93,1354.93,1371.93,1387.93,1405.93,1417.93,1435.93,1458.93,1475.93,1491.93,1505.93,1516.93,1531.93,1548.93,1565.93,1586.93,1606.93,1619.99,1631.99,1642.99,1657.99,1670.99,1681.01],\r\n\t\t\t\t\tgraphEle           : [39.00,7.00,39.00,22.00,26.00,36.00,4.00,27.00,6.00,19.00,20.00,-2.00,17.00,-2.00,18.00,21.00,21.00,27.00,39.00,36.00,46.00,48.00,60.00,72.00,83.00,74.00,60.00,51.00,39.00,44.00,45.00,44.00,54.00,65.00,74.00,85.00,98.00,103.00,113.00,117.00,115.00,109.00,108.00,115.00,121.00,131.00,142.00,154.00,164.00,168.00,173.00,174.00,186.00,189.00,184.00,205.00,198.00,202.00,189.00,174.00,171.00,159.00,167.00,155.00,140.00,154.00,138.00,133.00,131.00,124.00,117.00,118.00,121.00,123.00,121.00,111.00,101.00,91.00,83.00,82.00,88.00,61.00,53.00,67.00,62.00,105.00,89.00,70.00,72.00,74.00,81.00,72.00,56.00,65.00,54.00,70.00,62.00,72.00,76.00,53.00,70.00,54.00,68.00,57.00,50.00,67.00,50.00,71.00,59.00,62.00,60.00,59.00,52.00,53.00,51.00],\r\n\t\t\t\t\tgraphSpeed         : [],\r\n\t\t\t\t\tgraphHr            : [],\r\n\t\t\t\t\tgraphAtemp         : [],\r\n\t\t\t\t\tgraphCad           : [],\r\n\t\t\t\t\tgraphGrade         : [],\r\n\t\t\t\t\twaypoints          : [],\r\n\t\t\t\t\tunit               : \"0\",\r\n\t\t\t\t\tunitspeed          : \"0\",\r\n\t\t\t\t\tcolor1             : [\"#3366cc\"],\r\n\t\t\t\t\tcolor2             : \"#3366cc\",\r\n\t\t\t\t\tcolor3             : \"#ff0000\",\r\n\t\t\t\t\tcolor4             : \"#ff77bd\",\r\n\t\t\t\t\tcolor5             : \"#beecff\",\r\n\t\t\t\t\tcolor6             : \"#beecff\",\r\n\t\t\t\t\tcolor7             : \"#ff77bd\",\r\n\t\t\t\t\tchartFrom1         : \"\",\r\n\t\t\t\t\tchartTo1           : \"\",\r\n\t\t\t\t\tchartFrom2         : \"\",\r\n\t\t\t\t\tchartTo2           : \"\",\r\n\t\t\t\t\tstartIcon          : \"\",\r\n\t\t\t\t\tendIcon            : \"\",\r\n\t\t\t\t\tcurrentIcon        : \"\",\r\n\t\t\t\t\twaypointIcon       : \"\",\r\n\t\t\t\t\tcurrentpositioncon : \"\",\r\n\t\t\t\t\tusegpsposition     : \"\",\r\n\t\t\t\t\tzoomOnScrollWheel  : \"\",\r\n\t\t\t\t\tngGalleries        : [],\r\n\t\t\t\t\tngImages           : [],\r\n\t\t\t\t\tpluginUrl          : \"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/plugins\",\r\n\t\t\t\t\tTFApiKey           : \"AIzaSyBEHuzTdfowE4WGJfQwG5hgXaIKV-xllt0\",\r\n\t\t\t\t\tlangs              : {\r\n\t\t\t\t\t\taltitude        : \"H\u00f6he\",\r\n\t\t\t\t\t\tcurrentPosition : \"Aktuelle Position\",\r\n\t\t\t\t\t\tspeed           : \"Geschwindigkeit\",\r\n\t\t\t\t\t\tgrade           : \"Steigung\",\r\n\t\t\t\t\t\theartRate       : \"Herzfrequenz\",\r\n\t\t\t\t\t\tatemp           : \"Temperatur\",\r\n\t\t\t\t\t\tcadence         : \"Trittfrequenz\",\r\n\t\t\t\t\t\tgoFullScreen    : \"Vollbildansicht\",\r\n\t\t\t\t\t\texitFullFcreen  : \"Vollbild verlassen\",\r\n\t\t\t\t\t\thideImages      : \"Bilder verbergen\",\r\n\t\t\t\t\t\tshowImages      : \"Bilder zeigen\",\r\n\t\t\t\t\t\tbackToCenter\t: \"Zur\u00fcck zur Mitte\"\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\r\n\t\t\t});\r\n\r\n\t\t<\/script><\/p>\n<p><em>12.08.2025, K\u00f8benhavn - Gilleleje: Z<\/em><em>ugeh\u00f6riger Track leider fehlerhaft und somit nur als Bild verf\u00fcgbar<\/em><\/p>\n<p><a href=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/2025-08-12-001-485.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-8260 size-medium\" src=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/2025-08-12-001-485-300x263.jpg\" alt=\"\" width=\"300\" height=\"263\" srcset=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/2025-08-12-001-485-300x263.jpg 300w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/2025-08-12-001-485-342x300.jpg 342w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/2025-08-12-001-485.jpg 455w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>13.08.2025, Gilleleje - Ankern vor R\u00f8rvig:\u00a0Zugeh\u00f6riger Track leider fehlerhaft und somit nur als Bild verf\u00fcgbar<\/em><\/p>\n<p><a href=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/2025-08-13-001-486.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-8261 size-medium\" src=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/2025-08-13-001-486-300x159.jpg\" alt=\"\" width=\"300\" height=\"159\" srcset=\"http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/2025-08-13-001-486-300x159.jpg 300w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/2025-08-13-001-486-500x264.jpg 500w, http:\/\/www.delphin-66.de\/wordpress\/wp-content\/uploads\/2025-08-13-001-486.jpg 696w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>09.08.2025, Drag\u00f8r &#8211; K\u00f8benhavn Die vergangenen Tage waren ereignisreich und ich habe mich schwer getan, einen neuen Blog-Beitrag abzuschlie\u00dfen. Aber heute (zur Zeit in S\u00f8nderborg, 22.08.2025, zum Abwettern) finde ich die Zeit. Nun sind wir, mehr unverhofft als geplant, unserem &hellip; <a href=\"http:\/\/www.delphin-66.de\/wordpress\/sommerurlaub-2025-kopenhagen\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":8226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[19,20,22],"tags":[],"_links":{"self":[{"href":"http:\/\/www.delphin-66.de\/wordpress\/wp-json\/wp\/v2\/posts\/8220"}],"collection":[{"href":"http:\/\/www.delphin-66.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.delphin-66.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.delphin-66.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.delphin-66.de\/wordpress\/wp-json\/wp\/v2\/comments?post=8220"}],"version-history":[{"count":35,"href":"http:\/\/www.delphin-66.de\/wordpress\/wp-json\/wp\/v2\/posts\/8220\/revisions"}],"predecessor-version":[{"id":8335,"href":"http:\/\/www.delphin-66.de\/wordpress\/wp-json\/wp\/v2\/posts\/8220\/revisions\/8335"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.delphin-66.de\/wordpress\/wp-json\/wp\/v2\/media\/8226"}],"wp:attachment":[{"href":"http:\/\/www.delphin-66.de\/wordpress\/wp-json\/wp\/v2\/media?parent=8220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.delphin-66.de\/wordpress\/wp-json\/wp\/v2\/categories?post=8220"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.delphin-66.de\/wordpress\/wp-json\/wp\/v2\/tags?post=8220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}